{"id":11449,"date":"2020-06-09T14:12:00","date_gmt":"2020-06-09T17:12:00","guid":{"rendered":"http:\/\/blogopara.com.br\/?p=11449"},"modified":"2020-06-09T13:19:36","modified_gmt":"2020-06-09T16:19:36","slug":"juazeiro-paulo-bomfim-diz-fara-mais-e-melhor-que-isaac","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2020\/06\/09\/juazeiro-paulo-bomfim-diz-fara-mais-e-melhor-que-isaac","title":{"rendered":"Juazeiro: Paulo Bomfim diz far\u00e1 mais e melhor que Isaac"},"content":{"rendered":"<p style=\"text-align: justify;\">O prefeito de Juazeiro (BA), Paulo Bomfim, concedeu uma entrevista exclusiva na noite de segunda-feira (08) ao radialista e blogueiro Edenevaldo Alves e se posicionou a respeito da rela\u00e7\u00e3o e influ\u00eancia do ex-prefeito Isaac Carvalho no atual Governo municipal.<\/p>\n<p style=\"text-align: justify;\">Bomfim discorreu sobre o hist\u00f3rico profissional que teve na gest\u00e3o de Isaac e disse que na \u00e9poca foi um dos coordenadores da campanha de reelei\u00e7\u00e3o do vaqueiro. Posteriormente, teria sido convidado para assumir a Secretaria de Governo e na sucess\u00e3o, onde tudo mudaria. Paulo Bomfim afirmou que grupo pol\u00edtico do qual fazia parte entendeu que seria o seu nome o escolhido para suceder Isaac.<br \/>\n\u201cNaquele momento Isaac me credenciou a estrutura pol\u00edtica dele, porque abaixo da vontade de Deus e sem a for\u00e7a pol\u00edtica do grupo que Isaac montou, eu n\u00e3o estaria prefeito. O povo de Juazeiro me avaliou pela gest\u00e3o que Isaac fez, ent\u00e3o agora o gestor \u00e9 Paulo Bomfim, o gestor n\u00e3o \u00e9 mais Isaac\u201d, assegurou durante LIVE no Instagram do Blog Edenevaldo Alves .<\/p>\n<p style=\"text-align: justify;\">O Chefe do poder executivo municipal destacou que o relacionamento com o ex-prefeito \u00e9 o \u201cmelhor poss\u00edvel\u201d e que no primeiro momento havia convidado Isaac para trabalhar em sua gest\u00e3o. \u201cQualquer gestor desse pa\u00eds gostaria de estar perto da experi\u00eancia administrativa de Isaac, porque Isaac, at\u00e9 este momento, foi o melhor prefeito que j\u00e1 teve na hist\u00f3ria de Juazeiro\u201d, afirmou ressaltando que pretendo super\u00e1-lo.<\/p>\n<p style=\"text-align: justify;\">Paulo Bomfim n\u00e3o mencionou supostas interfer\u00eancias pol\u00edticas na gest\u00e3o que o escolheu para o comando da prefeitura. \u201cSe eu tiver a oportunidade que espero ter, de poder ter mais um mandato, eu vou fazer mais e melhor que Isaac, porque Isaac recebeu Juazeiro completamente destru\u00edda e eu recebi Juazeiro com outro patamar e a gente est\u00e1 colocando essa cidade no rumo que ela precisa estar e vai continuar assim se Deus permitir\u201d.<\/p>\n<pre>Fonte: Blog do Edenevaldo Alves<\/pre>\n","protected":false},"excerpt":{"rendered":"<p>O prefeito de Juazeiro (BA), Paulo Bomfim, concedeu uma entrevista exclusiva na noite de segunda-feira (08) ao radialista e blogueiro Edenevaldo Alves e se posicionou a respeito da rela\u00e7\u00e3o e influ\u00eancia do ex-prefeito Isaac Carvalho no atual Governo municipal. Bomfim discorreu sobre o hist\u00f3rico profissional que teve na gest\u00e3o de Isaac e disse que na [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":11450,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[203,197],"tags":[],"class_list":["post-11449","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-juazeiro","category-politica"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/06\/isaac-e-paulo-bomfim.jpg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/06\/isaac-e-paulo-bomfim.jpg",500,353,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/06\/isaac-e-paulo-bomfim-150x150.jpg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/06\/isaac-e-paulo-bomfim-300x212.jpg",300,212,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/06\/isaac-e-paulo-bomfim.jpg",500,353,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/06\/isaac-e-paulo-bomfim.jpg",500,353,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/06\/isaac-e-paulo-bomfim.jpg",500,353,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/06\/isaac-e-paulo-bomfim.jpg",500,353,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/06\/isaac-e-paulo-bomfim.jpg",500,353,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/06\/isaac-e-paulo-bomfim-420x307.jpg",420,307,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/06\/isaac-e-paulo-bomfim-300x353.jpg",300,353,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/06\/isaac-e-paulo-bomfim-464x290.jpg",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/06\/isaac-e-paulo-bomfim.jpg",500,353,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/06\/isaac-e-paulo-bomfim.jpg",322,227,false],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/06\/isaac-e-paulo-bomfim.jpg",500,353,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"O prefeito de Juazeiro (BA), Paulo Bomfim, concedeu uma entrevista exclusiva na noite de segunda-feira (08) ao radialista e blogueiro Edenevaldo Alves e se posicionou a respeito da rela\u00e7\u00e3o e influ\u00eancia do ex-prefeito Isaac Carvalho no atual Governo municipal. Bomfim discorreu sobre o hist\u00f3rico profissional que teve na gest\u00e3o de Isaac e disse que na&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/11449","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=11449"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/11449\/revisions"}],"predecessor-version":[{"id":11451,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/11449\/revisions\/11451"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/11450"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=11449"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=11449"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=11449"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}