{"id":1195,"date":"2019-07-06T11:27:30","date_gmt":"2019-07-06T14:27:30","guid":{"rendered":"http:\/\/blogopara.com.br\/?p=1195"},"modified":"2019-07-06T13:45:27","modified_gmt":"2019-07-06T16:45:27","slug":"policia-recupera-moto-roubada-em-sodradinho","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2019\/07\/06\/policia-recupera-moto-roubada-em-sodradinho","title":{"rendered":"POL\u00cdCIA MILITAR EM SODRADINHO RECUPERA MOTO ROUBADA, EM JUAZEIRO"},"content":{"rendered":"<p style=\"text-align: justify;\">Por volta das 15h50 do dia 05\/07, a guarni\u00e7\u00e3o PETO (96\u00aa CIPM\/SOBRADINHO) composta pelos soldados Adams, Denis e Fernandes, recebeu a informa\u00e7\u00e3o de que havia um indiv\u00edduo tentando vender uma moto HONDA\/BROS de cor preta, sem placa, pela quantia de R$ 1.000,00 (mil reais), provavelmente fruto de algum il\u00edcito.<\/p>\n<p style=\"text-align: justify;\">Quando efetuava ronda na Vila S\u00e3o Joaquim, entre as quadras N18 e N24, avistaram um indiv\u00edduo com as caracter\u00edsticas informadas. Ao perceber que a guarni\u00e7\u00e3o se aproximava, o indiv\u00edduo empreendeu fuga, sendo capturado. O mesmo assumiu que havia roubado de uma mulher no dia 04\/07\/19, na cidade de Juazeiro, no bairro Lomanto Junior. Tratava-se da moto HONDA\/BROS de cor preta, placa PDC-0848.<\/p>\n<p style=\"text-align: justify;\">O acusado John klebison Gomes dos Santos, natural de Juazeiro e o ve\u00edculo foram apresentados na Delegacia de Pol\u00edcia Civil em Juazeiro, onde foi autuado em flagrante delito, conforme ocorr\u00eancia 19\/00515, da DP de Sobradinho- BA.<\/p>\n<pre style=\"text-align: justify;\">ASCOM COMANDO DE POLICIAMENTO DA REGI\u00c3O NORTE<\/pre>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>Por volta das 15h50 do dia 05\/07, a guarni\u00e7\u00e3o PETO (96\u00aa CIPM\/SOBRADINHO) composta pelos soldados Adams, Denis e Fernandes, recebeu a informa\u00e7\u00e3o de que havia um indiv\u00edduo tentando vender uma moto HONDA\/BROS de cor preta, sem placa, pela quantia de R$ 1.000,00 (mil reais), provavelmente fruto de algum il\u00edcito. Quando efetuava ronda na Vila S\u00e3o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1216,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[199,203,202],"tags":[143,33,195],"class_list":["post-1195","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bahia","category-juazeiro","category-policia","tag-juazeiro-da-bahia","tag-policia-militar","tag-sodradinho"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2019\/07\/NOVA-DO-LADR.jpg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2019\/07\/NOVA-DO-LADR.jpg",940,788,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2019\/07\/NOVA-DO-LADR-150x150.jpg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2019\/07\/NOVA-DO-LADR-300x251.jpg",300,251,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2019\/07\/NOVA-DO-LADR-768x644.jpg",640,537,true],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2019\/07\/NOVA-DO-LADR.jpg",640,537,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2019\/07\/NOVA-DO-LADR.jpg",940,788,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2019\/07\/NOVA-DO-LADR.jpg",940,788,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2019\/07\/NOVA-DO-LADR.jpg",884,741,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2019\/07\/NOVA-DO-LADR.jpg",366,307,false],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2019\/07\/NOVA-DO-LADR.jpg",300,251,false],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2019\/07\/NOVA-DO-LADR.jpg",346,290,false],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2019\/07\/NOVA-DO-LADR.jpg",596,500,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2019\/07\/NOVA-DO-LADR.jpg",274,230,false],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2019\/07\/NOVA-DO-LADR.jpg",766,642,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"Por volta das 15h50 do dia 05\/07, a guarni\u00e7\u00e3o PETO (96\u00aa CIPM\/SOBRADINHO) composta pelos soldados Adams, Denis e Fernandes, recebeu a informa\u00e7\u00e3o de que havia um indiv\u00edduo tentando vender uma moto HONDA\/BROS de cor preta, sem placa, pela quantia de R$ 1.000,00 (mil reais), provavelmente fruto de algum il\u00edcito. Quando efetuava ronda na Vila S\u00e3o&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1195","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=1195"}],"version-history":[{"count":3,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1195\/revisions"}],"predecessor-version":[{"id":1199,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1195\/revisions\/1199"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/1216"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=1195"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=1195"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=1195"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}