{"id":13497,"date":"2020-08-16T08:27:24","date_gmt":"2020-08-16T11:27:24","guid":{"rendered":"http:\/\/blogopara.com.br\/?p=13497"},"modified":"2020-08-15T22:01:07","modified_gmt":"2020-08-16T01:01:07","slug":"covid-suspeitas-de-desvios-em-jacobina-vitoria-da-conquista-barreiras-e-juazeiro","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2020\/08\/16\/covid-suspeitas-de-desvios-em-jacobina-vitoria-da-conquista-barreiras-e-juazeiro","title":{"rendered":"Covid: Suspeitas de desvios em Jacobina, Vit\u00f3ria da Conquista, Barreiras e Juazeiro"},"content":{"rendered":"<p style=\"text-align: justify;\">Destaque na coluna \u201cO Carrasco\u201d do jornal A Tarde \u00e9 o valor repassado pelo governo Jair Messias Bolsonaro para o Estado da Bahia: R$ 1,2 bilh\u00e3o.\u00a0<strong>A coluna questiona o destino desse dinheiro nos diversos munic\u00edpios, em especial Jacobina, Vit\u00f3ria da Conquista, Barreiras e Juazeiro.<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-135127 alignleft tie-appear\" src=\"https:\/\/tvservidor.com.br\/wp-content\/uploads\/2020\/08\/xprefeito-de-jacobina-dem-democratas-bahia.jpg.pagespeed.ic.XZP-BO7prH.jpg\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" srcset=\"https:\/\/tvservidor.com.br\/wp-content\/uploads\/2020\/08\/prefeito-de-jacobina-dem-democratas-bahia.jpg 200w, https:\/\/tvservidor.com.br\/wp-content\/uploads\/2020\/08\/prefeito-de-jacobina-dem-democratas-bahia-150x150.jpg 150w\" alt=\"\" width=\"200\" height=\"200\" \/>Jacobina \u2013 Prefeito Luciano Ant\u00f4nio Riberiro (DEM):<\/strong><\/p>\n<p style=\"text-align: justify;\">O prefeito da cidade recebeu da Uni\u00e3o R$ 13,8 milh\u00f5es. Diz a coluna:\u00a0<em><strong>\u201cna cidade, s\u00f3 se fala na busca dele pela reelei\u00e7\u00e3o e a popula\u00e7\u00e3o j\u00e1 questiona onde foi aplicado tanto dinheiro que deveria ser para ajudar os moradores, que j\u00e1 s\u00e3o quase 400 infectados\u201d.<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-135128 alignright tie-appear\" src=\"https:\/\/tvservidor.com.br\/wp-content\/uploads\/2020\/08\/xherem-gusmao-vitoria-da-conquista-bahia.jpg.pagespeed.ic._HiwFxKw-k.jpg\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" srcset=\"https:\/\/tvservidor.com.br\/wp-content\/uploads\/2020\/08\/herem-gusmao-vitoria-da-conquista-bahia.jpg 200w, https:\/\/tvservidor.com.br\/wp-content\/uploads\/2020\/08\/herem-gusmao-vitoria-da-conquista-bahia-150x150.jpg 150w\" alt=\"\" width=\"200\" height=\"200\" \/>Vit\u00f3ria da Conquista \u2013 Herzem Gusm\u00e3o (PMDB):<\/strong><\/p>\n<p style=\"text-align: justify;\">A gest\u00e3o municipal foi agraciada com o valor de R$ 17.697.853,03 como consequ\u00eancia do combate ao V\u00edrus Chin\u00eas. Diz a coluna:<em><strong>\u00a0\u201cA briga pela reelei\u00e7\u00e3o est\u00e1 acirrada e ele (Herzem Gusm\u00e3o), sabendo que a candidatura est\u00e1 amea\u00e7ada, n\u00e3o perdeu tempo para fortalecer seu nome e se manter como prefeito da cidade do frio. Com isso, o emedebista esqueceu que os quase R$ 18 milh\u00f5es deveriam ser aplicados para combater a Covid na cidade e garantir atendimento \u00e0 popula\u00e7\u00e3o\u201d.<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-135129 alignleft tie-appear\" src=\"https:\/\/tvservidor.com.br\/wp-content\/uploads\/2020\/08\/xbarreiras-bahia.jpg.pagespeed.ic.3Qs2H5M9bw.jpg\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" srcset=\"https:\/\/tvservidor.com.br\/wp-content\/uploads\/2020\/08\/barreiras-bahia.jpg 200w, https:\/\/tvservidor.com.br\/wp-content\/uploads\/2020\/08\/barreiras-bahia-150x150.jpg 150w\" alt=\"\" width=\"200\" height=\"200\" \/>Barreiras \u2013 Zito Barbosa (DEM)<\/strong><\/p>\n<p style=\"text-align: justify;\">Filiado ao Democratas, Zito Barbosa recebeu R$ 15 milh\u00f5es para combater o avan\u00e7o do V\u00edrus Chin\u00eas na cidade de Barreiras, um dos munic\u00edpios mais \u201cricos\u201d de todo o Estado da Bahia. Diz a coluna:\u00a0<em><strong>\u201cparece que a gest\u00e3o deste montante vai de mal a pior. Focado no dia das urnas que est\u00e1 cada vez mais pr\u00f3ximo, Zito deixa a pandemia de lado para se preocupar com pesquisas eleitorais\u201d.<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-135130 alignright tie-appear\" src=\"https:\/\/tvservidor.com.br\/wp-content\/uploads\/2020\/08\/xjuazeiro-bahia-pt.jpg.pagespeed.ic.Ob3yHvaLly.jpg\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" srcset=\"https:\/\/tvservidor.com.br\/wp-content\/uploads\/2020\/08\/juazeiro-bahia-pt.jpg 200w, https:\/\/tvservidor.com.br\/wp-content\/uploads\/2020\/08\/juazeiro-bahia-pt-150x150.jpg 150w\" alt=\"\" width=\"200\" height=\"200\" \/>Juazeiro \u2013 Paulo Bonfim (PT)<\/strong><\/p>\n<p style=\"text-align: justify;\">O prefeito petista de Juazeiro abocanhou R$ 13 milh\u00f5es da Uni\u00e3o para combater o V\u00edrus Chin\u00eas. Diz a coluna:\u00a0<em><strong>\u201co prefeito desfilou tanto para fazer campanha que tamb\u00e9m testou positivo para a doen\u00e7a. Al\u00e9m de pedir voto por a\u00ed, o que intriga os eleitores \u00e9 o fato dele n\u00e3o aplicar o que recebeu da Uni\u00e3o para ajudar a popula\u00e7\u00e3o neste per\u00edodo da pandemia.\u201d <\/strong><\/em>Afinal, aonde est\u00e1 o dinheiro que chegou at\u00e9 a\u00ed Bonfim? Perguntar n\u00e3o ofende.<\/p>\n<p style=\"text-align: justify;\">Fonte: TvServidor<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Destaque na coluna \u201cO Carrasco\u201d do jornal A Tarde \u00e9 o valor repassado pelo governo Jair Messias Bolsonaro para o Estado da Bahia: R$ 1,2 bilh\u00e3o.\u00a0A coluna questiona o destino desse dinheiro nos diversos munic\u00edpios, em especial Jacobina, Vit\u00f3ria da Conquista, Barreiras e Juazeiro. Jacobina \u2013 Prefeito Luciano Ant\u00f4nio Riberiro (DEM): O prefeito da cidade [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":13498,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[199,197,205],"tags":[],"class_list":["post-13497","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bahia","category-politica","category-saude"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/08\/juazeiro-barreiras-vitoria-da-conquista-jacobina-bahia-jair-messias-bolsonaro-covidao-desvio.jpg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/08\/juazeiro-barreiras-vitoria-da-conquista-jacobina-bahia-jair-messias-bolsonaro-covidao-desvio.jpg",500,223,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/08\/juazeiro-barreiras-vitoria-da-conquista-jacobina-bahia-jair-messias-bolsonaro-covidao-desvio-150x150.jpg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/08\/juazeiro-barreiras-vitoria-da-conquista-jacobina-bahia-jair-messias-bolsonaro-covidao-desvio-300x134.jpg",300,134,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/08\/juazeiro-barreiras-vitoria-da-conquista-jacobina-bahia-jair-messias-bolsonaro-covidao-desvio.jpg",500,223,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/08\/juazeiro-barreiras-vitoria-da-conquista-jacobina-bahia-jair-messias-bolsonaro-covidao-desvio.jpg",500,223,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/08\/juazeiro-barreiras-vitoria-da-conquista-jacobina-bahia-jair-messias-bolsonaro-covidao-desvio.jpg",500,223,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/08\/juazeiro-barreiras-vitoria-da-conquista-jacobina-bahia-jair-messias-bolsonaro-covidao-desvio.jpg",500,223,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/08\/juazeiro-barreiras-vitoria-da-conquista-jacobina-bahia-jair-messias-bolsonaro-covidao-desvio.jpg",500,223,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/08\/juazeiro-barreiras-vitoria-da-conquista-jacobina-bahia-jair-messias-bolsonaro-covidao-desvio-420x223.jpg",420,223,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/08\/juazeiro-barreiras-vitoria-da-conquista-jacobina-bahia-jair-messias-bolsonaro-covidao-desvio-300x223.jpg",300,223,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/08\/juazeiro-barreiras-vitoria-da-conquista-jacobina-bahia-jair-messias-bolsonaro-covidao-desvio-464x223.jpg",464,223,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/08\/juazeiro-barreiras-vitoria-da-conquista-jacobina-bahia-jair-messias-bolsonaro-covidao-desvio.jpg",500,223,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/08\/juazeiro-barreiras-vitoria-da-conquista-jacobina-bahia-jair-messias-bolsonaro-covidao-desvio-322x223.jpg",322,223,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/08\/juazeiro-barreiras-vitoria-da-conquista-jacobina-bahia-jair-messias-bolsonaro-covidao-desvio.jpg",500,223,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"Destaque na coluna \u201cO Carrasco\u201d do jornal A Tarde \u00e9 o valor repassado pelo governo Jair Messias Bolsonaro para o Estado da Bahia: R$ 1,2 bilh\u00e3o.\u00a0A coluna questiona o destino desse dinheiro nos diversos munic\u00edpios, em especial Jacobina, Vit\u00f3ria da Conquista, Barreiras e Juazeiro. Jacobina \u2013 Prefeito Luciano Ant\u00f4nio Riberiro (DEM): O prefeito da cidade&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/13497","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=13497"}],"version-history":[{"count":2,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/13497\/revisions"}],"predecessor-version":[{"id":13500,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/13497\/revisions\/13500"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/13498"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=13497"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=13497"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=13497"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}