{"id":14120,"date":"2020-09-08T13:13:05","date_gmt":"2020-09-08T16:13:05","guid":{"rendered":"http:\/\/blogopara.com.br\/?p=14120"},"modified":"2020-09-08T13:28:38","modified_gmt":"2020-09-08T16:28:38","slug":"juazeiro-bateu-o-desespero-paulo-bomfim-cumpre-agenda-com-catolicos-e-evangelicos-nessa-terca-feira-08","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2020\/09\/08\/juazeiro-bateu-o-desespero-paulo-bomfim-cumpre-agenda-com-catolicos-e-evangelicos-nessa-terca-feira-08","title":{"rendered":"Juazeiro: Bateu o desespero? Paulo Bomfim cumpre agenda com cat\u00f3licos e evang\u00e9licos nessa ter\u00e7a-feira (08)"},"content":{"rendered":"<p style=\"text-align: justify;\">Embora muito simpatizantes da candidatura do prefeito Paulo Bomfim (PT) n\u00e3o sejam simpatizantes dos evang\u00e9licos, principalmente dos neopentecostais, mas o governo desde o seu in\u00edcio oscila entre os evang\u00e9licos e os povos de terreiros, dois grupos religiosos que n\u00e3o se comunicam bem.<\/p>\n<p style=\"text-align: justify;\">Com a presen\u00e7a dominante no governo, os pastores ditos evang\u00e9licos, organizaram sob os arrepios do artigo 19 da Constitui\u00e7\u00e3o, &#8221; A quarta-feira de ora\u00e7\u00e3o no gabinete do prefeito&#8221;.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-14121\" src=\"https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/09\/WhatsApp-Image-2019-05-29-at-18.38.42-300x225.jpeg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/09\/WhatsApp-Image-2019-05-29-at-18.38.42-300x225.jpeg 300w, https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/09\/WhatsApp-Image-2019-05-29-at-18.38.42.jpeg 712w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p style=\"text-align: justify;\">O prefeito \u00e9 passivo de perda do cargo, pois assim reza a Constitui\u00e7\u00e3o: &#8220;\u00c9 vedado \u00e0 Uni\u00e3o, aos Estados, ao Distrito Federal e aos Munic\u00edpios: <strong>I<\/strong> &#8211; estabelecer cultos religiosos ou igrejas, subvencion\u00e1-los, embara\u00e7ar-lhes o funcionamento ou manter com eles ou seus representantes rela\u00e7\u00f5es de depend\u00eancia ou alian\u00e7a, ressalvada, na forma da lei, a colabora\u00e7\u00e3o de interesse p\u00fablico&#8221;.<\/p>\n<p style=\"text-align: justify;\">A rela\u00e7\u00e3o do governo com os Povos de Terreiro, \u00e9 meramente para se aproximar dos movimentos sociais, durante esses \u00faltimos 12 anos n\u00e3o existe nenhuma pol\u00edtica p\u00fablica voltada para os Terreiros em Juazeiro, muito pelo contr\u00e1rio, acirram-se as agress\u00f5es e a exclus\u00e3o social.<\/p>\n<p style=\"text-align: justify;\">Agora no final da gest\u00e3o, e as v\u00e9speras das elei\u00e7\u00f5es o governo volta a se aproximar dos cat\u00f3licos, e reafirmar o seu compromisso majorit\u00e1rio com os evang\u00e9licos.<\/p>\n<p style=\"text-align: justify;\">Hoje, comemora-se o fim do Noven\u00e1rio a Nossa Senhora das Grotas, a padroeira de Juazeiro, e nesta mesma data, o prefeito marcou compromissos pol\u00edticos com&nbsp; cat\u00f3licos e evang\u00e9licos. O que dir\u00e1s aos cat\u00f3licos e aos evang\u00e9licos? Aos cat\u00f3licos dir\u00e1 que Nossa Senhora \u00e9 a nossa padroeira? E aos evang\u00e9licos dir\u00e1 que n\u00e3o devemos adorar imagens? Ou mentir\u00e1s para os dois, como faz com os Povos de Terreiros?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Embora muito simpatizantes da candidatura do prefeito Paulo Bomfim (PT) n\u00e3o sejam simpatizantes dos evang\u00e9licos, principalmente dos neopentecostais, mas o governo desde o seu in\u00edcio oscila entre os evang\u00e9licos e os povos de terreiros, dois grupos religiosos que n\u00e3o se comunicam bem. Com a presen\u00e7a dominante no governo, os pastores ditos evang\u00e9licos, organizaram sob os [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":14124,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[203],"tags":[],"class_list":["post-14120","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-juazeiro"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/09\/e673f926-7166-41b1-919a-8df6cf338ada.jpg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/09\/e673f926-7166-41b1-919a-8df6cf338ada.jpg",500,500,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/09\/e673f926-7166-41b1-919a-8df6cf338ada-150x150.jpg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/09\/e673f926-7166-41b1-919a-8df6cf338ada-300x300.jpg",300,300,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/09\/e673f926-7166-41b1-919a-8df6cf338ada.jpg",500,500,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/09\/e673f926-7166-41b1-919a-8df6cf338ada.jpg",500,500,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/09\/e673f926-7166-41b1-919a-8df6cf338ada.jpg",500,500,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/09\/e673f926-7166-41b1-919a-8df6cf338ada.jpg",500,500,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/09\/e673f926-7166-41b1-919a-8df6cf338ada.jpg",500,500,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/09\/e673f926-7166-41b1-919a-8df6cf338ada-420x307.jpg",420,307,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/09\/e673f926-7166-41b1-919a-8df6cf338ada-300x443.jpg",300,443,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/09\/e673f926-7166-41b1-919a-8df6cf338ada-464x290.jpg",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/09\/e673f926-7166-41b1-919a-8df6cf338ada.jpg",500,500,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/09\/e673f926-7166-41b1-919a-8df6cf338ada-322x230.jpg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/09\/e673f926-7166-41b1-919a-8df6cf338ada.jpg",500,500,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"Embora muito simpatizantes da candidatura do prefeito Paulo Bomfim (PT) n\u00e3o sejam simpatizantes dos evang\u00e9licos, principalmente dos neopentecostais, mas o governo desde o seu in\u00edcio oscila entre os evang\u00e9licos e os povos de terreiros, dois grupos religiosos que n\u00e3o se comunicam bem. Com a presen\u00e7a dominante no governo, os pastores ditos evang\u00e9licos, organizaram sob os&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/14120","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=14120"}],"version-history":[{"count":4,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/14120\/revisions"}],"predecessor-version":[{"id":14133,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/14120\/revisions\/14133"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/14124"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=14120"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=14120"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=14120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}