{"id":1670,"date":"2019-07-17T07:49:35","date_gmt":"2019-07-17T10:49:35","guid":{"rendered":"http:\/\/blogopara.com.br\/?p=1670"},"modified":"2019-07-17T07:49:42","modified_gmt":"2019-07-17T10:49:42","slug":"universidade-com-campi-na-ba-e-no-ce-cancela-vestibular-para-transgeneros-e-intersexuais-apos-pedido-do-mec","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2019\/07\/17\/universidade-com-campi-na-ba-e-no-ce-cancela-vestibular-para-transgeneros-e-intersexuais-apos-pedido-do-mec","title":{"rendered":"Universidade com campi na BA e no CE cancela vestibular para transg\u00eaneros e intersexuais ap\u00f3s pedido do MEC"},"content":{"rendered":"<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"33\" data-block-id=\"2\">\n<p class=\"content-text__container \" style=\"text-align: justify;\" data-track-category=\"Link no Texto\" data-track-links=\"\">A Universidade da Integra\u00e7\u00e3o da Lusofonia Afro-Brasileira (Unilab) cancelou o vestibular espec\u00edfico para candidatos transg\u00eaneros e intersexuais das unidades da institui\u00e7\u00e3o na Bahia e no Cear\u00e1, ap\u00f3s interven\u00e7\u00e3o do Minist\u00e9rio da Educa\u00e7\u00e3o (MEC).<\/p>\n<\/div>\n<div class=\"wall protected-content\">\n<div class=\"mc-column content-text active-extra-styles \" style=\"text-align: justify;\" data-block-type=\"unstyled\" data-block-weight=\"13\" data-block-id=\"3\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">A informa\u00e7\u00e3o foi divulgada pelo presidente Jair Bolsonaro, nesta ter\u00e7a-feira (16), no Twitter.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" style=\"text-align: justify;\" data-block-type=\"unstyled\" data-block-weight=\"45\" data-block-id=\"4\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">&#8220;A Universidade da Integra\u00e7\u00e3o da Lusofonia Afro-Brasileira (Federal) lan\u00e7ou vestibular para candidatos TRANSEXUAL (sic), TRAVESTIS, INTERSEXUAIS e pessoas N\u00c3O BIN\u00c1RIOS. Com interven\u00e7\u00e3o do MEC, a reitoria se posicionou pela suspens\u00e3o imediata do edital e sua anula\u00e7\u00e3o a posteriori&#8221;, escreveu o presidente em suas redes sociais.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" style=\"text-align: justify;\" data-block-type=\"unstyled\" data-block-weight=\"50\" data-block-id=\"5\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Em nota, o MEC informou que questionou a legalidade do processo seletivo na Unilab, via Procuradoria Geral da Rep\u00fablica (PGR). Segundo o Minist\u00e9rio da Educa\u00e7\u00e3o, a motiva\u00e7\u00e3o do pedido foi o fato de que &#8220;a Lei de Cotas n\u00e3o prev\u00ea vagas espec\u00edficas para o p\u00fablico alvo do citado vestibular&#8221;.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" style=\"text-align: justify;\" data-block-type=\"unstyled\" data-block-weight=\"39\" data-block-id=\"6\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Ainda de acordo com o MEC, a institui\u00e7\u00e3o de ensino n\u00e3o apresentou parecer com base legal para elabora\u00e7\u00e3o da pol\u00edtica afirmativa de cotas, conforme edital lan\u00e7ado na semana passada e, por isso, a universidade solicitou o cancelamento do certame.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" style=\"text-align: justify;\" data-block-type=\"unstyled\" data-block-weight=\"32\" data-block-id=\"7\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Tamb\u00e9m por meio de nota, a Universidade da Integra\u00e7\u00e3o Internacional da Lusofonia Afro-Brasileira (Unilab) disse que anulou o processo seletivo &#8220;considerando o Parecer n. 81\/2019, emitido pela Procuradoria Federal junto \u00e0 institui\u00e7\u00e3o&#8221;.<\/p>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"30\" data-block-id=\"9\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Ainda no comunicado, a Unilab disse que o &#8220;processo seletivo visava \u00e0 ocupa\u00e7\u00e3o de vagas ociosas, que n\u00e3o foram preenchidas por editais regulares da Unilab, notadamente aqueles baseados no Enem\/SiSU&#8221;.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"48\" data-block-id=\"10\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Conforme a institui\u00e7\u00e3o, a PGR \u00e9 respons\u00e1vel por orientar que os atos administrativos da universidade estejam em conformidade com a legisla\u00e7\u00e3o vigente e entendeu de que o edital vai de encontro \u00e0 Lei de Cotas e aos princ\u00edpios da razoabilidade, proporcionalidade e da ampla concorr\u00eancia em sele\u00e7\u00f5es p\u00fablicas.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles\" data-block-type=\"raw\" data-block-weight=\"1\" data-block-id=\"11\">\n<div class=\"content-intertitle\">\n<h2>Vestibular<\/h2>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"49\" data-block-id=\"13\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">A Unilab \u00e9 uma institui\u00e7\u00e3o federal e lan\u00e7ou o processo seletivo na \u00faltima quarta-feira (10), com 120 vagas em 15 cursos presenciais em tr\u00eas campi \u2014 S\u00e3o Francisco do Conde (BA), Reden\u00e7\u00e3o e Acarape (CE). Os cursos de gradua\u00e7\u00e3o presencial tinham ingresso previsto no dia 30 de setembro.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"27\" data-block-id=\"14\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Na Bahia, foram disponibilizadas 51 vagas nos seguintes cursos de gradua\u00e7\u00e3o: Ci\u00eancias Sociais (8), Hist\u00f3ria (8), Humanidades (8) Letras\/L\u00edngua Portuguesa (9) Pedagogia (8), Rela\u00e7\u00f5es Internacionais (10).<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"42\" data-block-id=\"15\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">J\u00e1 para o Cear\u00e1 eram 69 vagas para os cursos de Administra\u00e7\u00e3o P\u00fablica (5), Agronomia (2), Antropologia (10), Ci\u00eancias Biol\u00f3gicas (2), Enfermagem (6), Hist\u00f3ria (10), Humanidades (10) Letras\/L\u00edngua Inglesa (1), Letras\/L\u00edngua Portuguesa (3), Matem\u00e1tica (3), Pedagogia (8), Qu\u00edmica (4), Sociologia (5).<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"16\" data-block-id=\"16\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">As inscri\u00e7\u00f5es come\u00e7aram na segunda-feira (15) e ficariam abertas at\u00e9 o dia 24 de julho.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"content-ads content-ads--reveal\" data-block-type=\"ads\" data-block-id=\"8\">\n<pre id=\"banner_materia2\" class=\"tag-manager-publicidade-container mc-has-reveal mc-has-ad-lazyload tag-manager-publicidade-banner_materia2 tag-manager-publicidade-container--carregado tag-manager-publicidade-container--visivel\" style=\"text-align: justify;\" data-id=\"banner_materia2\" data-google-query-id=\"CKn0vf3iu-MCFZcahwodzYIIpQ\" data-cid=\"138274541972\" data-lid=\"5106561488\">\u00a0Fonte: G1<\/pre>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Processo seletivo disponibilizava 51 vagas de cursos de gradua\u00e7\u00f5es na Bahia e 69 vagas para o Cear\u00e1. Presidente Jair Bolsonaro falou sobre cancelamento nesta ter\u00e7a-feira (16), no Twitter.<\/p>\n","protected":false},"author":1,"featured_media":1671,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[200],"tags":[21,282,280,281],"class_list":["post-1670","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil","tag-bolsonaro","tag-intersexuais","tag-mec","tag-transgeneros"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2019\/07\/mec.jpg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2019\/07\/mec.jpg",984,656,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2019\/07\/mec-150x150.jpg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2019\/07\/mec-300x200.jpg",300,200,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2019\/07\/mec-768x512.jpg",640,427,true],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2019\/07\/mec.jpg",640,427,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2019\/07\/mec.jpg",984,656,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2019\/07\/mec.jpg",984,656,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2019\/07\/mec.jpg",984,656,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2019\/07\/mec.jpg",420,280,false],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2019\/07\/mec.jpg",300,200,false],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2019\/07\/mec.jpg",435,290,false],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2019\/07\/mec.jpg",600,400,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2019\/07\/mec.jpg",322,215,false],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2019\/07\/mec.jpg",963,642,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"Processo seletivo disponibilizava 51 vagas de cursos de gradua\u00e7\u00f5es na Bahia e 69 vagas para o Cear\u00e1. Presidente Jair Bolsonaro falou sobre cancelamento nesta ter\u00e7a-feira (16), no Twitter.","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1670","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=1670"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1670\/revisions"}],"predecessor-version":[{"id":1672,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1670\/revisions\/1672"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/1671"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=1670"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=1670"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=1670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}