{"id":16919,"date":"2020-12-10T11:22:30","date_gmt":"2020-12-10T14:22:30","guid":{"rendered":"http:\/\/blogopara.com.br\/?p=16919"},"modified":"2020-12-10T11:46:10","modified_gmt":"2020-12-10T14:46:10","slug":"juazeiro-camara-concede-titulo-de-cidada-a-pesquisadora-francisca-nemaura-haji","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2020\/12\/10\/juazeiro-camara-concede-titulo-de-cidada-a-pesquisadora-francisca-nemaura-haji","title":{"rendered":"Juazeiro: C\u00e2mara concede t\u00edtulo de cidad\u00e3 a pesquisadora Francisca Nemaura Haji"},"content":{"rendered":"<p style=\"text-align: justify;\">Numa sess\u00e3o solene marcada para essa quinta-feira (10), a C\u00e2mara Municipal de Juazeiro conceder\u00e1 a pesquisadora Francisca Nemaura Pedrosa Haji, o t\u00edtulo de cidad\u00e3 juazeirense. Uma honraria concedida pelos relevantes servi\u00e7os prestados \u00e0 comunidade, principalmente nas pesquisas na Moscamed com cria\u00e7\u00e3o de inimigos naturais diversos.<\/p>\n<p style=\"text-align: justify;\">CURR\u00cdCULO VITAE&nbsp; RESUMIDO DA HOMENAGEADA<\/p>\n<p style=\"text-align: justify;\">Francisca Nemaura Pedrosa Haji, filha de Boaventura de Sousa Pedrosa e Ant\u00f4nia Tavares Pedrosa, nasceu em 03.12.1939, em Nova Russas, Cear\u00e1, casada com Alberto Takero Haji, e radicada em Petrolina-PE, desde fevereiro 1982.&nbsp; Tem dois filhos: Andr\u00e9a Maria Pedrosa Haji e Alberto Takero Haji J\u00fanior e quatro netos. \u00c9 Engenheira Agr\u00f4noma pela Escola de Agronomia da Universidade Federal do Cear\u00e1 (UFC), com Mestrado (ago.1974\/mai.1977) e Doutorado (ago.1977\/jun.1981) em Entomologia, ambos, pela Escola Superior de Agricultura \u201cLuiz de Queiroz\u201d (ESALQ) da Universidade de S\u00e3o Paulo (USP). Foi Bolsista do CNPq no curso de P\u00f3s-Gradua\u00e7\u00e3o e, como pesquisadora, recebeu bolsa de Auxilio \u00e0 Pesquisa.<\/p>\n<p style=\"text-align: justify;\">Trabalhou na Secretaria de Agricultura do Estado do Cear\u00e1, com Fomento e Extens\u00e3o, atuando como Chefe da Resid\u00eancia Agropecu\u00e1ria de Nova Russas (1967\/1972). Em julho de 1972 foi transferida para o Departamento de Fitossanidade,&nbsp;da Secretaria de Agricultura do Estado do Cear\u00e1, em Fortaleza,&nbsp; para Chefiar o Setor dos Servi\u00e7os de Testes de Campo (Fungicidas)&nbsp;at\u00e9 jul.\/1974. De fev.\/1982 a dez.\/2005, trabalhou como pesquisadora, na Empresa Brasileira de Pesquisa Agropecu\u00e1ria \u2013 EMBRAPA &#8211; Embrapa Semi\u00e1rido, em Petrolina, respons\u00e1vel pelo Laborat\u00f3rio de Entomologia, atuando nas&nbsp;principais linhas de pesquisa: biologia, controle de pragas e manejo integrado de pragas. Foi a primeira pesquisadora com o t\u00edtulo de doutorado da Embrapa Semi\u00e1rido.<\/p>\n<p style=\"text-align: justify;\">Liderou importantes projetos de pesquisa que impactaram o setor produtivo, na viabiliza\u00e7\u00e3o das exporta\u00e7\u00f5es de manga e uvas finas de mesa da regi\u00e3o do Semi\u00e1rido do Vale do S\u00e3o, para o mercado internacional, como:&nbsp;Programa de monitoramento de moscas-das-frutas na cultura da manga no Subm\u00e9dio do Vale do S\u00e3o Francisco e Produ\u00e7\u00e3o Integrada de Uvas Finas de Mesa no Subm\u00e9dio do Vale do S\u00e3o Francisco;&nbsp;Manejo integrado de pragas do tomateiro em \u00e1reas irrigadas do Subm\u00e9dio S\u00e3o Francisco; Controle biol\u00f3gico de&nbsp;<em>Tuta absoluta<\/em>&nbsp;(Lepidoptera: Gelechiidae) com uso de&nbsp;<em>Trichogramma pretiosum<\/em>&nbsp;(Hymenoptera: Trichogrammatidae) na cultura do tomate no Subm\u00e9dio do Vale do S\u00e3o Francisco; Manejo integrado da mosca-branca&nbsp;<em>Bemisia argentifolli&nbsp;<\/em>(Hemiptera: Aleyrodidae) em culturas irrigadas do Nordeste brasileiro; Manejo integrado da mosca-branca&nbsp;<em>Bemisia argentifolli&nbsp;<\/em>(Hemiptera: Aleyrodidae) na cultura da uva no Subm\u00e9dio do Vale do S\u00e3o Francisco; Manejo integrado da mosca-branca&nbsp;<em>Bemisia argentifolli&nbsp;<\/em>(Hemiptera: Aleyrodidae) na cultura do tomate no Subm\u00e9dio do Vale do S\u00e3o Francisco; Bioecologia e alternativas de controle para o manejo integrado de&nbsp;<em>Cryptoblabes gnidiella<strong>&nbsp;<\/strong><\/em>(Milli\u00e8re, 1867)(Lepidoptera: Pyralidae) no sistema de Produ\u00e7\u00e3o Integrada de Uva no Subm\u00e9dio do Vale do&nbsp;&nbsp;S\u00e3o Francisco<strong>. <\/strong><\/p>\n<p style=\"text-align: justify;\">Publicou 22 trabalhos em peri\u00f3dicos; 62 trabalhos\/resumos apresentados em Congressos\/Eventos t\u00e9cnicos\/cient\u00edfico; 19 livros\/cap\u00edtulos; 07 orienta\u00e7\u00e3o\/co-orienta\u00e7\u00e3o de disserta\u00e7\u00f5es\/teses; 07 participa\u00e7\u00f5es em bancas examinadoras; 55 produ\u00e7\u00f5es t\u00e9cnicas; 07 pr\u00eamios\/t\u00edtulos recebidos. Como pesquisadora aposentada da Embrapa, recebeu as seguintes homenagens:<\/p>\n<p style=\"text-align: justify;\">* Da Sociedade Entomol\u00f3gica do Brasil (SEB), em mar\u00e7o de 2016, no &nbsp;XXVI&nbsp; &nbsp;Congresso Brasileiro de Entomologia e IX Congresso Latino-americano de&nbsp; Entomologia, em Macei\u00f3-AL, como reconhecimento ao seu trabalho merit\u00f3rio em Entomologia.<\/p>\n<p style=\"text-align: justify;\">&nbsp;* Em 2017, na SEB, passou a integrar a lista dos Grandes Entomologistas Brasileiros.<\/p>\n<p style=\"text-align: justify;\">&nbsp;* Da Sociedade Brasileira de Fruticultura, no XXVI Congresso Brasileiro de&nbsp; &nbsp;Fruticultura, realizado em outubro de 2019, em Juazeiro-BA\/Petrolina-PE \u2013&nbsp; Fruticultura de precis\u00e3o: desafios e oportunidades, em reconhecimento pelos relevantes servi\u00e7os prestados a Fruticultura Brasileira.<\/p>\n<p style=\"text-align: justify;\">* Em dezembro de 2019, no I Workshop de Mulheres do Agro \u201cMulheres que marcaram a Entomologia brasileira\u201d, realizado em Teresina-PI, pela Secretaria de Inova\u00e7\u00e3o e Neg\u00f3cios (SIN)\u2013EMBRAPA, Bras\u00edlia passou a figurar como uma das dez mulheres refer\u00eancia para a Entomologia brasileira, notadamente, na \u00e1rea de&nbsp;pesquisa.<\/p>\n<p style=\"text-align: justify;\">* Em janeiro de 2020, da Prefeitura Municipal de Petrolina, por ocasi\u00e3o da&nbsp; inaugura\u00e7\u00e3o do Centro Municipal de Ensino e Pesquisa em Seguran\u00e7a P\u00fablica, pelos relevantes servi\u00e7os prestados no campo da pesquisa, econ\u00f4mico e cultural, da regi\u00e3o do Semi\u00e1rido Nordestino.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-16921\" src=\"https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/12\/WhatsApp-Image-2020-12-09-at-18.28.45-1-300x217.jpeg\" alt=\"\" width=\"300\" height=\"217\" srcset=\"https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/12\/WhatsApp-Image-2020-12-09-at-18.28.45-1-300x217.jpeg 300w, https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/12\/WhatsApp-Image-2020-12-09-at-18.28.45-1-1024x740.jpeg 1024w, https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/12\/WhatsApp-Image-2020-12-09-at-18.28.45-1-768x555.jpeg 768w, https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/12\/WhatsApp-Image-2020-12-09-at-18.28.45-1-1020x741.jpeg 1020w, https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/12\/WhatsApp-Image-2020-12-09-at-18.28.45-1.jpeg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p style=\"text-align: justify;\"><strong>&nbsp;<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Numa sess\u00e3o solene marcada para essa quinta-feira (10), a C\u00e2mara Municipal de Juazeiro conceder\u00e1 a pesquisadora Francisca Nemaura Pedrosa Haji, o t\u00edtulo de cidad\u00e3 juazeirense. Uma honraria concedida pelos relevantes servi\u00e7os prestados \u00e0 comunidade, principalmente nas pesquisas na Moscamed com cria\u00e7\u00e3o de inimigos naturais diversos. CURR\u00cdCULO VITAE&nbsp; RESUMIDO DA HOMENAGEADA Francisca Nemaura Pedrosa Haji, filha [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":16923,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[203,197,204],"tags":[],"class_list":["post-16919","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-juazeiro","category-politica","category-social"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/12\/WhatsApp-Image-2020-12-10-at-10.25.40-1.jpeg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/12\/WhatsApp-Image-2020-12-10-at-10.25.40-1.jpeg",350,450,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/12\/WhatsApp-Image-2020-12-10-at-10.25.40-1-150x150.jpeg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/12\/WhatsApp-Image-2020-12-10-at-10.25.40-1-233x300.jpeg",233,300,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/12\/WhatsApp-Image-2020-12-10-at-10.25.40-1.jpeg",350,450,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/12\/WhatsApp-Image-2020-12-10-at-10.25.40-1.jpeg",350,450,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/12\/WhatsApp-Image-2020-12-10-at-10.25.40-1.jpeg",350,450,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/12\/WhatsApp-Image-2020-12-10-at-10.25.40-1.jpeg",350,450,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/12\/WhatsApp-Image-2020-12-10-at-10.25.40-1.jpeg",350,450,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/12\/WhatsApp-Image-2020-12-10-at-10.25.40-1-350x307.jpeg",350,307,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/12\/WhatsApp-Image-2020-12-10-at-10.25.40-1-300x443.jpeg",300,443,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/12\/WhatsApp-Image-2020-12-10-at-10.25.40-1-350x290.jpeg",350,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/12\/WhatsApp-Image-2020-12-10-at-10.25.40-1.jpeg",350,450,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/12\/WhatsApp-Image-2020-12-10-at-10.25.40-1-322x230.jpeg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/12\/WhatsApp-Image-2020-12-10-at-10.25.40-1.jpeg",350,450,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"Numa sess\u00e3o solene marcada para essa quinta-feira (10), a C\u00e2mara Municipal de Juazeiro conceder\u00e1 a pesquisadora Francisca Nemaura Pedrosa Haji, o t\u00edtulo de cidad\u00e3 juazeirense. Uma honraria concedida pelos relevantes servi\u00e7os prestados \u00e0 comunidade, principalmente nas pesquisas na Moscamed com cria\u00e7\u00e3o de inimigos naturais diversos. CURR\u00cdCULO VITAE&nbsp; RESUMIDO DA HOMENAGEADA Francisca Nemaura Pedrosa Haji, filha&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/16919","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=16919"}],"version-history":[{"count":4,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/16919\/revisions"}],"predecessor-version":[{"id":16930,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/16919\/revisions\/16930"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/16923"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=16919"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=16919"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=16919"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}