{"id":17782,"date":"2021-01-13T14:15:04","date_gmt":"2021-01-13T17:15:04","guid":{"rendered":"http:\/\/blogopara.com.br\/?p=17782"},"modified":"2021-01-13T14:49:42","modified_gmt":"2021-01-13T17:49:42","slug":"leitor-questiona-criterios-na-convocacao-de-aprovado-em-concurso-do-saae-orgao-esclarece","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2021\/01\/13\/leitor-questiona-criterios-na-convocacao-de-aprovado-em-concurso-do-saae-orgao-esclarece","title":{"rendered":"Leitor questiona crit\u00e9rios na convoca\u00e7\u00e3o de aprovado em concurso do SAAE; \u00f3rg\u00e3o esclarece"},"content":{"rendered":"<p style=\"text-align: justify;\">O concurso p\u00fablico realizado pelo Servi\u00e7o de \u00c1gua e Saneamento Ambiental (SAAE) de Juazeiro (BA) est\u00e1 sendo questionado quanto aos seus\u00a0<a href=\"http:\/\/www.asconprevconcursos.com.br\/index.php\/component\/jdownloads\/send\/10-concurso-saae-2019\/167-resultado-oficial-final\"><strong>crit\u00e9rios de convoca\u00e7\u00e3o<\/strong><\/a>. \u00c9 o que alerta um leitor deste Blog, que prefere o anonimato.<\/p>\n<p style=\"text-align: justify;\">Para ele houve uma\u00a0<em>\u201csuposta quebra de lisura\u201d<\/em>\u00a0referente \u00e0 convoca\u00e7\u00e3o do Concurso n\u00ba 001\/2019 do SAAE.<\/p>\n<p style=\"text-align: justify;\">\u201c<em>Conforme anexo 1, no Di\u00e1rio Oficial do Munic\u00edpio de Juazeiro, consta a Convoca\u00e7\u00e3o n\u00ba 001\/2020, datada de 16\/12\/2020, em raz\u00e3o do cumprimento de decis\u00e3o judicial. Contudo o candidato convocado, o\u00a0<a href=\"http:\/\/www.ipmbrasil.org.br\/visualizar-publicacoes?cod=3713&amp;file=87B31A2ED0193381E6BFE565A9F36E3A&amp;type=edicao\"><strong>Sr.Arthur Lucas da Silva Vieira<\/strong><\/a>\u00a0classificou-se na quinta posi\u00e7\u00e3o (conforme anexo 2), n\u00e3o sendo convocados, anteriormente, os outros candidatos que lograram melhor posi\u00e7\u00e3o classificat\u00f3ria, descumprindo, assim, a ordem de classifica\u00e7\u00e3o final do certame. Ainda que seja em raz\u00e3o de decis\u00e3o judicial, a quebra da ordem de convoca\u00e7\u00e3o, conforme a classifica\u00e7\u00e3o final do concurso, fere os regramentos e\u00a0 princ\u00edpios legais que regem a Administra\u00e7\u00e3o P\u00fablica<\/em>\u201d, relata.<\/p>\n<p style=\"text-align: justify;\"><strong>Resposta<\/strong><\/p>\n<p style=\"text-align: justify;\">Procurada pela reportagem, a dire\u00e7\u00e3o do SAAE esclareceu o questionamento por meio de nota enviada pela assessoria de comunica\u00e7\u00e3o. Confiram:<\/p>\n<p style=\"text-align: justify;\"><em>O SAAE esclarece que o resultado final do concurso foi homologado em 28 de janeiro de 2020 com prazo de validade de 02 anos e prorrog\u00e1veis por mais 02 anos. No entanto, logo ap\u00f3s a homologa\u00e7\u00e3o veio a pandemia em virtude da Covid-19, que ocasionou grandes impactos financeiros em todos os setores, inclusive na gest\u00e3o p\u00fablica. O Governo Federal editou a Lei Complementar n\u00ba 173 de 27 de maio de 2020, proibindo a contrata\u00e7\u00e3o de pessoal, conforme artigo 8\u00ba, incisos IV e V:<\/em><\/p>\n<p style=\"text-align: justify;\"><em>* Art. 8\u00ba \u2013 \u00a0Na hip\u00f3tese de que trata o art. 65 da Lei Complementar n\u00ba 101, de 4 de maio de 2000, a Uni\u00e3o, os Estados, o Distrito Federal e os Munic\u00edpios afetados pela calamidade p\u00fablica decorrente da pandemia da Covid-19 ficam proibidos, at\u00e9 31 de dezembro de 2021, de:<\/em><\/p>\n<p style=\"text-align: justify;\"><em>* IV \u2013 admitir ou contratar pessoal, a qualquer t\u00edtulo, ressalvadas as reposi\u00e7\u00f5es de cargos de chefia, de dire\u00e7\u00e3o e de assessoramento que n\u00e3o acarretem aumento de despesa, as reposi\u00e7\u00f5es decorrentes de vac\u00e2ncias de cargos efetivos ou vital\u00edcios, as contrata\u00e7\u00f5es tempor\u00e1rias de que trata o inciso IX do caput do art. 37 da Constitui\u00e7\u00e3o Federal, as contrata\u00e7\u00f5es de tempor\u00e1rios para presta\u00e7\u00e3o de servi\u00e7o militar e as contrata\u00e7\u00f5es de alunos de \u00f3rg\u00e3os de forma\u00e7\u00e3o de militares;<\/em><\/p>\n<p style=\"text-align: justify;\"><em>* V \u2013 realizar concurso p\u00fablico, exceto para as reposi\u00e7\u00f5es de vac\u00e2ncias previstas no inciso IV;<\/em><\/p>\n<p style=\"text-align: justify;\"><em>Assim sendo, a antiga gest\u00e3o do SAAE decidiu por n\u00e3o convocar imediatamente os aprovados no referido concurso, deixando para faz\u00ea-lo aos poucos e ao final da pandemia, haja vista a determina\u00e7\u00e3o da lei acima mencionada.<\/em><\/p>\n<p style=\"text-align: justify;\"><em>Com isso, durante esse per\u00edodo, um dos aprovados, Arthur Lucas da Silva Vieira, impetrou a\u00e7\u00e3o judicial requerente \u00e0 imediata contrata\u00e7\u00e3o. O juiz de primeiro grau concedeu uma liminar determinando sua contrata\u00e7\u00e3o provis\u00f3ria. Todavia, essa decis\u00e3o liminar tem car\u00e1ter apenas provis\u00f3rio, podendo ser modificada a qualquer momento, inclusive j\u00e1 existe recurso impetrado pelo SAAE pendente de julgamento no Tribunal de Justi\u00e7a da Bahia, tendo como um dos argumentos justamente o fato de que h\u00e1 outros aprovados em coloca\u00e7\u00e3o preferencial em rela\u00e7\u00e3o ao ora beneficiado.<\/em><\/p>\n<p style=\"text-align: justify;\"><em>Ainda, constata-se que h\u00e1 nos autos da a\u00e7\u00e3o judicial todas as informa\u00e7\u00f5es pertinentes ao concurso em baila, inclusive a informa\u00e7\u00e3o sobre coloca\u00e7\u00e3o de todos aprovados, entretanto, a decis\u00e3o judicial foi no sentido apenas de determinar a contrata\u00e7\u00e3o provis\u00f3ria \u00fanica e exclusivamente do Sr. Arthur, sem fazer qualquer men\u00e7\u00e3o aos outros aprovados. Portanto, o SAAE est\u00e1 apenas cumprindo estrita e integralmente a decis\u00e3o judicial.\u00a0\u00a0<\/em><\/p>\n<p style=\"text-align: justify;\">Fonte: Carlos Britto<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O concurso p\u00fablico realizado pelo Servi\u00e7o de \u00c1gua e Saneamento Ambiental (SAAE) de Juazeiro (BA) est\u00e1 sendo questionado quanto aos seus\u00a0crit\u00e9rios de convoca\u00e7\u00e3o. \u00c9 o que alerta um leitor deste Blog, que prefere o anonimato. Para ele houve uma\u00a0\u201csuposta quebra de lisura\u201d\u00a0referente \u00e0 convoca\u00e7\u00e3o do Concurso n\u00ba 001\/2019 do SAAE. \u201cConforme anexo 1, no Di\u00e1rio [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":17783,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[203,197],"tags":[],"class_list":["post-17782","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-juazeiro","category-politica"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/01\/SAAE-de-Juazeiro-1-696x533-1.png","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/01\/SAAE-de-Juazeiro-1-696x533-1.png",500,382,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/01\/SAAE-de-Juazeiro-1-696x533-1-150x150.png",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/01\/SAAE-de-Juazeiro-1-696x533-1-300x229.png",300,229,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/01\/SAAE-de-Juazeiro-1-696x533-1.png",500,382,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/01\/SAAE-de-Juazeiro-1-696x533-1.png",500,382,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/01\/SAAE-de-Juazeiro-1-696x533-1.png",500,382,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/01\/SAAE-de-Juazeiro-1-696x533-1.png",500,382,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/01\/SAAE-de-Juazeiro-1-696x533-1.png",500,382,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/01\/SAAE-de-Juazeiro-1-696x533-1-420x307.png",420,307,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/01\/SAAE-de-Juazeiro-1-696x533-1-300x382.png",300,382,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/01\/SAAE-de-Juazeiro-1-696x533-1-464x290.png",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/01\/SAAE-de-Juazeiro-1-696x533-1.png",500,382,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/01\/SAAE-de-Juazeiro-1-696x533-1-322x230.png",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/01\/SAAE-de-Juazeiro-1-696x533-1.png",500,382,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"O concurso p\u00fablico realizado pelo Servi\u00e7o de \u00c1gua e Saneamento Ambiental (SAAE) de Juazeiro (BA) est\u00e1 sendo questionado quanto aos seus\u00a0crit\u00e9rios de convoca\u00e7\u00e3o. \u00c9 o que alerta um leitor deste Blog, que prefere o anonimato. Para ele houve uma\u00a0\u201csuposta quebra de lisura\u201d\u00a0referente \u00e0 convoca\u00e7\u00e3o do Concurso n\u00ba 001\/2019 do SAAE. \u201cConforme anexo 1, no Di\u00e1rio&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/17782","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=17782"}],"version-history":[{"count":2,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/17782\/revisions"}],"predecessor-version":[{"id":17793,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/17782\/revisions\/17793"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/17783"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=17782"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=17782"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=17782"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}