{"id":19919,"date":"2021-02-21T09:00:00","date_gmt":"2021-02-21T12:00:00","guid":{"rendered":"http:\/\/blogopara.com.br\/?p=19919"},"modified":"2021-02-20T18:24:19","modified_gmt":"2021-02-20T21:24:19","slug":"petrolina-homem-e-assassinado-a-tiros-no-bairro-henrique-leite","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2021\/02\/21\/petrolina-homem-e-assassinado-a-tiros-no-bairro-henrique-leite","title":{"rendered":"Petrolina: Homem \u00e9 assassinado \u00e0 tiros no bairro Henrique Leite"},"content":{"rendered":"<p style=\"text-align: justify;\">Mais um crime cometido por disparos de arma de fogo aconteceu na cidade de Petrolina na manh\u00e3 deste s\u00e1bado (20). De acordo com informa\u00e7\u00f5es preliminares o crime ocorreu no bairro Henrique Leite.<\/p>\n<p style=\"text-align: justify;\">De acordo com testemunhas a v\u00edtima estava sob a companhia de algumas pessoas nas quais n\u00e3o tiveram suas identidades reveladas dentro de um ve\u00edculo, e que ao perceber que estava sendo perseguida tentou fugir, mas, acabou sendo alvejado com v\u00e1rios tiros na esquina da outra rua.<\/p>\n<p style=\"text-align: justify;\">Por enquanto a pol\u00edcia desconhece as causas para ter acontecido o crime.<\/p>\n<p style=\"text-align: justify;\">O corpo foi levado para o IML (Instituto M\u00e9dico Legal) e a Delegacia de Homic\u00eddio da Policia Civil j\u00e1 est\u00e1 investigando o caso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mais um crime cometido por disparos de arma de fogo aconteceu na cidade de Petrolina na manh\u00e3 deste s\u00e1bado (20). De acordo com informa\u00e7\u00f5es preliminares o crime ocorreu no bairro Henrique Leite. De acordo com testemunhas a v\u00edtima estava sob a companhia de algumas pessoas nas quais n\u00e3o tiveram suas identidades reveladas dentro de um [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":19920,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[203],"tags":[],"class_list":["post-19919","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-juazeiro"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/WhatsApp-Image-2021-02-20-at-14.28.51.jpeg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/WhatsApp-Image-2021-02-20-at-14.28.51.jpeg",500,666,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/WhatsApp-Image-2021-02-20-at-14.28.51-150x150.jpeg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/WhatsApp-Image-2021-02-20-at-14.28.51-225x300.jpeg",225,300,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/WhatsApp-Image-2021-02-20-at-14.28.51.jpeg",500,666,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/WhatsApp-Image-2021-02-20-at-14.28.51.jpeg",500,666,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/WhatsApp-Image-2021-02-20-at-14.28.51.jpeg",500,666,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/WhatsApp-Image-2021-02-20-at-14.28.51.jpeg",500,666,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/WhatsApp-Image-2021-02-20-at-14.28.51.jpeg",500,666,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/WhatsApp-Image-2021-02-20-at-14.28.51-420x307.jpeg",420,307,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/WhatsApp-Image-2021-02-20-at-14.28.51-300x443.jpeg",300,443,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/WhatsApp-Image-2021-02-20-at-14.28.51-464x290.jpeg",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/WhatsApp-Image-2021-02-20-at-14.28.51-500x500.jpeg",500,500,true],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/WhatsApp-Image-2021-02-20-at-14.28.51-322x230.jpeg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/WhatsApp-Image-2021-02-20-at-14.28.51-500x642.jpeg",500,642,true]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"Mais um crime cometido por disparos de arma de fogo aconteceu na cidade de Petrolina na manh\u00e3 deste s\u00e1bado (20). De acordo com informa\u00e7\u00f5es preliminares o crime ocorreu no bairro Henrique Leite. De acordo com testemunhas a v\u00edtima estava sob a companhia de algumas pessoas nas quais n\u00e3o tiveram suas identidades reveladas dentro de um&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/19919","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=19919"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/19919\/revisions"}],"predecessor-version":[{"id":19921,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/19919\/revisions\/19921"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/19920"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=19919"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=19919"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=19919"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}