{"id":19946,"date":"2021-02-22T07:48:52","date_gmt":"2021-02-22T10:48:52","guid":{"rendered":"http:\/\/blogopara.com.br\/?p=19946"},"modified":"2021-02-22T08:06:14","modified_gmt":"2021-02-22T11:06:14","slug":"idosa-e-cuidadora-sao-encontradas-mortas-por-golpes-de-facao-na-zona-rural-de-juazeiro","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2021\/02\/22\/idosa-e-cuidadora-sao-encontradas-mortas-por-golpes-de-facao-na-zona-rural-de-juazeiro","title":{"rendered":"Idosa e cuidadora s\u00e3o encontradas mortas por golpes de fac\u00e3o na zona rural de Juazeiro"},"content":{"rendered":"<p style=\"text-align: justify;\">Duas mulheres foram assassinadas nesse domingo (21), na zona rural de Juazeiro e de acordo com as informa\u00e7\u00f5es uma seria a idosa identificada apenas por Ivonizia, 80 anos, e a sua cuidadora. O objeto utilizado para praticar o crime teria sido um fac\u00e3o encontrado na cena do crime.<\/p>\n<p style=\"text-align: justify;\">T\u00e9cnicos do IML se deslocaram at\u00e9 o local conhecido por Bananeira, pr\u00f3ximo a Campo dos Cavalos e removeram os corpos para o setor de necropsia da unidade.<\/p>\n<p style=\"text-align: justify;\">Da Reda\u00e7\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Duas mulheres foram assassinadas nesse domingo (21), na zona rural de Juazeiro e de acordo com as informa\u00e7\u00f5es uma seria a idosa identificada apenas por Ivonizia, 80 anos, e a sua cuidadora. O objeto utilizado para praticar o crime teria sido um fac\u00e3o encontrado na cena do crime. T\u00e9cnicos do IML se deslocaram at\u00e9 o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":19950,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[203,202],"tags":[1778,1840,1934],"class_list":["post-19946","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-juazeiro","category-policia","tag-idosa","tag-violencia-2","tag-zona-rural"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/Facao22.02.png","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/Facao22.02.png",500,333,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/Facao22.02-150x150.png",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/Facao22.02-300x200.png",300,200,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/Facao22.02.png",500,333,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/Facao22.02.png",500,333,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/Facao22.02.png",500,333,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/Facao22.02.png",500,333,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/Facao22.02.png",500,333,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/Facao22.02-420x307.png",420,307,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/Facao22.02-300x333.png",300,333,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/Facao22.02-464x290.png",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/Facao22.02.png",500,333,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/Facao22.02-322x230.png",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/Facao22.02.png",500,333,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"Duas mulheres foram assassinadas nesse domingo (21), na zona rural de Juazeiro e de acordo com as informa\u00e7\u00f5es uma seria a idosa identificada apenas por Ivonizia, 80 anos, e a sua cuidadora. O objeto utilizado para praticar o crime teria sido um fac\u00e3o encontrado na cena do crime. T\u00e9cnicos do IML se deslocaram at\u00e9 o&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/19946","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=19946"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/19946\/revisions"}],"predecessor-version":[{"id":19947,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/19946\/revisions\/19947"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/19950"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=19946"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=19946"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=19946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}