{"id":20245,"date":"2021-03-01T12:40:00","date_gmt":"2021-03-01T15:40:00","guid":{"rendered":"http:\/\/blogopara.com.br\/?p=20245"},"modified":"2021-02-28T22:22:28","modified_gmt":"2021-03-01T01:22:28","slug":"salvador-arvore-cai-em-veiculo-e-deixa-tres-pessoas-presas-nas-ferragens-em-agua-de-meninos","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2021\/03\/01\/salvador-arvore-cai-em-veiculo-e-deixa-tres-pessoas-presas-nas-ferragens-em-agua-de-meninos","title":{"rendered":"Salvador: \u00c1rvore cai em ve\u00edculo e deixa tr\u00eas pessoas presas nas ferragens em \u00c1gua de Meninos"},"content":{"rendered":"<p style=\"text-align: justify;\">Uma palmeira imperial caiu em cima de um ve\u00edculo, neste s\u00e1bado (27), na cidade baixa, na regi\u00e3o de \u00c1gua de Meninos. O acidente deixou tr\u00eas pessoas presas nas ferragens. Tr\u00eas equipes de resgate do Corpo de Bombeiros conseguiram fazer o resgate de uma das v\u00edtimas e tentam retirar as outras duas.<\/p>\n<p style=\"text-align: justify;\">De acordo com os bombeiros, a aeronave do grupamento a\u00e9reo da Bahia foi mobilizada para apoiar a ocorr\u00eancia. A primeira v\u00edtima resgatada foi encaminhada para o Hospital Geral do Estado pela Unidade de Resgate do CBMBA.<\/p>\n<div style=\"text-align: justify;\"><\/div>\n<div id=\"div-gpt-ad-bn_principal_conteudo\" style=\"text-align: justify;\" data-google-query-id=\"CM_hoILQjO8CFfU3uQYdcjQAuA\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Uma palmeira imperial caiu em cima de um ve\u00edculo, neste s\u00e1bado (27), na cidade baixa, na regi\u00e3o de \u00c1gua de Meninos. O acidente deixou tr\u00eas pessoas presas nas ferragens. Tr\u00eas equipes de resgate do Corpo de Bombeiros conseguiram fazer o resgate de uma das v\u00edtimas e tentam retirar as outras duas. De acordo com os [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":20246,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[199,201],"tags":[1819,1059,1253],"class_list":["post-20245","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bahia","category-bombeiro","tag-blog","tag-resgate","tag-salvador"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/IMAGEM_NOTICIA_5-2.jpg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/IMAGEM_NOTICIA_5-2.jpg",450,331,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/IMAGEM_NOTICIA_5-2-150x150.jpg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/IMAGEM_NOTICIA_5-2-300x221.jpg",300,221,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/IMAGEM_NOTICIA_5-2.jpg",450,331,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/IMAGEM_NOTICIA_5-2.jpg",450,331,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/IMAGEM_NOTICIA_5-2.jpg",450,331,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/IMAGEM_NOTICIA_5-2.jpg",450,331,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/IMAGEM_NOTICIA_5-2.jpg",450,331,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/IMAGEM_NOTICIA_5-2-420x307.jpg",420,307,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/IMAGEM_NOTICIA_5-2-300x331.jpg",300,331,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/IMAGEM_NOTICIA_5-2-450x290.jpg",450,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/IMAGEM_NOTICIA_5-2.jpg",450,331,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/IMAGEM_NOTICIA_5-2-322x230.jpg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/IMAGEM_NOTICIA_5-2.jpg",450,331,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"Uma palmeira imperial caiu em cima de um ve\u00edculo, neste s\u00e1bado (27), na cidade baixa, na regi\u00e3o de \u00c1gua de Meninos. O acidente deixou tr\u00eas pessoas presas nas ferragens. Tr\u00eas equipes de resgate do Corpo de Bombeiros conseguiram fazer o resgate de uma das v\u00edtimas e tentam retirar as outras duas. De acordo com os&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/20245","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=20245"}],"version-history":[{"count":2,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/20245\/revisions"}],"predecessor-version":[{"id":20248,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/20245\/revisions\/20248"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/20246"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=20245"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=20245"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=20245"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}