{"id":20628,"date":"2021-03-09T17:40:00","date_gmt":"2021-03-09T20:40:00","guid":{"rendered":"http:\/\/blogopara.com.br\/?p=20628"},"modified":"2021-03-09T16:54:53","modified_gmt":"2021-03-09T19:54:53","slug":"estudo-preliminar-indica-que-coronavac-e-eficaz-contra-cepa-originada-no-amazonas","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2021\/03\/09\/estudo-preliminar-indica-que-coronavac-e-eficaz-contra-cepa-originada-no-amazonas","title":{"rendered":"Estudo preliminar indica que Coronavac \u00e9 eficaz contra cepa originada no Amazonas"},"content":{"rendered":"<p style=\"text-align: justify;\">Resultados preliminares de um estudo feito no Brasil sugerem que a Coronavac, vacina desenvolvida pela farmac\u00eautica chinesa Sinovac e produzida no Brasil pelo Instituto Butantan, \u00e9 eficaz contra a variante P.1 do coronav\u00edrus, originada em Manaus no fim de 2020 e j\u00e1 presente em ao menos 17 Estados.<\/p>\n<p style=\"text-align: justify;\">O imunizante teria se mostrado efetivo contra a nova cepa em estudos feitos com o soro de pessoas vacinadas, segundo afirmou \u00e0 ag\u00eancia Reuters uma fonte envolvida nas pesquisas que n\u00e3o quis se identificar. Os estudos com soro geralmente avaliam se os anticorpos presentes no sangue do imunizante s\u00e3o capazes de neutralizar o v\u00edrus.<\/p>\n<p style=\"text-align: justify;\">Conforme a Reuters, a fonte n\u00e3o divulgou mais dados, nem informou quando os resultados ser\u00e3o divulgados publicamente ou em um artigo cient\u00edfico. A informa\u00e7\u00e3o sobre esses achados preliminares foi confirmada pelo Estad\u00e3o com pessoas envolvidas nas pesquisas. De acordo com essas fontes, al\u00e9m dos dados das pesquisas em laborat\u00f3rio, com o soro dos vacinados, resultados preliminares de estudos de efetividade tamb\u00e9m demonstraram redu\u00e7\u00e3o de casos graves entre idosos, o que indicaria que a vacina est\u00e1 tendo efic\u00e1cia no Pa\u00eds mesmo em meio \u00e0 dissemina\u00e7\u00e3o da nova cepa do coronav\u00edrus.<\/p>\n<p style=\"text-align: justify;\">Os estudos de efetividade s\u00e3o os chamados testes \u201cde vida real\u201d, em que a efic\u00e1cia da vacina \u00e9 avaliada ao ser aplicada em massa na popula\u00e7\u00e3o. De acordo com as fontes, bons resultados j\u00e1 est\u00e3o sendo observados em locais como os Estados de S\u00e3o Paulo e Pernambuco.<\/p>\n<p style=\"text-align: justify;\"><strong>Cepa perigosa<\/strong><\/p>\n<p style=\"text-align: justify;\">Pesquisas recentes mostram que a variante P.1 \u00e9 duas vezes mais transmiss\u00edvel do que as cepas predominantes no Brasil durante a primeira onda. Segundo os estudos, ela teria ainda probabilidade de 25% a 61% maior de escapar da imunidade desenvolvida, com base em uma contamina\u00e7\u00e3o pr\u00e9via e aumentaria em dez vezes a carga viral nas c\u00e9lulas do doente. Na semana passada, fontes tamb\u00e9m informaram \u00e0 imprensa que o imunizante Covishield, desenvolvido pela Universidade de Oxford e pela farmac\u00eautica brit\u00e2nica AstraZeneca, se mostrou eficaz contra a cepa P.1. Os dados dos testes, por\u00e9m, n\u00e3o foram apresentados. Os resultados s\u00e3o prometidos para esta semana. Em ambos os casos, a comunidade cient\u00edfica cobra que os resultados detalhados sejam divulgados para que a efic\u00e1cia da vacina contra a P.1 seja conhecida. Os dois imunizantes j\u00e1 t\u00eam sido utilizados, desde janeiro, na campanha nacional de vacina\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\">Fonte: Correio Brasiliense.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Resultados preliminares de um estudo feito no Brasil sugerem que a Coronavac, vacina desenvolvida pela farmac\u00eautica chinesa Sinovac e produzida no Brasil pelo Instituto Butantan, \u00e9 eficaz contra a variante P.1 do coronav\u00edrus, originada em Manaus no fim de 2020 e j\u00e1 presente em ao menos 17 Estados. O imunizante teria se mostrado efetivo contra [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":20629,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1624],"tags":[2122,2121,2120,1099],"class_list":["post-20628","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-covid-19","tag-amazonas","tag-cepa","tag-coronavac","tag-estudo"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/03\/CoronaVac09.03.jpg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/03\/CoronaVac09.03.jpg",500,332,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/03\/CoronaVac09.03-150x150.jpg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/03\/CoronaVac09.03-300x199.jpg",300,199,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/03\/CoronaVac09.03.jpg",500,332,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/03\/CoronaVac09.03.jpg",500,332,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/03\/CoronaVac09.03.jpg",500,332,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/03\/CoronaVac09.03.jpg",500,332,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/03\/CoronaVac09.03.jpg",500,332,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/03\/CoronaVac09.03-420x307.jpg",420,307,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/03\/CoronaVac09.03-300x332.jpg",300,332,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/03\/CoronaVac09.03-464x290.jpg",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/03\/CoronaVac09.03.jpg",500,332,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/03\/CoronaVac09.03-322x230.jpg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/03\/CoronaVac09.03.jpg",500,332,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"Resultados preliminares de um estudo feito no Brasil sugerem que a Coronavac, vacina desenvolvida pela farmac\u00eautica chinesa Sinovac e produzida no Brasil pelo Instituto Butantan, \u00e9 eficaz contra a variante P.1 do coronav\u00edrus, originada em Manaus no fim de 2020 e j\u00e1 presente em ao menos 17 Estados. O imunizante teria se mostrado efetivo contra&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/20628","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=20628"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/20628\/revisions"}],"predecessor-version":[{"id":20630,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/20628\/revisions\/20630"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/20629"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=20628"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=20628"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=20628"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}