{"id":23679,"date":"2021-05-23T09:20:00","date_gmt":"2021-05-23T12:20:00","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=23679"},"modified":"2021-05-23T13:27:12","modified_gmt":"2021-05-23T16:27:12","slug":"poliamor-relacoes-nao-convencionais-se-multiplicam-e-lutam-pelo-reconhecimento-da-justica","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2021\/05\/23\/poliamor-relacoes-nao-convencionais-se-multiplicam-e-lutam-pelo-reconhecimento-da-justica","title":{"rendered":"Poliamor: rela\u00e7\u00f5es n\u00e3o convencionais se multiplicam e lutam pelo reconhecimento da Justi\u00e7a"},"content":{"rendered":"<div class=\"bbc-19j92fr e57qer20\" dir=\"ltr\">\n<p dir=\"ltr\" style=\"text-align: justify;\">\n<p dir=\"ltr\" style=\"text-align: justify;\"><img decoding=\"async\" src=\"https:\/\/ichef.bbci.co.uk\/news\/640\/cpsprodpb\/5AAC\/production\/_118121232_foto_01.jpg\" alt=\"Ian Jenkins, Alan e Jeremy com beb\u00ea no colo e cachorros em volta\"><\/p>\n<pre dir=\"ltr\">Ian Jenkins (\u00e0 esquerda), Alan (ao centro) e Jeremy (\u00e0 direita) decidiram formar uma fam\u00edlia<\/pre>\n<p class=\"bbc-bm53ic e1cc2ql70\" dir=\"ltr\" style=\"text-align: justify;\"><b>Ian Jenkins, de 45 anos, enfrentou amea\u00e7as de morte depois de se declarar homossexual quando estava na universidade no Estado da Virg\u00ednia, nos Estados Unidos.<\/b><\/p>\n<\/div>\n<div class=\"bbc-19j92fr e57qer20\" dir=\"ltr\" style=\"text-align: justify;\">\n<p class=\"bbc-bm53ic e1cc2ql70\" dir=\"ltr\">Na \u00e9poca, ele mal conseguia imaginar que um dia poderia viver com um parceiro sendo assumidamente gay \u2014 que dir\u00e1 com dois.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr e57qer20\" dir=\"ltr\" style=\"text-align: justify;\">\n<p class=\"bbc-bm53ic e1cc2ql70\" dir=\"ltr\">Mas hoje ele divide a casa em San Diego com seus dois companheiros, Alan, de 43 anos, e Jeremy, de 37 (que preferem usar apenas seus primeiros nomes por quest\u00e3o de privacidade) e seus dois filhos, que est\u00e3o com 3 e 1 ano.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr e57qer20\" dir=\"ltr\" style=\"text-align: justify;\">\n<p class=\"bbc-bm53ic e1cc2ql70\" dir=\"ltr\">Todos os tr\u00eas s\u00e3o legalmente pais das crian\u00e7as, seus nomes constam nas duas certid\u00f5es de nascimento.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr e57qer20\" dir=\"ltr\" style=\"text-align: justify;\">\n<p class=\"bbc-bm53ic e1cc2ql70\" dir=\"ltr\">Jenkins e seu primeiro parceiro, Alan, ambos m\u00e9dicos, haviam discutido a possibilidade de um relacionamento mais aberto durante anos, antes de conhecer Jeremy em 2012.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr e57qer20\" dir=\"ltr\" style=\"text-align: justify;\">\n<p class=\"bbc-bm53ic e1cc2ql70\" dir=\"ltr\">Embora Jeremy, um tratador de zool\u00f3gico que trabalha para salvar esp\u00e9cies amea\u00e7adas de extin\u00e7\u00e3o, n\u00e3o se interessasse inicialmente por poliamor, ele conheceu o casal como amigo e &#8220;todos ficaram \u00e0 vontade com a ideia \u2014 simplesmente rolou uma qu\u00edmica boa&#8221;, diz Jenkins.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr e57qer20\" dir=\"ltr\" style=\"text-align: justify;\">\n<p class=\"bbc-bm53ic e1cc2ql70\" dir=\"ltr\">Eles formaram uma fam\u00edlia, mas quando tomaram a decis\u00e3o de ter filhos, apareceram os obst\u00e1culos.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr e57qer20\" dir=\"ltr\" style=\"text-align: justify;\">\n<p class=\"bbc-bm53ic e1cc2ql70\" dir=\"ltr\">Al\u00e9m do fato de que cada um tinha que ter seu pr\u00f3prio advogado envolvido nos contratos de barriga de aluguel e de doa\u00e7\u00e3o de \u00f3vulos para gerar o primeiro filho (uma mulher serviu de barriga de aluguel, e outra doou os \u00f3vulos), eles ainda tinham que convencer o juiz de que todos os tr\u00eas deveriam ser legalmente reconhecidos como pais da crian\u00e7a.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr e57qer20\" dir=\"ltr\" style=\"text-align: justify;\">\n<p class=\"bbc-bm53ic e1cc2ql70\" dir=\"ltr\">Jenkins conta que a ju\u00edza que recebeu o caso &#8220;entendeu a situa\u00e7\u00e3o e queria nos ajudar&#8221;, mas como era de primeira inst\u00e2ncia &#8221; n\u00e3o tinha permiss\u00e3o para abrir precedentes&#8221;.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr e57qer20\" dir=\"ltr\" style=\"text-align: justify;\">\n<p class=\"bbc-bm53ic e1cc2ql70\" dir=\"ltr\">At\u00e9 ent\u00e3o, homens em relacionamentos a tr\u00eas jamais haviam obtido direitos conjuntos de paternidade de uma crian\u00e7a na Calif\u00f3rnia, ou possivelmente em qualquer lugar dos Estados Unidos.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr e57qer20\" dir=\"ltr\" style=\"text-align: justify;\">\n<p class=\"bbc-bm53ic e1cc2ql70\" dir=\"ltr\">Mas os tr\u00eas defenderam sua posi\u00e7\u00e3o, cada um explicando &#8220;por que era t\u00e3o importante e necess\u00e1rio que tiv\u00e9ssemos [nossos nomes] na certid\u00e3o de nascimento&#8221;, relembra Jenkins.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr e57qer20\" dir=\"ltr\" style=\"text-align: justify;\">\n<p class=\"bbc-bm53ic e1cc2ql70\" dir=\"ltr\">A justi\u00e7a acabou concedendo aos tr\u00eas os direitos parentais em rela\u00e7\u00e3o ao primeiro filho, nascido em 2017, e Jenkins acabou escrevendo um livro sobre a jornada deles chamado&nbsp;<i class=\"bbc-h1y5j7 ewc4zcb0\">Three Dads and a Baby: Adventures in Modern Parenting<\/i>, publicado em 9 de mar\u00e7o nos Estados Unidos.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr e57qer20\" dir=\"ltr\" style=\"text-align: justify;\">\n<p class=\"bbc-bm53ic e1cc2ql70\" dir=\"ltr\">Embora ainda seja raro para pessoas em relacionamentos poliamorosos compartilharem legalmente a paternidade dos filhos, v\u00e1rias formas de &#8216;rela\u00e7\u00f5es \u00e9ticas n\u00e3o-monog\u00e2micas&#8217; \u2014 que envolvem mais de dois adultos de forma consensual \u2014 t\u00eam se tornado cada vez mais comuns na \u00faltima d\u00e9cada.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr e57qer20\" dir=\"ltr\" style=\"text-align: justify;\">\n<p class=\"bbc-bm53ic e1cc2ql70\" dir=\"ltr\">Diversos fatores contribuem para isso, desde o surgimento de aplicativos de relacionamento para m\u00faltiplos parceiros at\u00e9 a maior representatividade na m\u00eddia e nas redes sociais, al\u00e9m do acesso mais f\u00e1cil para os interessados \u200b\u200bnesse estilo de vida.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr e57qer20\" dir=\"ltr\" style=\"text-align: justify;\">\n<p class=\"bbc-bm53ic e1cc2ql70\" dir=\"ltr\">&#8220;Acho que um fator importante \u00e9 a vontade das pessoas de serem abertas (a essa possibilidade)&#8221;, diz Jenkins. &#8220;Precisa haver visibilidade.&#8221;<\/p>\n<\/div>\n<div class=\"bbc-19j92fr e57qer20\" dir=\"ltr\" style=\"text-align: justify;\">\n<p class=\"bbc-bm53ic e1cc2ql70\" dir=\"ltr\">Essas mudan\u00e7as culturais, no entanto, remetem aos defensores do amor livre na d\u00e9cada de 1960, que trabalharam duro para ampliar nossas fronteiras sexuais ao redor do mundo.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr e57qer20\" dir=\"ltr\" style=\"text-align: justify;\">\n<p class=\"bbc-bm53ic e1cc2ql70\" dir=\"ltr\">E as mudan\u00e7as continuam a acontecer por causa de pessoas como Jenkins e seus companheiros, cujas hist\u00f3rias ajudam a quebrar tabus de longa data sobre ter m\u00faltiplos parceiros.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr e57qer20\" dir=\"ltr\" style=\"text-align: justify;\">\n<h2 id=\"N\u00e3o-\u00e9-algo-novo-a-hist\u00f3ria-da-n\u00e3omonogamia\" class=\"bbc-l3e97o e14hemmw0\" tabindex=\"-1\">&#8216;N\u00e3o \u00e9 algo novo&#8217;: a hist\u00f3ria da n\u00e3o-monogamia<\/h2>\n<\/div>\n<div class=\"bbc-19j92fr e57qer20\" dir=\"ltr\" style=\"text-align: justify;\">\n<p class=\"bbc-bm53ic e1cc2ql70\" dir=\"ltr\">Em 2016, uma pesquisa feita com quase 9 mil adultos solteiros nos Estados Unidos mostrou que um em cada cinco j\u00e1 havia tido um relacionamento consensualmente n\u00e3o-monog\u00e2mico.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr e57qer20\" dir=\"ltr\" style=\"text-align: justify;\">\n<p class=\"bbc-bm53ic e1cc2ql70\" dir=\"ltr\">Um estudo canadense apresentou basicamente os mesmos n\u00fameros um ano depois.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr e57qer20\" dir=\"ltr\" style=\"text-align: justify;\">\n<p class=\"bbc-bm53ic e1cc2ql70\" dir=\"ltr\">&#8220;Outra coisa que vimos na \u00faltima d\u00e9cada \u00e9 que as buscas no Google pelos termos &#8216;poliamor&#8217; e &#8216;rela\u00e7\u00f5es abertas&#8217; aumentaram, o que demonstra que h\u00e1 mais interesse neste t\u00f3pico&#8221;, diz Justin Lehmiller, psic\u00f3logo social e pesquisador do Instituto Kinsey para Pesquisa em Sexo, G\u00eanero e Reprodu\u00e7\u00e3o da Universidade de Indiana, nos Estados Unidos.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr e57qer20\" dir=\"ltr\" style=\"text-align: justify;\">\n<p class=\"bbc-bm53ic e1cc2ql70\" dir=\"ltr\">Mas as pessoas t\u00eam se envolvido nesse tipo de relacionamento &#8220;h\u00e1 muito tempo&#8221;, ele acrescenta. &#8220;N\u00e3o \u00e9 algo novo.&#8221;<\/p>\n<\/div>\n<div class=\"bbc-19j92fr e57qer20\" dir=\"ltr\" style=\"text-align: justify;\">\n<p class=\"bbc-bm53ic e1cc2ql70\" dir=\"ltr\">Era uma novidade em 1969, no entanto, quando Dossie Easton, coautora do livro&nbsp;<i class=\"bbc-h1y5j7 ewc4zcb0\">The Ethical Slut<\/i>&nbsp;(1977) em parceria com Janet Hardy, tomou a decis\u00e3o ent\u00e3o &#8220;bastante incomum&#8221; de que &#8220;nunca seria monog\u00e2mica novamente&#8221; depois de ter sa\u00eddo de um relacionamento ruim.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr e57qer20\" dir=\"ltr\" style=\"text-align: justify;\">\n<p class=\"bbc-bm53ic e1cc2ql70\" dir=\"ltr\">Em 1973, ela se juntou a um grupo chamado San Francisco Sex Information (que ainda existe) e se viu em meio a uma comunidade de pessoas que exploravam estilos de vida sexuais abertos. &#8220;Eu precisava fazer parte do avan\u00e7o desse mundo&#8221;, diz ela.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr e57qer20\" dir=\"ltr\" style=\"text-align: justify;\">\n<p class=\"bbc-bm53ic e1cc2ql70\" dir=\"ltr\">Easton, agora com 77 anos, vinha falando sobre a n\u00e3o-monogamia \u00e9tica h\u00e1 anos, at\u00e9 que ela e Hardy ministraram uma oficina de BDSM (sigla em ingl\u00eas para submiss\u00e3o, domina\u00e7\u00e3o, sadismo e masoquismo) durante uma confer\u00eancia em 1994 nos arredores de San Francisco.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr e57qer20\" dir=\"ltr\" style=\"text-align: justify;\">\n<p class=\"bbc-bm53ic e1cc2ql70\" dir=\"ltr\">Embora o p\u00fablico n\u00e3o tenha ficado escandalizado com o BDSM, ficou chocado que Easton e Hardy, que namoravam na \u00e9poca, tivessem apresentado a oficina bem na frente do parceiro masculino de Easton.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr e57qer20\" dir=\"ltr\" style=\"text-align: justify;\">\n<p class=\"bbc-bm53ic e1cc2ql70\" dir=\"ltr\">Isso levou a dupla a escrever o livro, que aborda como manter relacionamentos saud\u00e1veis \u200b\u200bn\u00e3o-monog\u00e2micos. Ainda \u00e9 uma leitura um tanto obrigat\u00f3ria para pessoas interessadas nesse estilo de vida. &#8220;A cada ano, vende mais&#8221;, diz Easton.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr e57qer20\" dir=\"ltr\" style=\"text-align: justify;\">\n<p class=\"bbc-bm53ic e1cc2ql70\" dir=\"ltr\">Nas \u00faltimas d\u00e9cadas, ela viajou para &#8220;encontros de poliamor&#8221; no Reino Unido, Alemanha, Holanda e Austr\u00e1lia. Em Berlim, conheceu Claudia Zinser, de 57 anos, que come\u00e7ou a &#8220;viver o poliamor abertamente h\u00e1 cerca de 25 anos&#8221;, revela a pr\u00f3pria.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr e57qer20\" dir=\"ltr\" style=\"text-align: justify;\">\n<p class=\"bbc-bm53ic e1cc2ql70\" dir=\"ltr\">Zinser aconselha pessoas em relacionamentos poliamorosos h\u00e1 uma d\u00e9cada \u2014 e testemunhou a abertura em rela\u00e7\u00e3o a esse estilo de vida crescer, sobretudo entre jovens urbanos.<\/p>\n<\/div>\n<div class=\"ek1plzs1 bbc-9m7iam e57qer20\" dir=\"ltr\" style=\"text-align: justify;\">\n<figure class=\"bbc-1qdcvv9 e6bmn90\">\n<div class=\"bbc-vx18wi e57qer20\" dir=\"ltr\">\n<div class=\"bbc-vx18wi e57qer20\" dir=\"ltr\">\n<div class=\"bbc-rprdln e57qer20\" dir=\"ltr\">\n<div class=\"bbc-1ve91qc e1whu0\" data-e2e=\"image-placeholder\">\n<div class=\"lazyload-wrapper \"><img decoding=\"async\" class=\"css-fat2bc e1enwo3v0\" src=\"https:\/\/ichef.bbci.co.uk\/news\/640\/cpsprodpb\/CFDC\/production\/_118121235_foto_03.jpg\" srcset=\"https:\/\/ichef.bbci.co.uk\/news\/240\/cpsprodpb\/CFDC\/production\/_118121235_foto_03.jpg 240w, https:\/\/ichef.bbci.co.uk\/news\/320\/cpsprodpb\/CFDC\/production\/_118121235_foto_03.jpg 320w, https:\/\/ichef.bbci.co.uk\/news\/412\/cpsprodpb\/CFDC\/production\/_118121235_foto_03.jpg 412w\" alt=\"Janie Frank, Cody Coppola e Maggie Odell\" width=\"412\"><\/div>\n<div class=\"lazyload-wrapper \"><span style=\"font-size: inherit;\">Janie Frank (\u00e0 esquerda), Cody Coppola (ao centro) e Maggie Odell (\u00e0 direita) se conheceram no aplicativo de relacionamento Feeld<\/span><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"bbc-vx18wi e57qer20\" dir=\"ltr\">\n<div class=\"bbc-3edg7g e57qer20\" dir=\"ltr\"><\/div>\n<\/div>\n<\/figure>\n<\/div>\n<div class=\"bbc-19j92fr e57qer20\" dir=\"ltr\" style=\"text-align: justify;\">\n<p class=\"bbc-bm53ic e1cc2ql70\" dir=\"ltr\">&#8220;A m\u00eddia, incluindo as redes sociais, promoveu o assunto&#8230; ent\u00e3o n\u00e3o \u00e9 mais algo desconhecido ou tabu&#8221;, diz ela. &#8220;Talvez at\u00e9 esteja na moda.&#8221;<\/p>\n<\/div>\n<div class=\"bbc-19j92fr e57qer20\" dir=\"ltr\" style=\"text-align: justify;\">\n<h2 id=\"O-empurr\u00e3o-dos-aplicativos\" class=\"bbc-l3e97o e14hemmw0\" tabindex=\"-1\">O &#8216;empurr\u00e3o&#8217; dos aplicativos<\/h2>\n<\/div>\n<div class=\"bbc-19j92fr e57qer20\" dir=\"ltr\" style=\"text-align: justify;\">\n<p class=\"bbc-bm53ic e1cc2ql70\" dir=\"ltr\">Os relacionamentos \u00e9ticos n\u00e3o-monog\u00e2micos n\u00e3o tiveram uma trajet\u00f3ria puramente ascendente.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr e57qer20\" dir=\"ltr\" style=\"text-align: justify;\">\n<p class=\"bbc-bm53ic e1cc2ql70\" dir=\"ltr\">Lehmiller lembra que a epidemia de HIV, v\u00edrus causador da Aids, das d\u00e9cadas de 1980 e 1990 fez com que as pesquisas sobre n\u00e3o-monogamia consensual diminu\u00edssem, uma vez que fazer sexo com v\u00e1rios parceiros passou a ser visto como menos seguro.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr e57qer20\" dir=\"ltr\" style=\"text-align: justify;\">\n<p class=\"bbc-bm53ic e1cc2ql70\" dir=\"ltr\">&#8220;O renascimento da pesquisa nessa \u00e1rea come\u00e7ou por volta de 2010&#8221;, explica Lehmiller. &#8220;Na \u00faltima d\u00e9cada, realmente vimos uma explos\u00e3o.&#8221;<\/p>\n<\/div>\n<div class=\"bbc-19j92fr e57qer20\" dir=\"ltr\" style=\"text-align: justify;\">\n<p class=\"bbc-bm53ic e1cc2ql70\" dir=\"ltr\">A atual quase inclus\u00e3o da n\u00e3o-monogamia \u00e9tica, diz ele, aconteceu tanto por causa da pesquisa acad\u00eamica que chegou at\u00e9 o p\u00fablico, por meio de centros de educa\u00e7\u00e3o e m\u00eddia, quanto pela representa\u00e7\u00e3o dessas rela\u00e7\u00f5es na TV.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr e57qer20\" dir=\"ltr\" style=\"text-align: justify;\">\n<p class=\"bbc-bm53ic e1cc2ql70\" dir=\"ltr\">As representa\u00e7\u00f5es mais recentes v\u00e3o al\u00e9m da s\u00e9rie&nbsp;<i class=\"bbc-h1y5j7 ewc4zcb0\">Amor Imenso,<\/i>&nbsp;da HBO, ou&nbsp;<i class=\"bbc-h1y5j7 ewc4zcb0\">Sister Wives<\/i>, do TLC, que mostram fam\u00edlias m\u00f3rmons com um marido e v\u00e1rias esposas, para retratar a diversidade de rela\u00e7\u00f5es m\u00faltiplas existentes.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr e57qer20\" dir=\"ltr\" style=\"text-align: justify;\">\n<p class=\"bbc-bm53ic e1cc2ql70\" dir=\"ltr\"><i class=\"bbc-h1y5j7 ewc4zcb0\">Unicornland<\/i>, de Lucy Gillespie, em que uma mulher que acaba de ficar solteira sai com v\u00e1rios casais diferentes; e&nbsp;<i class=\"bbc-h1y5j7 ewc4zcb0\">You Me Her<\/i>, em que um casal se apaixona junto por outra mulher, s\u00e3o exemplos fortes.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr e57qer20\" dir=\"ltr\" style=\"text-align: justify;\">\n<p class=\"bbc-bm53ic e1cc2ql70\" dir=\"ltr\">&#8220;A internet e os aplicativos de relacionamento mais inclusivos tamb\u00e9m desempenharam um papel nessa mudan\u00e7a de atitude&#8221;, afirma Lehmiller.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr e57qer20\" dir=\"ltr\" style=\"text-align: justify;\">\n<p class=\"bbc-bm53ic e1cc2ql70\" dir=\"ltr\">V\u00e1rios aplicativos voltados para a n\u00e3o-monogamia tornam mais f\u00e1cil encontrar outras pessoas que buscam relacionamentos com v\u00e1rios parceiros ou experi\u00eancias sexuais.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr e57qer20\" dir=\"ltr\" style=\"text-align: justify;\">\n<p class=\"bbc-bm53ic e1cc2ql70\" dir=\"ltr\">No Feeld, um aplicativo voltado para relacionamentos m\u00faltiplos, 60% dos casais est\u00e3o \u00e0 procura de uma terceira pessoa, diz um porta-voz da empresa.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr e57qer20\" dir=\"ltr\" style=\"text-align: justify;\">\n<p class=\"bbc-bm53ic e1cc2ql70\" dir=\"ltr\">E n\u00e3o \u00e9 apenas sexo que eles buscam. Uma pesquisa que ouviu 640 usu\u00e1rios dos EUA e do Reino Unido do aplicativo 3Fun, voltado para aventuras a tr\u00eas, mostrou que cerca de 43% das pessoas que procuram sexo a tr\u00eas tamb\u00e9m buscam relacionamentos a tr\u00eas.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr e57qer20\" dir=\"ltr\" style=\"text-align: justify;\">\n<p class=\"bbc-bm53ic e1cc2ql70\" dir=\"ltr\">Com esses aplicativos, &#8220;h\u00e1 mais op\u00e7\u00f5es para se conhecer e se conectar&#8221;, afirma Lehmiller, &#8220;n\u00e3o \u00e9 mais tanto uma cena underground como era no passado&#8221;.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr e57qer20\" dir=\"ltr\" style=\"text-align: justify;\">\n<p class=\"bbc-bm53ic e1cc2ql70\" dir=\"ltr\">Foi por meio do Feeld que Janie Frank, de 25 anos, conheceu seus dois parceiros, Maggie Odell, de 27, e Cody Coppola, de 31, em 2016.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr e57qer20\" dir=\"ltr\" style=\"text-align: justify;\">\n<p class=\"bbc-bm53ic e1cc2ql70\" dir=\"ltr\">Ela come\u00e7ou a usar o aplicativo no in\u00edcio daquele ano porque, embora s\u00f3 tivesse sa\u00eddo com homens anteriormente, tinha percebido que tamb\u00e9m gostava de mulheres.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr e57qer20\" dir=\"ltr\" style=\"text-align: justify;\">\n<p class=\"bbc-bm53ic e1cc2ql70\" dir=\"ltr\">&#8220;Eu estava muito nervosa em rela\u00e7\u00e3o a namorar uma mulher pela primeira vez&#8221;, conta Frank.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr e57qer20\" dir=\"ltr\" style=\"text-align: justify;\">\n<p class=\"bbc-bm53ic e1cc2ql70\" dir=\"ltr\">&#8220;Decidi que a maneira que eu iria contornar isso seria namorando casais, para ir me acostumando, ent\u00e3o eu sairia com um homem e uma mulher ao mesmo tempo.&#8221;<\/p>\n<\/div>\n<div class=\"bbc-19j92fr e57qer20\" dir=\"ltr\" style=\"text-align: justify;\">\n<p class=\"bbc-bm53ic e1cc2ql70\" dir=\"ltr\">Olhando para tr\u00e1s, Frank acha essa l\u00f3gica &#8220;estranha e engra\u00e7ada&#8221;, mas fez com que ela sa\u00edsse com v\u00e1rios casais antes de conhecer Odell e Coppola. &#8220;E (me apresentou a) todo esse estilo de vida que eu n\u00e3o sabia que existia&#8221;, diz ela<\/p>\n<\/div>\n<div class=\"bbc-19j92fr e57qer20\" dir=\"ltr\" style=\"text-align: justify;\">\n<p class=\"bbc-bm53ic e1cc2ql70\" dir=\"ltr\">&#8220;Conversando com as pessoas no aplicativo&#8230; comecei a perceber que existe toda uma comunidade de pessoas que s\u00e3o eticamente n\u00e3o-monog\u00e2micas.&#8221;<\/p>\n<\/div>\n<div class=\"bbc-19j92fr e57qer20\" dir=\"ltr\" style=\"text-align: justify;\">\n<p class=\"bbc-bm53ic e1cc2ql70\" dir=\"ltr\">Hoje, Frank e Odell t\u00eam perfis no TikTok com algumas centenas de milhares de seguidores. &#8220;N\u00f3s usamos para tentar falar sobre poliamor, conscientizar as pessoas sobre isso, para normalizar e educar as pessoas sobre&#8230; como pode ser&#8221;, explica Frank.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr e57qer20\" dir=\"ltr\" style=\"text-align: justify;\">\n<p class=\"bbc-bm53ic e1cc2ql70\" dir=\"ltr\">Algumas pessoas eticamente n\u00e3o-monog\u00e2micas entram em contato com elas para agradecer pela representatividade.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr e57qer20\" dir=\"ltr\" style=\"text-align: justify;\">\n<p class=\"bbc-bm53ic e1cc2ql70\" dir=\"ltr\">Outras, menos familiarizadas com o estilo de vida, comentam que est\u00e3o contentes por aprender sobre poliamor com os v\u00eddeos que elas postam.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr e57qer20\" dir=\"ltr\" style=\"text-align: justify;\">\n<p class=\"bbc-bm53ic e1cc2ql70\" dir=\"ltr\">&#8220;Nunca tinha ouvido falar disso antes&#8221;, escrevem algumas.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr e57qer20\" dir=\"ltr\" style=\"text-align: justify;\">\n<h2 id=\"A-lei-est\u00e1-sendo-atualizada\" class=\"bbc-l3e97o e14hemmw0\" tabindex=\"-1\">A lei est\u00e1 sendo atualizada?<\/h2>\n<\/div>\n<div class=\"bbc-19j92fr e57qer20\" dir=\"ltr\" style=\"text-align: justify;\">\n<p class=\"bbc-bm53ic e1cc2ql70\" dir=\"ltr\">O aumento de relacionamentos \u00e9ticos n\u00e3o-monog\u00e2micos est\u00e1 levando ao reconhecimento jur\u00eddico \u2014 al\u00e9m do reconhecimento \u00e0 paternidade obtido por Jenkins e seus companheiros.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr e57qer20\" dir=\"ltr\" style=\"text-align: justify;\">\n<p class=\"bbc-bm53ic e1cc2ql70\" dir=\"ltr\">Em julho de 2020, o conselho municipal de Somerville, no Estado americano de Massachusetts, votou unanimemente pelo reconhecimento de parcerias dom\u00e9sticas poliamorosas. A cidade de Cambridge, que faz fronteira com Somerville, fez o mesmo recentemente.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr e57qer20\" dir=\"ltr\" style=\"text-align: justify;\">\n<p class=\"bbc-bm53ic e1cc2ql70\" dir=\"ltr\">E isso n\u00e3o est\u00e1 acontecendo apenas nos Estados Unidos. Em 2018, dois homens e uma mulher em um relacionamento poliamoroso foram reconhecidos legalmente como pais do filho em Newfoundland, no Canad\u00e1.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr e57qer20\" dir=\"ltr\" style=\"text-align: justify;\">\n<p class=\"bbc-bm53ic e1cc2ql70\" dir=\"ltr\">No ano anterior, tr\u00eas homens em um relacionamento em Medell\u00edn, na Col\u00f4mbia, se casaram legalmente.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr e57qer20\" dir=\"ltr\" style=\"text-align: justify;\">\n<p class=\"bbc-bm53ic e1cc2ql70\" dir=\"ltr\">Esses movimentos geograficamente dispersos em dire\u00e7\u00e3o \u00e0 normaliza\u00e7\u00e3o da n\u00e3o-monogamia \u00e9tica podem ajudar a desencadear um movimento mais global.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr e57qer20\" dir=\"ltr\" style=\"text-align: justify;\">\n<p class=\"bbc-bm53ic e1cc2ql70\" dir=\"ltr\">Zinser, em Berlim, acredita que o est\u00edmulo a encontros e comunidades online, provocado pela pandemia de covid-19, vai refor\u00e7ar as &#8220;redes globais&#8221; para aqueles que praticam a n\u00e3o-monogamia \u00e9tica.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr e57qer20\" dir=\"ltr\" style=\"text-align: justify;\">\n<p class=\"bbc-bm53ic e1cc2ql70\" dir=\"ltr\">A dissemina\u00e7\u00e3o de informa\u00e7\u00f5es sobre a n\u00e3o-monogamia, por sua vez, &#8220;dar\u00e1 \u00e0s pessoas mais op\u00e7\u00f5es para criar o tipo de relacionamento certo para elas&#8221;, avalia Lehmiller.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr e57qer20\" dir=\"ltr\" style=\"text-align: justify;\">\n<p class=\"bbc-bm53ic e1cc2ql70\" dir=\"ltr\">Mas, apesar dessas mudan\u00e7as, as pessoas em relacionamentos n\u00e3o-monog\u00e2micos e&nbsp;<i class=\"bbc-h1y5j7 ewc4zcb0\">queer&nbsp;<\/i>ainda lutam contra o estigma.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr e57qer20\" dir=\"ltr\" style=\"text-align: justify;\">\n<p class=\"bbc-bm53ic e1cc2ql70\" dir=\"ltr\">Frank diz que ela e seus parceiros j\u00e1 receberam uma correspond\u00eancia an\u00f4nima de \u00f3dio. E, h\u00e1 um ano, Jenkins conta que os alunos da faculdade que frequentou ainda entoavam um canto homof\u00f3bico em partidas de futebol.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr e57qer20\" dir=\"ltr\" style=\"text-align: justify;\">\n<p class=\"bbc-bm53ic e1cc2ql70\" dir=\"ltr\">Em San Diego, no entanto, Jenkins afirma que ele e seus companheiros n\u00e3o enfrentam discrimina\u00e7\u00e3o \u2014 foi principalmente por isso que ele e Alan decidiram se mudar para l\u00e1.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr e57qer20\" dir=\"ltr\" style=\"text-align: justify;\">\n<p class=\"bbc-bm53ic e1cc2ql70\" dir=\"ltr\">Depois que o livro de Jenkins foi lan\u00e7ado, os colegas do hospital em que ele trabalha, incluindo todos os administradores mais velhos, escreveram para parabeniza-lo.<\/p>\n<\/div>\n<div class=\"bbc-19j92fr e57qer20\" dir=\"ltr\">\n<p class=\"bbc-bm53ic e1cc2ql70\" dir=\"ltr\" style=\"text-align: justify;\">&#8220;Eles at\u00e9 sugeriram que poder\u00edamos fazer uma sess\u00e3o de aut\u00f3grafos no futuro&#8221;, diz Jenkins. &#8220;Temos muita sorte de estar nesse ambiente.&#8221;<\/p>\n<p dir=\"ltr\">Fonte: BBC<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ian Jenkins (\u00e0 esquerda), Alan (ao centro) e Jeremy (\u00e0 direita) decidiram formar uma fam\u00edlia Ian Jenkins, de 45 anos, enfrentou amea\u00e7as de morte depois de se declarar homossexual quando estava na universidade no Estado da Virg\u00ednia, nos Estados Unidos. Na \u00e9poca, ele mal conseguia imaginar que um dia poderia viver com um parceiro sendo [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":23695,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[273],"tags":[295,3121,223,3120,3123],"class_list":["post-23679","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mundo","tag-aplicativo","tag-casamento","tag-eua","tag-monogamia","tag-relacionamentos"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/05\/118121236_foto_04.jpg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/05\/118121236_foto_04.jpg",500,500,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/05\/118121236_foto_04-150x150.jpg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/05\/118121236_foto_04-300x300.jpg",300,300,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/05\/118121236_foto_04.jpg",500,500,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/05\/118121236_foto_04.jpg",500,500,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/05\/118121236_foto_04.jpg",500,500,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/05\/118121236_foto_04.jpg",500,500,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/05\/118121236_foto_04.jpg",500,500,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/05\/118121236_foto_04-420x307.jpg",420,307,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/05\/118121236_foto_04-300x443.jpg",300,443,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/05\/118121236_foto_04-464x290.jpg",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/05\/118121236_foto_04.jpg",500,500,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/05\/118121236_foto_04-322x230.jpg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/05\/118121236_foto_04.jpg",500,500,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"Ian Jenkins (\u00e0 esquerda), Alan (ao centro) e Jeremy (\u00e0 direita) decidiram formar uma fam\u00edlia Ian Jenkins, de 45 anos, enfrentou amea\u00e7as de morte depois de se declarar homossexual quando estava na universidade no Estado da Virg\u00ednia, nos Estados Unidos. Na \u00e9poca, ele mal conseguia imaginar que um dia poderia viver com um parceiro sendo&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/23679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=23679"}],"version-history":[{"count":2,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/23679\/revisions"}],"predecessor-version":[{"id":23696,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/23679\/revisions\/23696"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/23695"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=23679"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=23679"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=23679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}