{"id":23922,"date":"2021-05-29T17:41:00","date_gmt":"2021-05-29T20:41:00","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=23922"},"modified":"2021-05-29T14:53:25","modified_gmt":"2021-05-29T17:53:25","slug":"protestos-contra-bolsonaro-reunem-manifestantes-nas-ruas-em-meio-a-pandemia","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2021\/05\/29\/protestos-contra-bolsonaro-reunem-manifestantes-nas-ruas-em-meio-a-pandemia","title":{"rendered":"Protestos contra Bolsonaro re\u00fanem manifestantes nas ruas em meio \u00e0 pandemia"},"content":{"rendered":"<p style=\"text-align: justify;\">Protestos contra o presidente Jair Bolsonaro liderados por centrais sindicais, movimentos sociais e partidos de esquerda re\u00fanem manifestantes em v\u00e1rias cidades do pa\u00eds. Na manh\u00e3 deste s\u00e1bado (29), h\u00e1 atos em capitais como Rio de Janeiro, Salvador, Belo Horizonte e Recife.<br \/>\u00a0<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: inherit;\">As manifesta\u00e7\u00f5es, que foram alvo de cr\u00edticas por acontecerem presencialmente em meio \u00e0 pandemia da Covid-19, s\u00e3o realizadas num momento em que o pa\u00eds chega a 459 mil mortes pela doen\u00e7a, sendo 2.418 registradas em 24 horas. Pelo menos nove capitais, al\u00e9m do Distrito Federal, t\u00eam ocupa\u00e7\u00e3o acima de 90% dos leitos de UTI.<\/span><\/p>\n<p style=\"text-align: justify;\">\u00a0A expectativa da organiza\u00e7\u00e3o \u00e9 que atos semelhantes aconte\u00e7am at\u00e9 o final do dia em cerca de 200 cidades, incluindo as 27 capitais. Em S\u00e3o Paulo, o protesto est\u00e1 marcado para as 16h com concentra\u00e7\u00e3o em frente ao Masp, na avenida Paulista.<br \/>\u00a0<\/p>\n<p style=\"text-align: justify;\">Como mostrou a Folha, a mobiliza\u00e7\u00e3o nacional deste s\u00e1bado foi feita pensando em desgastar Bolsonaro e incentivar a CPI da Covid, enquanto o impeachment \u00e9 visto como algo ainda distante. L\u00edderes ligados \u00e0 organiza\u00e7\u00e3o, por\u00e9m, enxergam os atos como um impulso.<br \/>\u00a0<\/p>\n<p style=\"text-align: justify;\">O dilema entre o discurso pr\u00f3-isolamento social e o incentivo a aglomera\u00e7\u00f5es resultou em diferentes n\u00edveis de participa\u00e7\u00e3o. A CUT (Central \u00danica dos Trabalhadores) e o MST (Movimento dos Trabalhadores Rurais Sem Terra) n\u00e3o convocaram seus integrantes institucionalmente, embora n\u00e3o impe\u00e7am a ida.<br \/>\u00a0<\/p>\n<p style=\"text-align: justify;\">PT, PSOL, PC do B, PCB, PCO e UP declararam apoio \u00e0 iniciativa e dispararam chamados para os militantes, mas ressaltaram que a organiza\u00e7\u00e3o \u00e9 de responsabilidade de frentes Povo sem Medo, Brasil Popular e Coaliz\u00e3o Negra por Direitos (que congregam dezenas de entidades).<br \/>\u00a0<\/p>\n<p style=\"text-align: justify;\">Mesmo entre os partidos que endossaram a iniciativa n\u00e3o houve unanimidade. Em estados como a Bahia, por exemplo, o PT do governador Rui Costa incentivou a realiza\u00e7\u00e3o de atos virtuais.<br \/>\u00a0<\/p>\n<p style=\"text-align: justify;\">Em Pernambuco, o Minist\u00e9rio P\u00fablico estadual emitiu uma recomenda\u00e7\u00e3o de suspens\u00e3o dos atos marcados para este s\u00e1bado, para evitar a dissemina\u00e7\u00e3o do v\u00edrus. Ele expediu recomenda\u00e7\u00f5es semelhantes contra aglomera\u00e7\u00f5es em manifesta\u00e7\u00f5es de apoio ao presidente Bolsonaro.<br \/>\u00a0<\/p>\n<p style=\"text-align: justify;\">Mesmo com a recomenda\u00e7\u00e3o, o protesto foi mantido pelos organizadores. Mas houve baixas: o PT de Pernambuco orientou aos seus militantes que n\u00e3o participassem do ato presencial.<br \/>\u00a0<\/p>\n<p style=\"text-align: justify;\">No Rio de Janeiro, manifestantes come\u00e7am a se reunir no centro na manh\u00e3 deste s\u00e1bado na avenida Presidente Vargas, na altura do Monumento Zumbi. O protesto tem as seguintes pautas: &#8220;Pela vida, por vacina, pelo aux\u00edlio digno e contra os cortes na educa\u00e7\u00e3o&#8221;. Os organizadores tamb\u00e9m pediram que os manifestantes levassem um quilo de alimento n\u00e3o perec\u00edvel.<br \/>\u00a0<\/p>\n<p style=\"text-align: justify;\">No \u00faltimo domingo (23), a capital fluminense foi palco de uma mobiliza\u00e7\u00e3o pr\u00f3-Bolsonaro. Tr\u00eas dias ap\u00f3s dizer em live que voltou a ter sintomas da Covid-19, o presidente fez um passeio de moto com p\u00fablico estimado em 10 mil a 15 mil pessoas pela prefeitura carioca.<br \/>\u00a0<\/p>\n<p style=\"text-align: justify;\">Ao final, ele fez um discurso criticando as medidas restritivas adotadas para conter a pandemia, causando aglomera\u00e7\u00e3o. Tamb\u00e9m sem m\u00e1scara, o ex-ministro da Sa\u00fade general Eduardo Pazuello esteve ao lado dele em cima de um carro de som.<br \/>\u00a0<\/p>\n<p style=\"text-align: justify;\">Em Belo Horizonte, os manifestantes se re\u00fanem na Pra\u00e7a da Liberdade, regi\u00e3o centro-sul da cidade. O local \u00e9 o mesmo utilizado para atos organizados por correligion\u00e1rios do presidente.<br \/>\u00a0<\/p>\n<p style=\"text-align: justify;\">O protesto come\u00e7ou por volta das 10h. Com bandeiras e camisas vermelhas, os manifestantes seguir\u00e3o em passeata at\u00e9 o centro. Os organizadores do ato avisam sobre a necessidade de distanciamento de dois metros entre os participantes, uso de m\u00e1scaras e \u00e1lcool em gel.<br \/>\u00a0<\/p>\n<p style=\"text-align: justify;\">Uma carreata tamb\u00e9m come\u00e7a a ser organizada para quem n\u00e3o se sentir seguro de participar da passeata.<br \/>\u00a0<\/p>\n<p style=\"text-align: justify;\">Em Salvador, a concentra\u00e7\u00e3o do protesto acontece na pra\u00e7a do Campo Grande, regi\u00e3o central, e re\u00fane manifestantes com cartazes e bandeiras contra Bolsonaro.<br \/>\u00a0<\/p>\n<p style=\"text-align: justify;\">For\u00e7as da oposi\u00e7\u00e3o de esquerda estavam rachadas nos \u00faltimos meses sobre ir \u00e0s ruas em meio \u00e0 pandemia de Covid-19, mas entenderam que o descontrole do v\u00edrus e os \u00edndices de desemprego e fome exigem a realiza\u00e7\u00e3o de protestos.<br \/>\u00a0<\/p>\n<p style=\"text-align: justify;\">Para neutralizar as cr\u00edticas, tanto entre apoiadores quanto entre detratores do governo, os articuladores deram orienta\u00e7\u00f5es de seguran\u00e7a para as pessoas que ir\u00e3o aos atos, como o uso de m\u00e1scara adequada (do tipo PFF2) e a ordem de manter distanciamento nas passeatas.<br \/>\u00a0<\/p>\n<p style=\"text-align: justify;\">As manifesta\u00e7\u00f5es deste s\u00e1bado abra\u00e7am ainda pautas como a acelera\u00e7\u00e3o da vacina\u00e7\u00e3o contra a Covid, o retorno do aux\u00edlio emergencial de R$ 600, a luta antirracista, o combate \u00e0 viol\u00eancia policial, o ataque \u00e0s privatiza\u00e7\u00f5es e a defesa da educa\u00e7\u00e3o p\u00fablica.<br \/>\u00a0<\/p>\n<p style=\"text-align: justify;\">Embora partidos e movimentos por tr\u00e1s da convoca\u00e7\u00e3o afirmem que o mote &#8220;fora, Bolsonaro&#8221; traduz o desejo de afastamento imediato, l\u00edderes admitem haver obst\u00e1culos para o desenrolar de um processo. Eles, no entanto, enxergam as mobiliza\u00e7\u00f5es como um passaporte que pode levar a esse destino.<br \/>\u00a0<\/p>\n<p style=\"text-align: justify;\">A avalia\u00e7\u00e3o \u00e9 que o impeachment pode ganhar for\u00e7a a partir da ocupa\u00e7\u00e3o das ruas. Por isso, o esfor\u00e7o \u00e9 para pressionar o centr\u00e3o, fiel a Bolsonaro e uma barreira para o processo na C\u00e2mara, e o presidente da Casa, Arthur Lira (PP-AL), a quem cabe desengavetar um dos 114 pedidos protocolados.<br \/>\u00a0<\/p>\n<p style=\"text-align: justify;\">Na quarta-feira (26), centrais sindicais e movimentos sindicais fizeram um protesto em Bras\u00edlia, no gramado em frente ao Congresso Nacional, para denunciar o aumento da fome no pa\u00eds, reclamar da gest\u00e3o da crise sanit\u00e1ria e pedir o reajuste no valor do aux\u00edlio emergencial.<br \/>\u00a0<\/p>\n<p style=\"text-align: justify;\">A iniciativa foi tratada como um ato simb\u00f3lico, com a presen\u00e7a de n\u00famero reduzido de pessoas e transmiss\u00e3o dos discursos pelas redes sociais. Os manifestantes procuraram congressistas para expor suas bandeiras e fizeram doa\u00e7\u00e3o de alimentos para catadores de material recicl\u00e1vel.<\/p>\n<p>Fonte: Bahia Not\u00edcias<\/p>\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Protestos contra o presidente Jair Bolsonaro liderados por centrais sindicais, movimentos sociais e partidos de esquerda re\u00fanem manifestantes em v\u00e1rias cidades do pa\u00eds. Na manh\u00e3 deste s\u00e1bado (29), h\u00e1 atos em capitais como Rio de Janeiro, Salvador, Belo Horizonte e Recife.\u00a0 As manifesta\u00e7\u00f5es, que foram alvo de cr\u00edticas por acontecerem presencialmente em meio \u00e0 pandemia [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":23923,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[200,197],"tags":[21,3223,1484,3222],"class_list":["post-23922","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil","category-politica","tag-bolsonaro","tag-manifestantes","tag-pandemia","tag-protestos"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/05\/IMAGEM_NOTICIA_5-2-1.jpg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/05\/IMAGEM_NOTICIA_5-2-1.jpg",500,368,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/05\/IMAGEM_NOTICIA_5-2-1-150x150.jpg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/05\/IMAGEM_NOTICIA_5-2-1-300x221.jpg",300,221,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/05\/IMAGEM_NOTICIA_5-2-1.jpg",500,368,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/05\/IMAGEM_NOTICIA_5-2-1.jpg",500,368,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/05\/IMAGEM_NOTICIA_5-2-1.jpg",500,368,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/05\/IMAGEM_NOTICIA_5-2-1.jpg",500,368,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/05\/IMAGEM_NOTICIA_5-2-1.jpg",500,368,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/05\/IMAGEM_NOTICIA_5-2-1-420x307.jpg",420,307,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/05\/IMAGEM_NOTICIA_5-2-1-300x368.jpg",300,368,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/05\/IMAGEM_NOTICIA_5-2-1-464x290.jpg",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/05\/IMAGEM_NOTICIA_5-2-1.jpg",500,368,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/05\/IMAGEM_NOTICIA_5-2-1-322x230.jpg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/05\/IMAGEM_NOTICIA_5-2-1.jpg",500,368,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"Protestos contra o presidente Jair Bolsonaro liderados por centrais sindicais, movimentos sociais e partidos de esquerda re\u00fanem manifestantes em v\u00e1rias cidades do pa\u00eds. Na manh\u00e3 deste s\u00e1bado (29), h\u00e1 atos em capitais como Rio de Janeiro, Salvador, Belo Horizonte e Recife.\u00a0 As manifesta\u00e7\u00f5es, que foram alvo de cr\u00edticas por acontecerem presencialmente em meio \u00e0 pandemia&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/23922","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=23922"}],"version-history":[{"count":2,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/23922\/revisions"}],"predecessor-version":[{"id":23925,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/23922\/revisions\/23925"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/23923"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=23922"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=23922"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=23922"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}