{"id":24777,"date":"2021-06-21T16:50:00","date_gmt":"2021-06-21T19:50:00","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=24777"},"modified":"2021-06-21T13:38:20","modified_gmt":"2021-06-21T16:38:20","slug":"para-reforcar-qualificacao-diretoria-do-instituto-de-previdencia-de-juazeiro-participa-de-curso-sobre-gestao-de-investimentos-financeiros","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2021\/06\/21\/para-reforcar-qualificacao-diretoria-do-instituto-de-previdencia-de-juazeiro-participa-de-curso-sobre-gestao-de-investimentos-financeiros","title":{"rendered":"Para refor\u00e7ar qualifica\u00e7\u00e3o, diretoria do Instituto de Previd\u00eancia de Juazeiro participa de curso sobre gest\u00e3o de investimentos financeiros"},"content":{"rendered":"<p style=\"text-align: justify;\">O zelo pelo patrim\u00f4nio do Instituto de Previd\u00eancia de Juazeiro (IPJ) \u00e9 prioridade para a diretoria da autarquia. Para garantir a administra\u00e7\u00e3o eficiente dos recursos e a sustentabilidade da previd\u00eancia, o instituto vem investindo na capacita\u00e7\u00e3o continuada de toda a equipe.<br \/>\u00a0<br \/>No \u00faltimo final de semana, o diretor executivo, Marcus Onildo, e o diretor financeiro, Edgar Rodrigues, participaram de um curso sobre investimentos financeiros na cidade de S\u00e3o Paulo (SP). As aulas abordaram pontos como: no\u00e7\u00e3o clara de valor, avalia\u00e7\u00e3o de cen\u00e1rios e probabilidades para aplica\u00e7\u00f5es, entre outros.<br \/>\u00a0<br \/>\u201cO objetivo da gest\u00e3o \u00e9 elevar o conhecimento e desenvolvimento do Instituto de Previd\u00eancia de Juazeiro. Estamos procurando nos manter atualizados sobre todos os aspectos que envolvem a gest\u00e3o da autarquia para garantir a sua sa\u00fade financeira. \u00c9 necess\u00e1rio entender que a Previd\u00eancia passa por uma atualiza\u00e7\u00e3o constante, e n\u00f3s tamb\u00e9m seguimos essas mudan\u00e7as, que ir\u00e3o refletir diretamente no nosso trabalho enquanto gestores financeiros\u201d, comentou o diretor Marcus Onildo.<br \/>\u00a0<br \/><b>Capacita\u00e7\u00e3o t\u00e9cnica<\/b><br \/>\u00a0<br \/>O IPJ vem cumprindo as determina\u00e7\u00f5es legais, impostas pela Portaria N\u00ba 9.907 da Secretaria Especial de Previd\u00eancia e Trabalho, que exigem certifica\u00e7\u00f5es que atestam a capacidade t\u00e9cnica dos gestores dos Regimes Pr\u00f3prios de Previd\u00eancia (RPP).<br \/>\u00a0<br \/>No m\u00eas de mar\u00e7o, os integrantes do comit\u00ea de investimentos do IPJ, formado pelos diretores Marcus Onildo, Edgar Rodrigues e pela secret\u00e1ria Thayla Costa receberam o Certificado de Gestor de Regime Pr\u00f3prio de Previd\u00eancia Social (CGRPPS &#8211; 4699), emitido pela Associa\u00e7\u00e3o dos Analistas e Profissionais de Investimentos do Mercado de Capitais (APIMEC). A superintendente Tarsila Ramos e a gerente Silmara Cust\u00f3dio tamb\u00e9m foram aprovadas.<\/p>\n<p>\u00a0<\/p>\n\n\n<p>IPJ-ASCOM PMJ<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O zelo pelo patrim\u00f4nio do Instituto de Previd\u00eancia de Juazeiro (IPJ) \u00e9 prioridade para a diretoria da autarquia. Para garantir a administra\u00e7\u00e3o eficiente dos recursos e a sustentabilidade da previd\u00eancia, o instituto vem investindo na capacita\u00e7\u00e3o continuada de toda a equipe.\u00a0No \u00faltimo final de semana, o diretor executivo, Marcus Onildo, e o diretor financeiro, Edgar [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":24778,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[203],"tags":[2628,3628,1424,3045,3627],"class_list":["post-24777","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-juazeiro","tag-curso","tag-diretoria","tag-gestao","tag-instituto-de-previdencia","tag-qualioficacao"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/06\/Curso-diretoria.jpeg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/06\/Curso-diretoria.jpeg",500,394,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/06\/Curso-diretoria-150x150.jpeg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/06\/Curso-diretoria-300x236.jpeg",300,236,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/06\/Curso-diretoria.jpeg",500,394,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/06\/Curso-diretoria.jpeg",500,394,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/06\/Curso-diretoria.jpeg",500,394,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/06\/Curso-diretoria.jpeg",500,394,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/06\/Curso-diretoria.jpeg",500,394,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/06\/Curso-diretoria-420x307.jpeg",420,307,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/06\/Curso-diretoria-300x394.jpeg",300,394,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/06\/Curso-diretoria-464x290.jpeg",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/06\/Curso-diretoria.jpeg",500,394,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/06\/Curso-diretoria-322x230.jpeg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/06\/Curso-diretoria.jpeg",500,394,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"O zelo pelo patrim\u00f4nio do Instituto de Previd\u00eancia de Juazeiro (IPJ) \u00e9 prioridade para a diretoria da autarquia. Para garantir a administra\u00e7\u00e3o eficiente dos recursos e a sustentabilidade da previd\u00eancia, o instituto vem investindo na capacita\u00e7\u00e3o continuada de toda a equipe.\u00a0No \u00faltimo final de semana, o diretor executivo, Marcus Onildo, e o diretor financeiro, Edgar&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/24777","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=24777"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/24777\/revisions"}],"predecessor-version":[{"id":24779,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/24777\/revisions\/24779"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/24778"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=24777"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=24777"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=24777"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}