{"id":25112,"date":"2021-06-30T14:09:00","date_gmt":"2021-06-30T17:09:00","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=25112"},"modified":"2021-06-30T12:18:14","modified_gmt":"2021-06-30T15:18:14","slug":"pastor-e-preso-por-estuprar-adolescentes-em-vera-cruz","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2021\/06\/30\/pastor-e-preso-por-estuprar-adolescentes-em-vera-cruz","title":{"rendered":"Pastor \u00e9 preso por estuprar adolescentes em Vera Cruz"},"content":{"rendered":"\n\n<p style=\"text-align: justify;\">Um homem de 57 anos que atuava como pastor foi preso, por abusar sexualmente de adolescentes, em Vera Cruz. O l\u00edder religioso foi localizado por investigadores da 24\u00aa Delegacia Territorial (DT\/Vera Cruz), na tarde de ter\u00e7a-feira (29), no bairro do Com\u00e9rcio, em Salvador.<\/p>\n<div class=\"td-a-ad id_inline_ad0 id_ad_content-horiz-center\" style=\"text-align: justify;\">\n<div class=\"a-single a-21\"><span style=\"font-size: inherit;\">As investiga\u00e7\u00f5es foram iniciadas quando a m\u00e3e de uma garota, de 13 anos, realizou a den\u00fancia na unidade policial. De acordo o titular da DT\/Vera Cruz, delegado Willian Achan, outras mulheres foram v\u00edtimas do abusador. \u201cEle aproveitava-se de sua condi\u00e7\u00e3o de l\u00edder religioso e mantinha rela\u00e7\u00f5es com frequentadoras da igreja. Ficou conhecido como o pastor que abusava das ovelhas\u201d, esclareceu Achan.<\/span><\/div>\n<\/div>\n<p style=\"text-align: justify;\">\u201cTemos informa\u00e7\u00f5es que ele tamb\u00e9m atacou a enteada, h\u00e1 cerca de 18 anos, quando ela ainda era adolescente\u201d, acrescentou o titular. Conforme foi levantado nas apura\u00e7\u00f5es, o suspeito gravava e armazenava v\u00eddeos e outros materiais relacionados \u00e0 pornografia infantil. \u201cEle destruiu v\u00e1rias provas e fugiu da cidade, mas conseguimos localiz\u00e1-lo e cumprir o mandado\u201d, disse o delegado.<\/p>\n<p style=\"text-align: justify;\">Apresentado na unidade policial, o homem deve prestar depoimento e ser submetido ao exame de les\u00f5es corporais. Ele permanecer\u00e1 custodiado, \u00e0 disposi\u00e7\u00e3o da Justi\u00e7a.<\/p>\n\n\n<p>Fonte: Informe Baiano<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um homem de 57 anos que atuava como pastor foi preso, por abusar sexualmente de adolescentes, em Vera Cruz. O l\u00edder religioso foi localizado por investigadores da 24\u00aa Delegacia Territorial (DT\/Vera Cruz), na tarde de ter\u00e7a-feira (29), no bairro do Com\u00e9rcio, em Salvador. As investiga\u00e7\u00f5es foram iniciadas quando a m\u00e3e de uma garota, de 13 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":25113,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[202],"tags":[3790,1219,3403,1817,3791],"class_list":["post-25112","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policia","tag-adolescentes","tag-estupro","tag-pastor","tag-preso","tag-vera-cruz"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/06\/ADCD856B-154B-417C-9345-BBAC69BAFF72-696x464-1.jpeg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/06\/ADCD856B-154B-417C-9345-BBAC69BAFF72-696x464-1.jpeg",500,333,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/06\/ADCD856B-154B-417C-9345-BBAC69BAFF72-696x464-1-150x150.jpeg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/06\/ADCD856B-154B-417C-9345-BBAC69BAFF72-696x464-1-300x200.jpeg",300,200,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/06\/ADCD856B-154B-417C-9345-BBAC69BAFF72-696x464-1.jpeg",500,333,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/06\/ADCD856B-154B-417C-9345-BBAC69BAFF72-696x464-1.jpeg",500,333,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/06\/ADCD856B-154B-417C-9345-BBAC69BAFF72-696x464-1.jpeg",500,333,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/06\/ADCD856B-154B-417C-9345-BBAC69BAFF72-696x464-1.jpeg",500,333,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/06\/ADCD856B-154B-417C-9345-BBAC69BAFF72-696x464-1.jpeg",500,333,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/06\/ADCD856B-154B-417C-9345-BBAC69BAFF72-696x464-1-420x307.jpeg",420,307,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/06\/ADCD856B-154B-417C-9345-BBAC69BAFF72-696x464-1-300x333.jpeg",300,333,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/06\/ADCD856B-154B-417C-9345-BBAC69BAFF72-696x464-1-464x290.jpeg",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/06\/ADCD856B-154B-417C-9345-BBAC69BAFF72-696x464-1.jpeg",500,333,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/06\/ADCD856B-154B-417C-9345-BBAC69BAFF72-696x464-1-322x230.jpeg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/06\/ADCD856B-154B-417C-9345-BBAC69BAFF72-696x464-1.jpeg",500,333,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"Um homem de 57 anos que atuava como pastor foi preso, por abusar sexualmente de adolescentes, em Vera Cruz. O l\u00edder religioso foi localizado por investigadores da 24\u00aa Delegacia Territorial (DT\/Vera Cruz), na tarde de ter\u00e7a-feira (29), no bairro do Com\u00e9rcio, em Salvador. As investiga\u00e7\u00f5es foram iniciadas quando a m\u00e3e de uma garota, de 13&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/25112","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=25112"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/25112\/revisions"}],"predecessor-version":[{"id":25114,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/25112\/revisions\/25114"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/25113"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=25112"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=25112"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=25112"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}