{"id":26263,"date":"2021-07-27T15:15:00","date_gmt":"2021-07-27T18:15:00","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=26263"},"modified":"2021-07-27T14:07:36","modified_gmt":"2021-07-27T17:07:36","slug":"facape-esta-com-inscricoes-abertas-para-processo-seletivo-matriculas-sao-imediatas-com-ingresso-no-segundo-semestre","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2021\/07\/27\/facape-esta-com-inscricoes-abertas-para-processo-seletivo-matriculas-sao-imediatas-com-ingresso-no-segundo-semestre","title":{"rendered":"Facape est\u00e1 com inscri\u00e7\u00f5es abertas para processo seletivo; matr\u00edculas s\u00e3o imediatas, com ingresso no segundo semestre"},"content":{"rendered":"\n\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"77\" data-block-id=\"2\">\n<p class=\"content-text__container \" style=\"text-align: justify;\" data-track-category=\"Link no Texto\" data-track-links=\"\">A Faculdade de Petrolina \u2013 Facape est\u00e1 com\u00a0<span class=\"highlight highlighted\">inscri\u00e7\u00f5es abertas, at\u00e9 o dia 13 de agosto, para a \u00faltima etapa de processo seletivo simplificado, com matr\u00edcula imediata em cursos de gradua\u00e7\u00e3o.<\/span>\u00a0Os interessados podem concorrer as vagas atrav\u00e9s da nota do Enem, com nota m\u00ednima de 300 pontos, ou an\u00e1lise do hist\u00f3rico escolar.\u00a0<span class=\"highlight highlighted\">As inscri\u00e7\u00f5es podem ser feitas presencialmente no setor de concursos da Facape e o valor da taxa de inscri\u00e7\u00e3o \u00e9 de R$ 20,00.<\/span><\/p>\n<\/div>\n<div class=\"wall protected-content\">\n<div class=\"mc-column content-text active-extra-styles \" style=\"text-align: justify;\" data-block-type=\"unstyled\" data-block-weight=\"28\" data-block-id=\"3\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Neste semestre, a Facape oferece vagas distribu\u00eddas entre os cursos de\u00a0<span class=\"highlight highlighted\">administra\u00e7\u00e3o, ci\u00eancia da computa\u00e7\u00e3o, ci\u00eancias cont\u00e1beis, direito, economia, servi\u00e7o social e superior de tecnologia em com\u00e9rcio exterior.<\/span><\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" style=\"text-align: justify;\" data-block-type=\"unstyled\" data-block-weight=\"37\" data-block-id=\"4\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\"><span class=\"highlight highlighted\">Os documentos exigidos no ato da inscri\u00e7\u00e3o s\u00e3o c\u00f3pia do RG ou documento equivalente, boletim da nota do Enem ou hist\u00f3rico escolar e documentos exigidos para matr\u00edcula,<\/span>\u00a0que voc\u00ea encontra no edital do processo seletivo\u00a0<a href=\"http:\/\/sistemas.facape.br:8080\/vestibular\/arquivos\/editais\/PROCESSO_SELETIVO_SIMPLIFICADO_PARA_MATRICULA_IMEDIATA.pdf\" target=\"_blank\" rel=\"noopener\">(clique aqui).<\/a><\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" style=\"text-align: justify;\" data-block-type=\"unstyled\" data-block-weight=\"16\" data-block-id=\"5\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\"><span class=\"highlight highlighted\">Os aprovados realizar\u00e3o matr\u00edcula imediata, com ingresso no segundo semestre letivo do ano de 2021.<\/span><\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" style=\"text-align: justify;\" data-block-type=\"unstyled\" data-block-weight=\"38\" data-block-id=\"6\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Outras informa\u00e7\u00f5es podem ser consultadas atrav\u00e9s dos seguintes canais oficiais da Facape:\u00a0<span class=\"highlight highlighted\">Whatsapp: (87) 3866 &#8211; 3260\/ E-mail: vestibular@facape.br\/ telefones (87) 3866-3269 ou (87) 3866-3260 (das 8h \u00e0s 12h e das 15h \u00e0s 19h, de segunda a sexta-feira).<\/span><\/p>\n<\/div>\n<\/div>\n<div class=\"block-podcast\" style=\"text-align: justify;\">\u00a0<\/div>\n\n\n<p><strong>Por: G1 Petrolina<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Faculdade de Petrolina \u2013 Facape est\u00e1 com\u00a0inscri\u00e7\u00f5es abertas, at\u00e9 o dia 13 de agosto, para a \u00faltima etapa de processo seletivo simplificado, com matr\u00edcula imediata em cursos de gradua\u00e7\u00e3o.\u00a0Os interessados podem concorrer as vagas atrav\u00e9s da nota do Enem, com nota m\u00ednima de 300 pontos, ou an\u00e1lise do hist\u00f3rico escolar.\u00a0As inscri\u00e7\u00f5es podem ser feitas [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":26264,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[851],"tags":[897,2627,993,3037],"class_list":["post-26263","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-petrolina","tag-facape","tag-inscricoes-abertas","tag-processo-seletivo","tag-segundo-semestre"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/07\/facape-2021.1.jpeg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/07\/facape-2021.1.jpeg",500,333,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/07\/facape-2021.1-150x150.jpeg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/07\/facape-2021.1-300x200.jpeg",300,200,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/07\/facape-2021.1.jpeg",500,333,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/07\/facape-2021.1.jpeg",500,333,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/07\/facape-2021.1.jpeg",500,333,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/07\/facape-2021.1.jpeg",500,333,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/07\/facape-2021.1.jpeg",500,333,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/07\/facape-2021.1-420x307.jpeg",420,307,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/07\/facape-2021.1-300x333.jpeg",300,333,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/07\/facape-2021.1-464x290.jpeg",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/07\/facape-2021.1.jpeg",500,333,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/07\/facape-2021.1-322x230.jpeg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/07\/facape-2021.1.jpeg",500,333,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"A Faculdade de Petrolina \u2013 Facape est\u00e1 com\u00a0inscri\u00e7\u00f5es abertas, at\u00e9 o dia 13 de agosto, para a \u00faltima etapa de processo seletivo simplificado, com matr\u00edcula imediata em cursos de gradua\u00e7\u00e3o.\u00a0Os interessados podem concorrer as vagas atrav\u00e9s da nota do Enem, com nota m\u00ednima de 300 pontos, ou an\u00e1lise do hist\u00f3rico escolar.\u00a0As inscri\u00e7\u00f5es podem ser feitas&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/26263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=26263"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/26263\/revisions"}],"predecessor-version":[{"id":26265,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/26263\/revisions\/26265"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/26264"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=26263"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=26263"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=26263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}