{"id":26681,"date":"2021-08-07T11:28:00","date_gmt":"2021-08-07T14:28:00","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=26681"},"modified":"2021-08-07T10:03:06","modified_gmt":"2021-08-07T13:03:06","slug":"petrolina-anuncia-novo-cronograma-de-retorno-das-aulas-presenciais-na-rede-municipal","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2021\/08\/07\/petrolina-anuncia-novo-cronograma-de-retorno-das-aulas-presenciais-na-rede-municipal","title":{"rendered":"Petrolina anuncia novo cronograma de retorno das aulas presenciais na rede municipal"},"content":{"rendered":"<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"91\" data-block-id=\"2\">\n<p class=\"content-text__container \" style=\"text-align: justify;\" data-track-category=\"Link no Texto\" data-track-links=\"\">A prefeitura de Petrolina, no Sert\u00e3o de Pernambuco, anunciou nesta sexta-feira (6) um novo cronograma de retorno das aulas presenciais na rede municipal de ensino.\u00a0<span class=\"highlight highlighted\">Na segunda-feira (9), retomam as aulas nas Escolas de Tempo Integral. No dia 16 de agosto, retornam as turmas dos anos finais (do 6\u00ba ao 9\u00ba ano). No dia 23 deste m\u00eas, ser\u00e1 a vez dos alunos do 4\u00ba, 5\u00ba ano e EJA. No dia 30, as turmas do 1\u00ba, 2\u00ba e 3\u00ba ano. Em 6 de setembro, iniciam todos os estudantes da Educa\u00e7\u00e3o Infantil.<\/span><\/p>\n<\/div>\n<div class=\"wall protected-content\" style=\"text-align: justify;\">\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"61\" data-block-id=\"3\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">O retorno \u00e0s aulas presenciais ser\u00e1 opcional e h\u00edbrido, ou seja, as fam\u00edlias v\u00e3o poder decidir se enviam as crian\u00e7as para as aulas presenciais ou se as mant\u00eam, somente, no ensino remoto. Para isso, a Secretaria disponibilizou um termo de responsabilidade que foi preenchido e assinado pelos respons\u00e1veis dos estudantes, autorizando a modalidade de ensino que o aluno participar\u00e1.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"53\" data-block-id=\"4\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Segundo a prefeitura, visando garantir a seguran\u00e7a de toda comunidade escolar, as salas de aula funcionar\u00e3o inicialmente com 50% da capacidade. As turmas ser\u00e3o divididas em grupos, que revezar\u00e3o a ida \u00e0s escolas, para garantir o distanciamento de 1 metro em salas ventiladas, e de 2 metros nas que t\u00eam pouca ventila\u00e7\u00e3o.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"64\" data-block-id=\"6\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">A prefeitura informou que a estrutura das escolas foi refor\u00e7ada com dispensers de \u00e1lcool e sabonetes, pias e torneiras autom\u00e1ticas, term\u00f4metro para aferi\u00e7\u00e3o de temperatura e tapetes sanitizantes, al\u00e9m disso, as unidades receberam EPIS que ser\u00e3o utilizados pelos funcion\u00e1rios, para preven\u00e7\u00e3o do Covid-19, como face shield, m\u00e1scaras, luvas e toucas. Cada estudante vai ganhar duas m\u00e1scaras e uma garrafa squeze para uso individual.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"45\" data-block-id=\"7\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Ao chegar \u00e0 escola, todos ter\u00e3o as m\u00e3os e cal\u00e7ados higienizados, al\u00e9m de passar por aferi\u00e7\u00e3o de temperatura. Mais de R$ 4 milh\u00f5es foram investidos para a compra de equipamentos de seguran\u00e7a e manuten\u00e7\u00e3o nas escolas, destinados a preparar os espa\u00e7os para o retorno.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"3\" data-block-id=\"8\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\"><strong>Mudan\u00e7a de data<\/strong><\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"45\" data-block-id=\"9\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Anteriormente,<a href=\"https:\/\/g1.globo.com\/pe\/petrolina-regiao\/noticia\/2021\/07\/05\/petrolina-divulga-calendario-de-retorno-presencial-de-escolas-da-rede-municipal-de-ensino.ghtml\">\u00a0o in\u00edcio das aulas estava previsto para o dia 2 de agosto.<\/a>\u00a0No entanto, a prefeitura informou que as aulas das quatro escolas de tempo integral foram adiadas por pelo menos uma semana devido a um atraso no processo licitat\u00f3rio da merenda escolar.<\/p>\n<p data-track-category=\"Link no Texto\" data-track-links=\"\">\n<\/div>\n<\/div>\n<div class=\"block-podcast\" style=\"text-align: justify;\">Por: G1 Petrolina<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A prefeitura de Petrolina, no Sert\u00e3o de Pernambuco, anunciou nesta sexta-feira (6) um novo cronograma de retorno das aulas presenciais na rede municipal de ensino.\u00a0Na segunda-feira (9), retomam as aulas nas Escolas de Tempo Integral. No dia 16 de agosto, retornam as turmas dos anos finais (do 6\u00ba ao 9\u00ba ano). No dia 23 deste [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":26684,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[851],"tags":[3217,4514,2478,3472,3919],"class_list":["post-26681","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-petrolina","tag-anuncio","tag-novo-cronograma","tag-petrolina-pe","tag-rede-municipal","tag-retorno-as-aulas"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/08\/escolaintegral.jpg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/08\/escolaintegral.jpg",500,333,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/08\/escolaintegral-150x150.jpg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/08\/escolaintegral-300x200.jpg",300,200,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/08\/escolaintegral.jpg",500,333,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/08\/escolaintegral.jpg",500,333,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/08\/escolaintegral.jpg",500,333,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/08\/escolaintegral.jpg",500,333,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/08\/escolaintegral.jpg",500,333,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/08\/escolaintegral-420x307.jpg",420,307,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/08\/escolaintegral-300x333.jpg",300,333,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/08\/escolaintegral-464x290.jpg",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/08\/escolaintegral.jpg",500,333,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/08\/escolaintegral-322x230.jpg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/08\/escolaintegral.jpg",500,333,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"A prefeitura de Petrolina, no Sert\u00e3o de Pernambuco, anunciou nesta sexta-feira (6) um novo cronograma de retorno das aulas presenciais na rede municipal de ensino.\u00a0Na segunda-feira (9), retomam as aulas nas Escolas de Tempo Integral. No dia 16 de agosto, retornam as turmas dos anos finais (do 6\u00ba ao 9\u00ba ano). No dia 23 deste&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/26681","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=26681"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/26681\/revisions"}],"predecessor-version":[{"id":26685,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/26681\/revisions\/26685"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/26684"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=26681"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=26681"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=26681"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}