{"id":27012,"date":"2021-08-15T07:49:00","date_gmt":"2021-08-15T10:49:00","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=27012"},"modified":"2021-08-14T21:23:47","modified_gmt":"2021-08-15T00:23:47","slug":"atepaaj-e-sinserp-vao-realizar-manifesto-em-frente-ao-paco-segunda-16-pedindo-auditoria-no-ipj","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2021\/08\/15\/atepaaj-e-sinserp-vao-realizar-manifesto-em-frente-ao-paco-segunda-16-pedindo-auditoria-no-ipj","title":{"rendered":"Atepaaj e Sinserp v\u00e3o realizar manifesto em frente ao Pa\u00e7o segunda (16) pedindo auditoria no IPJ"},"content":{"rendered":"<div class=\"post-content-area\">\n<p style=\"text-align: justify;\">No programa Geraldo Jos\u00e9 (R\u00e1dio Juazeiro Am St\u00e9reo) da \u00faltima sexta-feira (13) a professora Maeth Soares, presidente da Associa\u00e7\u00e3o dos Trabalhadores em Educa\u00e7\u00e3o, dos Pensionistas e Aposentados de Juazeiro (ATEPAAJ) e Luiz Alberto presidente do Sinserp (Sindicato dos Servidores P\u00fablicos da Prefeitura Municipal) anunciaram manifesta\u00e7\u00e3o na pr\u00f3xima segunda-feira (16), a partir das 8:30h, em frente ao Pa\u00e7o Municipal.<\/p>\n<p style=\"text-align: justify;\">\u201cIremos promover um movimento em frente ao Pa\u00e7o Municipal, nossa pauta ser\u00e1 a instala\u00e7\u00e3o de uma auditoria no IPJ (Instituto Previdenci\u00e1rio de Juazeiro), em car\u00e1ter de urg\u00eancia. Estamos sabendo de ind\u00edcios fortes de fraudes e a\u00e7\u00f5es obscuras no Instituto. N\u00e3o podemos nos calar\u201d pontuou Maete Soares.<\/p>\n<p style=\"text-align: justify;\">J\u00e1 o presidente do Sinserp lembrou que a manifesta\u00e7\u00e3o atende a pedido do pr\u00f3prio servidor. \u201cO que n\u00f3s desejamos \u00e9 apenas transpar\u00eancia com o patrim\u00f4nio do servidor. A garantia de que tudo est\u00e1 andando corretamente no IPJ\u201d.<\/p>\n<p style=\"text-align: justify;\">\u201cVamos pedir a Prefeita, que est\u00e1 silenciosa no tocante ao m\u00e9rito, que se pronuncie e fa\u00e7a uma interven\u00e7\u00e3o nessa autarquia da Prefeitura\u201d concluiu Maete Soares.<\/p>\n<p style=\"text-align: justify;\">\n<p>Fonte: Rede GN<\/p>\n<\/div>\n<div class=\"post-footer\" style=\"text-align: justify;\">&nbsp;<\/div>\n","protected":false},"excerpt":{"rendered":"<p>No programa Geraldo Jos\u00e9 (R\u00e1dio Juazeiro Am St\u00e9reo) da \u00faltima sexta-feira (13) a professora Maeth Soares, presidente da Associa\u00e7\u00e3o dos Trabalhadores em Educa\u00e7\u00e3o, dos Pensionistas e Aposentados de Juazeiro (ATEPAAJ) e Luiz Alberto presidente do Sinserp (Sindicato dos Servidores P\u00fablicos da Prefeitura Municipal) anunciaram manifesta\u00e7\u00e3o na pr\u00f3xima segunda-feira (16), a partir das 8:30h, em frente [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":21379,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[203],"tags":[4673,1655,524,4674,3459],"class_list":["post-27012","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-juazeiro","tag-atepaaj-e-sinserp","tag-ipj","tag-manifestacao","tag-pedido-de-auditoria","tag-proxima-segunda-feira"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/03\/IPJ29.03.jpeg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/03\/IPJ29.03.jpeg",500,333,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/03\/IPJ29.03-150x150.jpeg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/03\/IPJ29.03-300x200.jpeg",300,200,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/03\/IPJ29.03.jpeg",500,333,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/03\/IPJ29.03.jpeg",500,333,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/03\/IPJ29.03.jpeg",500,333,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/03\/IPJ29.03.jpeg",500,333,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/03\/IPJ29.03.jpeg",500,333,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/03\/IPJ29.03-420x307.jpeg",420,307,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/03\/IPJ29.03-300x333.jpeg",300,333,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/03\/IPJ29.03-464x290.jpeg",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/03\/IPJ29.03.jpeg",500,333,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/03\/IPJ29.03-322x230.jpeg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/03\/IPJ29.03.jpeg",500,333,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"No programa Geraldo Jos\u00e9 (R\u00e1dio Juazeiro Am St\u00e9reo) da \u00faltima sexta-feira (13) a professora Maeth Soares, presidente da Associa\u00e7\u00e3o dos Trabalhadores em Educa\u00e7\u00e3o, dos Pensionistas e Aposentados de Juazeiro (ATEPAAJ) e Luiz Alberto presidente do Sinserp (Sindicato dos Servidores P\u00fablicos da Prefeitura Municipal) anunciaram manifesta\u00e7\u00e3o na pr\u00f3xima segunda-feira (16), a partir das 8:30h, em frente&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/27012","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=27012"}],"version-history":[{"count":2,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/27012\/revisions"}],"predecessor-version":[{"id":27014,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/27012\/revisions\/27014"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/21379"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=27012"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=27012"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=27012"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}