{"id":27092,"date":"2021-08-17T09:40:00","date_gmt":"2021-08-17T12:40:00","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=27092"},"modified":"2021-08-16T16:42:23","modified_gmt":"2021-08-16T19:42:23","slug":"prefeitura-de-juazeiro-realiza-serie-de-formacoes-preparatorias-para-prova-que-avalia-qualidade-da-educacao-basica","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2021\/08\/17\/prefeitura-de-juazeiro-realiza-serie-de-formacoes-preparatorias-para-prova-que-avalia-qualidade-da-educacao-basica","title":{"rendered":"Prefeitura de Juazeiro realiza s\u00e9rie de forma\u00e7\u00f5es preparat\u00f3rias para prova que avalia qualidade da educa\u00e7\u00e3o b\u00e1sica"},"content":{"rendered":"<p dir=\"ltr\">A Prefeitura de Juazeiro, atrav\u00e9s da Secretaria de Educa\u00e7\u00e3o e Juventude (Seduc), est\u00e1 realizando uma s\u00e9rie de forma\u00e7\u00f5es continuadas preparat\u00f3rias para a Avalia\u00e7\u00e3o Nacional da Educa\u00e7\u00e3o B\u00e1sica (Saeb), que acontecer\u00e1 entre os dias 8 de novembro a 10 de dezembro. A iniciativa \u00e9 voltada para professores da Rede Municipal de Ensino, que atuam com 2\u00ba, 5\u00ba e 9\u00ba anos, e visa dar suporte pedag\u00f3gico, tamb\u00e9m, para os profissionais rec\u00e9m-contratados e, oportunamente, preparar os estudantes para avalia\u00e7\u00e3o nacional. Os resultados da avalia\u00e7\u00e3o\u00a0 geram dados para o desenvolvimento de pol\u00edticas educacionais brasileiras.<\/p>\n<p dir=\"ltr\">A programa\u00e7\u00e3o virtual ser\u00e1 realizada at\u00e9 o m\u00eas de novembro e visa atender mais de 300 professores da Rede Municipal. As forma\u00e7\u00f5es s\u00e3o conduzidas pelos formadores da Escola de Forma\u00e7\u00e3o de Educadores Parlim (Efep) e abordam as habilidades b\u00e1sicas e compet\u00eancias da prova Saeb, dentro dos componentes curriculares L\u00edngua Portuguesa, Matem\u00e1tica, Ci\u00eancias da Natureza e Ci\u00eancias Humanas.<\/p>\n<p dir=\"ltr\">\u201cEssa \u00e9 uma avalia\u00e7\u00e3o importante para definir o \u00edndice de qualidade da Educa\u00e7\u00e3o B\u00e1sica de cada munic\u00edpio brasileiro. Preparar os professores \u00e9 investir nos estudantes e contribuir para a constru\u00e7\u00e3o de um ensino de qualidade em Juazeiro\u201d, destacou a secret\u00e1ria de Educa\u00e7\u00e3o e Juventude, Normeide Almeida.<\/p>\n<p dir=\"ltr\">Prova Saeb<\/p>\n<p dir=\"ltr\">Antes aplicada de forma bianual, a partir de 2021 a prova Saeb ser\u00e1 aplicada anualmente, de acordo com a Portaria N\u00ba 250\/2021. O resultado da avalia\u00e7\u00e3o nacional \u00e9 utilizado para calcular o \u00cdndice de Desenvolvimento da Educa\u00e7\u00e3o B\u00e1sica (Ideb), e dessa forma, criar, monitorar e aprimorar pol\u00edticas p\u00fablicas para esse segmento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Juazeiro, atrav\u00e9s da Secretaria de Educa\u00e7\u00e3o e Juventude (Seduc), est\u00e1 realizando uma s\u00e9rie de forma\u00e7\u00f5es continuadas preparat\u00f3rias para a Avalia\u00e7\u00e3o Nacional da Educa\u00e7\u00e3o B\u00e1sica (Saeb), que acontecer\u00e1 entre os dias 8 de novembro a 10 de dezembro. A iniciativa \u00e9 voltada para professores da Rede Municipal de Ensino, que atuam com 2\u00ba, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":27093,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[203],"tags":[4405,3472,4709,902],"class_list":["post-27092","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-juazeiro","tag-prova","tag-rede-municipal","tag-saeb","tag-seduc"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/08\/Formacoes-Seduc.jpg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/08\/Formacoes-Seduc.jpg",500,332,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/08\/Formacoes-Seduc-150x150.jpg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/08\/Formacoes-Seduc-300x199.jpg",300,199,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/08\/Formacoes-Seduc.jpg",500,332,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/08\/Formacoes-Seduc.jpg",500,332,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/08\/Formacoes-Seduc.jpg",500,332,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/08\/Formacoes-Seduc.jpg",500,332,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/08\/Formacoes-Seduc.jpg",500,332,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/08\/Formacoes-Seduc-420x307.jpg",420,307,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/08\/Formacoes-Seduc-300x332.jpg",300,332,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/08\/Formacoes-Seduc-464x290.jpg",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/08\/Formacoes-Seduc.jpg",500,332,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/08\/Formacoes-Seduc-322x230.jpg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/08\/Formacoes-Seduc.jpg",500,332,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"A Prefeitura de Juazeiro, atrav\u00e9s da Secretaria de Educa\u00e7\u00e3o e Juventude (Seduc), est\u00e1 realizando uma s\u00e9rie de forma\u00e7\u00f5es continuadas preparat\u00f3rias para a Avalia\u00e7\u00e3o Nacional da Educa\u00e7\u00e3o B\u00e1sica (Saeb), que acontecer\u00e1 entre os dias 8 de novembro a 10 de dezembro. A iniciativa \u00e9 voltada para professores da Rede Municipal de Ensino, que atuam com 2\u00ba,&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/27092","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=27092"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/27092\/revisions"}],"predecessor-version":[{"id":27094,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/27092\/revisions\/27094"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/27093"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=27092"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=27092"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=27092"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}