{"id":27527,"date":"2021-08-27T14:21:00","date_gmt":"2021-08-27T17:21:00","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=27527"},"modified":"2021-08-27T14:21:16","modified_gmt":"2021-08-27T17:21:16","slug":"paciente-denuncia-falta-de-medicamento-no-caps-ad-iii-em-juazeiro-ba","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2021\/08\/27\/paciente-denuncia-falta-de-medicamento-no-caps-ad-iii-em-juazeiro-ba","title":{"rendered":"Paciente Den\u00fancia falta de medicamento no CAPS AD III, em Juazeiro-BA"},"content":{"rendered":"<p style=\"text-align: justify;\">Na manh\u00e3 desta sexta-feira (27) a Reda\u00e7\u00e3o do Blog Opar\u00e1 recebeu uma den\u00fancia de um Paciente do CAPS AD III, de Juazeiro (BA), reclamando da falta de rem\u00e9dios b\u00e1sicos, que s\u00e3o distribu\u00eddos aos pacientes que recebem assist\u00eancia da Unidade de Sa\u00fade.<\/p>\n<p style=\"text-align: justify;\">O paciente relatou que esteve no CAPS hoje, pela manh\u00e3, com a receita n\u00e3o m\u00e3o, para pegas os medicamentos, clonazepam ou rivotril, mas foi informado que a medica\u00e7\u00e3o indicada est\u00e1 em falta.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-27533\" src=\"https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/08\/WhatsApp-Image-2021-08-27-at-11.16.05-300x169.jpeg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/08\/WhatsApp-Image-2021-08-27-at-11.16.05-300x169.jpeg 300w, https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/08\/WhatsApp-Image-2021-08-27-at-11.16.05.jpeg 500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na manh\u00e3 desta sexta-feira (27) a Reda\u00e7\u00e3o do Blog Opar\u00e1 recebeu uma den\u00fancia de um Paciente do CAPS AD III, de Juazeiro (BA), reclamando da falta de rem\u00e9dios b\u00e1sicos, que s\u00e3o distribu\u00eddos aos pacientes que recebem assist\u00eancia da Unidade de Sa\u00fade. O paciente relatou que esteve no CAPS hoje, pela manh\u00e3, com a receita n\u00e3o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":27531,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[203],"tags":[4920,784,1882,4604],"class_list":["post-27527","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-juazeiro","tag-caps-adiii","tag-denuncia","tag-falta-de-medicamento","tag-paciente"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/08\/WhatsApp-Image-2021-08-27-at-11.16.06.jpeg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/08\/WhatsApp-Image-2021-08-27-at-11.16.06.jpeg",500,281,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/08\/WhatsApp-Image-2021-08-27-at-11.16.06-150x150.jpeg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/08\/WhatsApp-Image-2021-08-27-at-11.16.06-300x169.jpeg",300,169,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/08\/WhatsApp-Image-2021-08-27-at-11.16.06.jpeg",500,281,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/08\/WhatsApp-Image-2021-08-27-at-11.16.06.jpeg",500,281,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/08\/WhatsApp-Image-2021-08-27-at-11.16.06.jpeg",500,281,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/08\/WhatsApp-Image-2021-08-27-at-11.16.06.jpeg",500,281,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/08\/WhatsApp-Image-2021-08-27-at-11.16.06.jpeg",500,281,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/08\/WhatsApp-Image-2021-08-27-at-11.16.06-420x281.jpeg",420,281,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/08\/WhatsApp-Image-2021-08-27-at-11.16.06-300x281.jpeg",300,281,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/08\/WhatsApp-Image-2021-08-27-at-11.16.06-464x281.jpeg",464,281,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/08\/WhatsApp-Image-2021-08-27-at-11.16.06.jpeg",500,281,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/08\/WhatsApp-Image-2021-08-27-at-11.16.06-322x230.jpeg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/08\/WhatsApp-Image-2021-08-27-at-11.16.06.jpeg",500,281,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"Na manh\u00e3 desta sexta-feira (27) a Reda\u00e7\u00e3o do Blog Opar\u00e1 recebeu uma den\u00fancia de um Paciente do CAPS AD III, de Juazeiro (BA), reclamando da falta de rem\u00e9dios b\u00e1sicos, que s\u00e3o distribu\u00eddos aos pacientes que recebem assist\u00eancia da Unidade de Sa\u00fade. O paciente relatou que esteve no CAPS hoje, pela manh\u00e3, com a receita n\u00e3o&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/27527","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=27527"}],"version-history":[{"count":3,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/27527\/revisions"}],"predecessor-version":[{"id":27537,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/27527\/revisions\/27537"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/27531"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=27527"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=27527"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=27527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}