{"id":27837,"date":"2021-09-04T16:36:51","date_gmt":"2021-09-04T19:36:51","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=27837"},"modified":"2021-09-04T16:36:54","modified_gmt":"2021-09-04T19:36:54","slug":"o-corpo-de-um-homem-foi-encontro-proximo-a-entrada-do-vale-do-salitre-em-juazeiro-ba","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2021\/09\/04\/o-corpo-de-um-homem-foi-encontro-proximo-a-entrada-do-vale-do-salitre-em-juazeiro-ba","title":{"rendered":"O Corpo de um homem foi encontro pr\u00f3ximo a entrada do Vale do Salitre, em Juazeiro-BA"},"content":{"rendered":"\n\n<p style=\"text-align: justify;\">Na manh\u00e3 deste s\u00e1bado (04) mais um crime violento e intencional foi registrado em Juazeiro, no norte da Bahia por volta de 10:40h . O corpo de um homem foi encontrado pr\u00f3ximo a pista\u00a0 que d\u00e1 acesso ao Vale do Salitre.\u00a0<\/p>\n<p style=\"text-align: justify;\">De acordo informa\u00e7\u00f5es de populares,\u00a0 coletadores encontraram um cad\u00e1ver com marcas de viol\u00eancia, nas proximidades do aterro sanit\u00e1rio, \u00e0s margens da BA-210, no sentidod o Salitre.<\/p>\n<p style=\"text-align: justify;\">A PM preservou o local\u00a0 do fato. O corpo do homem foi encaminhado para o IML, ap\u00f3s Departamento de Pol\u00edcia T\u00e9cnica realizar o procedimentos necess\u00e1rios.<\/p>\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na manh\u00e3 deste s\u00e1bado (04) mais um crime violento e intencional foi registrado em Juazeiro, no norte da Bahia por volta de 10:40h . O corpo de um homem foi encontrado pr\u00f3ximo a pista\u00a0 que d\u00e1 acesso ao Vale do Salitre.\u00a0 De acordo informa\u00e7\u00f5es de populares,\u00a0 coletadores encontraram um cad\u00e1ver com marcas de viol\u00eancia, nas [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":27838,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[203,202],"tags":[5098,3605,143,5099],"class_list":["post-27837","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-juazeiro","category-policia","tag-corpo-de-homem","tag-encontrado","tag-juazeiro-da-bahia","tag-proximo-a-entrada"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/09\/a13cfb10-7ac1-4917-9e4e-139dddd4ed02.jpg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/09\/a13cfb10-7ac1-4917-9e4e-139dddd4ed02.jpg",500,281,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/09\/a13cfb10-7ac1-4917-9e4e-139dddd4ed02-150x150.jpg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/09\/a13cfb10-7ac1-4917-9e4e-139dddd4ed02-300x169.jpg",300,169,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/09\/a13cfb10-7ac1-4917-9e4e-139dddd4ed02.jpg",500,281,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/09\/a13cfb10-7ac1-4917-9e4e-139dddd4ed02.jpg",500,281,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/09\/a13cfb10-7ac1-4917-9e4e-139dddd4ed02.jpg",500,281,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/09\/a13cfb10-7ac1-4917-9e4e-139dddd4ed02.jpg",500,281,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/09\/a13cfb10-7ac1-4917-9e4e-139dddd4ed02.jpg",500,281,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/09\/a13cfb10-7ac1-4917-9e4e-139dddd4ed02-420x281.jpg",420,281,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/09\/a13cfb10-7ac1-4917-9e4e-139dddd4ed02-300x281.jpg",300,281,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/09\/a13cfb10-7ac1-4917-9e4e-139dddd4ed02-464x281.jpg",464,281,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/09\/a13cfb10-7ac1-4917-9e4e-139dddd4ed02.jpg",500,281,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/09\/a13cfb10-7ac1-4917-9e4e-139dddd4ed02-322x230.jpg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/09\/a13cfb10-7ac1-4917-9e4e-139dddd4ed02.jpg",500,281,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"Na manh\u00e3 deste s\u00e1bado (04) mais um crime violento e intencional foi registrado em Juazeiro, no norte da Bahia por volta de 10:40h . O corpo de um homem foi encontrado pr\u00f3ximo a pista\u00a0 que d\u00e1 acesso ao Vale do Salitre.\u00a0 De acordo informa\u00e7\u00f5es de populares,\u00a0 coletadores encontraram um cad\u00e1ver com marcas de viol\u00eancia, nas&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/27837","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=27837"}],"version-history":[{"count":2,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/27837\/revisions"}],"predecessor-version":[{"id":27840,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/27837\/revisions\/27840"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/27838"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=27837"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=27837"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=27837"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}