{"id":28298,"date":"2021-09-18T11:45:00","date_gmt":"2021-09-18T14:45:00","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=28298"},"modified":"2021-09-18T09:15:24","modified_gmt":"2021-09-18T12:15:24","slug":"mais-sete-casos-da-variante-delta-sao-confirmados-em-pernambuco-que-agora-soma-36","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2021\/09\/18\/mais-sete-casos-da-variante-delta-sao-confirmados-em-pernambuco-que-agora-soma-36","title":{"rendered":"Mais sete casos da variante Delta s\u00e3o confirmados em Pernambuco, que agora soma 36"},"content":{"rendered":"<p style=\"text-align: justify;\">Mais 7\u00a0casos de Covid-19 causados pela variante Delta do novo coronav\u00edrus foram confirmados em Pernambuco. O an\u00fancio foi feito pela\u00a0Secretaria Estadual de Sa\u00fade (SES-PE) no in\u00edcio da noite desta\u00a0sexta-feira (17) ap\u00f3s mais uma rodada do sequenciamento gen\u00e9tico de amostras de pacientes com Covid-19 feito pelo Instituto Aggeu Magalh\u00e3es (IAM\/Fiocruz PE).<\/p>\n<div id=\"ad-middle\" class=\" adRef\" style=\"text-align: justify;\" data-google-query-id=\"CPq2mfS9iPMCFdQmuQYd6UUL0w\">\n<div id=\"google_ads_iframe_\/21867286880\/folhape\/middle_0__container__\"><span style=\"font-size: revert; color: initial;\">Com essas novas confirma\u00e7\u00f5es, Pernambuco totaliza 36 pessoas infectadas pela variante Delta.<\/span><\/div>\n<\/div>\n<p style=\"text-align: justify;\">Das 27 amostras sequenciadas, 20 foram identificadas como linhagem e sublinhagem da variante Gamma (74%), inicialmente detectada no Brasil, e 7 (26%) para a Delta, de pacientes residentes em Exu (1), Camaragibe (1), Petrolina (4) e Primavera (1).<\/p>\n<p>Todos os novos casos da variante Delta foram diagnosticados como leves, mas os munic\u00edpos foram orientados, segundo a SES-PE,\u00a0 a investigar e acompanhar os casos.<\/p>\n<p style=\"text-align: justify;\">Dos 7 pacientes, 4 s\u00e3o do sexo masculino e 3 do sexo feminino, com idades entre 20 e 56 anos. As faixas et\u00e1rias s\u00e3o: 20 a 29 (4), 30 a 39 (2) e 50 a 59 (1).<\/p>\n<div class=\"teads-inread sm-screen\" style=\"text-align: justify;\">\n<div>\n<div class=\"teads-ui-components-adchoices\"><\/div>\n<div class=\"teads-ui-components-label\"><\/div>\n<div id=\"teads0\" class=\"teads-player\"><span style=\"font-size: revert; color: initial;\">Segundo a SES-PE, todas os materiais biol\u00f3gicos foram coletados entre os dias 6 e 27 de agosto nos munic\u00edpios de Exu, Terezinha, Igarassu, Caruaru, Ipojuca, Camaragibe, Sair\u00e9, Petrolina, Primavera e Cabrob\u00f3.\u00a0<\/span><\/div>\n<div><\/div>\n<div><\/div>\n<div class=\"teads-player\"><span style=\"color: initial; font-size: revert;\">A variante Delta \u00e9 da linhagem viral B.1.617, que apareceu na \u00cdndia em outubro de 2020. Segundo estudo divulgado em julho por pesquisadores ligados \u00e0 Organiza\u00e7\u00e3o Mundial da Sa\u00fade e ao Imperial College de Londres, a variante \u00e9 cerca de 97% mais transmiss\u00edvel do que o coronav\u00edrus original identificado na China, sendo assim ainda mais preocupante do que as variantes surgidas no Reino Unido (Alfa), na \u00c1frica do Sul (Beta) e no Brasil (Gama).<\/span><\/div>\n<\/div>\n<\/div>\n<div class=\"dn_noticiasRelacionadas\" style=\"text-align: justify;\">\n<div class=\"clear\"><\/div>\n<div class=\"spacer30\"><strong style=\"font-size: revert; color: initial;\">Balan\u00e7o<\/strong><\/div>\n<\/div>\n<p style=\"text-align: justify;\">Al\u00e9m desses\u00a07 novos casos,\u00a0<a href=\"https:\/\/www.folhape.com.br\/noticias\/pernambuco-confirma-mais-15-casos-de-infeccao-pela-variante-delta-do\/197235\/\">outros 15 casos j\u00e1 haviam sido registrados no \u00faltimo dia 10<\/a>, sendo 14 de pacientes provenientes das cidades pernambucanas de Ara\u00e7oiaba (1), Caruaru (4), Escada (1), Jaboat\u00e3o dos Guararapes (1), Jata\u00faba (2), Quipap\u00e1 (1), Recife (3) e Fernando de Noronha (1), al\u00e9m de 1 paciente\u00a0de outro estado: S\u00e3o Paulo\/Ubatuba (1), turista que foi testado e notificado por Fernando de Noronha.<\/p>\n<p style=\"text-align: justify;\">Ainda em setembro, outros 4 foram confirmados no dia 2:\u00a0pacientes provenientes das cidades de Olinda (1), Ipojuca (1), Caruaru (1) e Araripina (1).<\/p>\n<p>J\u00e1 em 27 de agosto, foram confirmados 8 casos da variante em pessoas residentes em\u00a0Recife (5), Olinda (1), Cabo de Santo Agostinho (1) e Exu (1). Antes disso, no dia 18 de agosto, foram confirmadas 2 amostras com a cepa origin\u00e1ria da \u00cdndia, de residentes de Abreu e Lima (1) e Olinda (1), que adoeceram em julho.<\/p>\n<section class=\"bannerBillboardDetalhe\">\n<div id=\"middle\"><\/div>\n<\/section>\n<div class=\"clear\" style=\"text-align: justify;\"><\/div>\n<div>Por:<strong>\u00a0Portal Folha de Pernambuco<\/strong><\/div>\n<div class=\"spacer30\" style=\"text-align: justify;\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Mais 7\u00a0casos de Covid-19 causados pela variante Delta do novo coronav\u00edrus foram confirmados em Pernambuco. O an\u00fancio foi feito pela\u00a0Secretaria Estadual de Sa\u00fade (SES-PE) no in\u00edcio da noite desta\u00a0sexta-feira (17) ap\u00f3s mais uma rodada do sequenciamento gen\u00e9tico de amostras de pacientes com Covid-19 feito pelo Instituto Aggeu Magalh\u00e3es (IAM\/Fiocruz PE). Com essas novas confirma\u00e7\u00f5es, Pernambuco [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":28305,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1507],"tags":[5337,5336,532,3751],"class_list":["post-28298","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pernambuco","tag-confirmados","tag-mais-sete-casos","tag-pernambuco","tag-variante-delta"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/09\/da36d7a8-1904-4307-aa6e-e383e3abd43e-1.jpg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/09\/da36d7a8-1904-4307-aa6e-e383e3abd43e-1.jpg",500,333,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/09\/da36d7a8-1904-4307-aa6e-e383e3abd43e-1-150x150.jpg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/09\/da36d7a8-1904-4307-aa6e-e383e3abd43e-1-300x200.jpg",300,200,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/09\/da36d7a8-1904-4307-aa6e-e383e3abd43e-1.jpg",500,333,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/09\/da36d7a8-1904-4307-aa6e-e383e3abd43e-1.jpg",500,333,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/09\/da36d7a8-1904-4307-aa6e-e383e3abd43e-1.jpg",500,333,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/09\/da36d7a8-1904-4307-aa6e-e383e3abd43e-1.jpg",500,333,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/09\/da36d7a8-1904-4307-aa6e-e383e3abd43e-1.jpg",500,333,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/09\/da36d7a8-1904-4307-aa6e-e383e3abd43e-1-420x307.jpg",420,307,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/09\/da36d7a8-1904-4307-aa6e-e383e3abd43e-1-300x333.jpg",300,333,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/09\/da36d7a8-1904-4307-aa6e-e383e3abd43e-1-464x290.jpg",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/09\/da36d7a8-1904-4307-aa6e-e383e3abd43e-1.jpg",500,333,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/09\/da36d7a8-1904-4307-aa6e-e383e3abd43e-1-322x230.jpg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/09\/da36d7a8-1904-4307-aa6e-e383e3abd43e-1.jpg",500,333,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"Mais 7\u00a0casos de Covid-19 causados pela variante Delta do novo coronav\u00edrus foram confirmados em Pernambuco. O an\u00fancio foi feito pela\u00a0Secretaria Estadual de Sa\u00fade (SES-PE) no in\u00edcio da noite desta\u00a0sexta-feira (17) ap\u00f3s mais uma rodada do sequenciamento gen\u00e9tico de amostras de pacientes com Covid-19 feito pelo Instituto Aggeu Magalh\u00e3es (IAM\/Fiocruz PE). Com essas novas confirma\u00e7\u00f5es, Pernambuco&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/28298","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=28298"}],"version-history":[{"count":2,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/28298\/revisions"}],"predecessor-version":[{"id":28307,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/28298\/revisions\/28307"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/28305"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=28298"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=28298"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=28298"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}