{"id":29710,"date":"2021-10-28T18:47:00","date_gmt":"2021-10-28T21:47:00","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=29710"},"modified":"2021-10-28T13:38:02","modified_gmt":"2021-10-28T16:38:02","slug":"jovem-de-18-anos-e-morta-por-traficantes-no-planeta-dos-macacos-apos-deixar-amiga-em-casa","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2021\/10\/28\/jovem-de-18-anos-e-morta-por-traficantes-no-planeta-dos-macacos-apos-deixar-amiga-em-casa","title":{"rendered":"Jovem de 18 anos \u00e9 morta por traficantes no Planeta dos Macacos ap\u00f3s deixar amiga em casa"},"content":{"rendered":"<p style=\"text-align: justify;\">Uma jovem de 18 anos foi morta com um tiro na nuca enquanto passava de carro na localidade conhecida como Planeta dos Macacos, em S\u00e3o Crist\u00f3v\u00e3o, na noite de quarta-feira (27). Jamile Sanches Ara\u00fajo estava ao lado dos pais e foi no bairro deixar uma amiga em casa, ap\u00f3s assistirem um filme em um shopping de Salvador.<\/p>\n<p style=\"text-align: justify;\">Segundo o pai da v\u00edtima, dois indiv\u00edduos armados, que aparentavam ser menores de idade, abordaram o carro em que a fam\u00edlia estava e ordenaram que o motorista engatasse a r\u00e9. Mesmo com a luz interna ligada e fazendo o que os traficantes mandaram, mais a frente, um suspeito atirou duas vezes contra o carro.<\/p>\n<p style=\"text-align: justify;\">Jamile foi atingida na cabe\u00e7a e foi socorrida para o hospital, mas n\u00e3o resistiu. Ela era filha \u00fanica. A fam\u00edlia est\u00e1 destro\u00e7ada.<\/p>\n<p style=\"text-align: justify;\">Em entrevista ao Balan\u00e7o Geral nesta quinta-feira (28), o pai de Jamile disse que pelo menos quatro homens participaram da emboscada e ele acredita que apenas o desejo de matar tenha motivado o ataque.<\/p>\n<p style=\"text-align: justify;\">\u201cMinha esposa est\u00e1 muito abalada, minha m\u00e3e devastada, passando mal. Minha filha era uma menina muito querida, todo mundo a amava. Pe\u00e7o ao governador e ao prefeito pra tirar essa gente da rua. N\u00e3o acredito na Justi\u00e7a, acredito em Deus\u201d, destacou o pai.<\/p>\n<p style=\"text-align: justify;\">A m\u00e3e de Jamile lembrou que n\u00e3o deixava a filha sair sozinha, nem para o col\u00e9gio, e cuidava da jovem com todo amor. \u201cMinha filha morreu nos meus bra\u00e7os, ela era tudo na minha vida, me realizava em tudo, era minha parceira. Queria ser veterin\u00e1ria, estudava, era uma menina excelente. Tive minha filha jovem, eduquei, dei muito amor e a perdi dessa forma tr\u00e1gica\u201d, lamentou a mulher.<\/p>\n<p style=\"text-align: justify;\">A delegada Zaira Pimentel, titular da 1\u00aa Delegacia de Homic\u00eddios (DH\/Atl\u00e2ntico), adiantou ao Balan\u00e7o Geral que investigadores est\u00e3o no local do crime coletando imagens e informa\u00e7\u00f5es. Ela pediu que a popula\u00e7\u00e3o ajude com informa\u00e7\u00f5es atrav\u00e9s do Disque Den\u00fancia, pelo n\u00famero 181.<\/p>\n<p>Por: BNws<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma jovem de 18 anos foi morta com um tiro na nuca enquanto passava de carro na localidade conhecida como Planeta dos Macacos, em S\u00e3o Crist\u00f3v\u00e3o, na noite de quarta-feira (27). Jamile Sanches Ara\u00fajo estava ao lado dos pais e foi no bairro deixar uma amiga em casa, ap\u00f3s assistirem um filme em um shopping [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":29711,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[202],"tags":[5912,3765,5913,1965],"class_list":["post-29710","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-policia","tag-jovem-de-18-anos","tag-morta","tag-planeta-dos-macacos","tag-traficantes"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/10\/328415-IMAGEM_NOTICIA_0.jpg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/10\/328415-IMAGEM_NOTICIA_0.jpg",500,246,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/10\/328415-IMAGEM_NOTICIA_0-150x150.jpg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/10\/328415-IMAGEM_NOTICIA_0-300x148.jpg",300,148,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/10\/328415-IMAGEM_NOTICIA_0.jpg",500,246,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/10\/328415-IMAGEM_NOTICIA_0.jpg",500,246,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/10\/328415-IMAGEM_NOTICIA_0.jpg",500,246,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/10\/328415-IMAGEM_NOTICIA_0.jpg",500,246,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/10\/328415-IMAGEM_NOTICIA_0.jpg",500,246,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/10\/328415-IMAGEM_NOTICIA_0-420x246.jpg",420,246,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/10\/328415-IMAGEM_NOTICIA_0-300x246.jpg",300,246,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/10\/328415-IMAGEM_NOTICIA_0-464x246.jpg",464,246,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/10\/328415-IMAGEM_NOTICIA_0.jpg",500,246,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/10\/328415-IMAGEM_NOTICIA_0-322x230.jpg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/10\/328415-IMAGEM_NOTICIA_0.jpg",500,246,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"Uma jovem de 18 anos foi morta com um tiro na nuca enquanto passava de carro na localidade conhecida como Planeta dos Macacos, em S\u00e3o Crist\u00f3v\u00e3o, na noite de quarta-feira (27). Jamile Sanches Ara\u00fajo estava ao lado dos pais e foi no bairro deixar uma amiga em casa, ap\u00f3s assistirem um filme em um shopping&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/29710","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=29710"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/29710\/revisions"}],"predecessor-version":[{"id":29712,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/29710\/revisions\/29712"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/29711"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=29710"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=29710"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=29710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}