{"id":30815,"date":"2021-11-28T07:49:00","date_gmt":"2021-11-28T10:49:00","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=30815"},"modified":"2021-11-27T20:28:24","modified_gmt":"2021-11-27T23:28:24","slug":"brasil-fechara-fronteiras-aereas-para-seis-paises-africanos-devido-a-nova-variante-do-coronavirus","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2021\/11\/28\/brasil-fechara-fronteiras-aereas-para-seis-paises-africanos-devido-a-nova-variante-do-coronavirus","title":{"rendered":"Brasil fechar\u00e1 fronteiras a\u00e9reas para seis pa\u00edses africanos devido \u00e0 nova variante do coronav\u00edrus"},"content":{"rendered":"<p style=\"text-align: justify;\">O PSDB escolheu o nome de\u00a0<a href=\"https:\/\/www.bnews.com.br\/noticias\/politica\/323007,se-eleito-vou-privatizar-a-petrobras-diz-joao-doria-em-campanha-de-previas-para-2022.html\" target=\"_blank\" rel=\"noopener\">Jo\u00e3o D\u00f3ria<\/a>\u00a0como candidato a presidente da Rep\u00fablica em 2022. O resultado da vota\u00e7\u00e3o das pr\u00e9vias foi anunciado pelo presidente nacional do partido, Bruno Ara\u00fajo, na noite deste s\u00e1bado (27). Ele venceu os outros pr\u00e9-candidatos\u00a0<a href=\"https:\/\/www.bnews.com.br\/noticias\/politica\/323856,psdb-da-bahia-anuncia-apoio-a-eduardo-leite-nas-previas-do-partido.html\" target=\"_blank\" rel=\"noopener\">Eduardo Leite<\/a>, governador do Rio Grande do Sul, e\u00a0<a href=\"https:\/\/www.bnews.com.br\/noticias\/politica\/330348,arthur-virgilio-afirma-que-psdb-precisa-recuperar-protagonismo-nacional.html\" target=\"_blank\" rel=\"noopener\">Arthur Virg\u00edlio<\/a>, ex-prefeito de Manaus.<\/p>\n<p style=\"text-align: justify;\">O governador de S\u00e3o Paulo obteve \u00a053,99% dos votos. Leite ficou com 44,66% e Virg\u00edlio, com \u00a01,35%. A vota\u00e7\u00e3o foi conclu\u00edda uma semana ap\u00f3s o\u00a0<a href=\"https:\/\/www.bnews.com.br\/noticias\/politica\/331195,psdb-suspende-votacao-das-previas-apos-problema-com-aplicativo.html\" target=\"_blank\" rel=\"noopener\">problema no aplicativo do PSDB<\/a>, que interrompeu o pleito.<\/p>\n<p style=\"text-align: justify;\">Derrotado, Arthur Virg\u00edlio defendeu o rompimento definitivo do partido com o bolsonarismo e defendeu ainda que Leite seja preparado para ser um eventual sucessor de Doria. &#8220;Vamos preparar o Eduardo para ser o seu sucessor&#8221;, sugeriu.<\/p>\n<p style=\"text-align: justify;\">Ao todo, 979 filiados baianos do PSDB se inscreveram para votar.\u00a0Em setembro, o presidente estadual do PSDB na Bahia, deputado federal\u00a0<a href=\"https:\/\/www.bnews.com.br\/noticias\/politica\/323856,psdb-da-bahia-anuncia-apoio-a-eduardo-leite-nas-previas-do-partido.html\" target=\"_blank\" rel=\"noopener\">Adolfo Viana, anunciou oficialmente o apoio da Executiva Estadual da sigla \u00e0 pr\u00e9-candidatura de Eduardo Leite.<\/a>\u00a0\u00a0<\/p>\n<p style=\"text-align: justify;\">No Brasil, o partido informou que 44,7 mil filiados em todo o Brasil se cadastraram para votar nas pr\u00e9vias. Isso corresponde a 3,4% dos 1,3 milh\u00e3o de pessoas filiadas ao PSDB.<\/p>\n<p>\u00a0<\/p>\n<p>Por:<strong>\u00a0Ag\u00eancia O Globo<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O PSDB escolheu o nome de\u00a0Jo\u00e3o D\u00f3ria\u00a0como candidato a presidente da Rep\u00fablica em 2022. O resultado da vota\u00e7\u00e3o das pr\u00e9vias foi anunciado pelo presidente nacional do partido, Bruno Ara\u00fajo, na noite deste s\u00e1bado (27). Ele venceu os outros pr\u00e9-candidatos\u00a0Eduardo Leite, governador do Rio Grande do Sul, e\u00a0Arthur Virg\u00edlio, ex-prefeito de Manaus. O governador de S\u00e3o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":30816,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[200],"tags":[6486,1479,2764,6487],"class_list":["post-30815","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil","tag-brasil-fechara-fronteiras-aereas","tag-coronavirus","tag-nova-variante","tag-seis-paises-africanos"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/11\/51299238135-842cf471d8-k.jpg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/11\/51299238135-842cf471d8-k.jpg",500,333,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/11\/51299238135-842cf471d8-k-150x150.jpg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/11\/51299238135-842cf471d8-k-300x200.jpg",300,200,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/11\/51299238135-842cf471d8-k.jpg",500,333,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/11\/51299238135-842cf471d8-k.jpg",500,333,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/11\/51299238135-842cf471d8-k.jpg",500,333,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/11\/51299238135-842cf471d8-k.jpg",500,333,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/11\/51299238135-842cf471d8-k.jpg",500,333,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/11\/51299238135-842cf471d8-k-420x307.jpg",420,307,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/11\/51299238135-842cf471d8-k-300x333.jpg",300,333,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/11\/51299238135-842cf471d8-k-464x290.jpg",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/11\/51299238135-842cf471d8-k.jpg",500,333,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/11\/51299238135-842cf471d8-k-322x230.jpg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/11\/51299238135-842cf471d8-k.jpg",500,333,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"O PSDB escolheu o nome de\u00a0Jo\u00e3o D\u00f3ria\u00a0como candidato a presidente da Rep\u00fablica em 2022. O resultado da vota\u00e7\u00e3o das pr\u00e9vias foi anunciado pelo presidente nacional do partido, Bruno Ara\u00fajo, na noite deste s\u00e1bado (27). Ele venceu os outros pr\u00e9-candidatos\u00a0Eduardo Leite, governador do Rio Grande do Sul, e\u00a0Arthur Virg\u00edlio, ex-prefeito de Manaus. O governador de S\u00e3o&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/30815","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=30815"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/30815\/revisions"}],"predecessor-version":[{"id":30817,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/30815\/revisions\/30817"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/30816"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=30815"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=30815"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=30815"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}