{"id":31689,"date":"2021-12-23T08:53:00","date_gmt":"2021-12-23T11:53:00","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=31689"},"modified":"2021-12-22T19:48:19","modified_gmt":"2021-12-22T22:48:19","slug":"defesa-civil-emite-alerta-para-os-proximos-dias-em-juazeiro","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2021\/12\/23\/defesa-civil-emite-alerta-para-os-proximos-dias-em-juazeiro","title":{"rendered":"Defesa Civil emite alerta para os pr\u00f3ximos dias em Juazeiro"},"content":{"rendered":"<p class=\"x_MsoNormal\" style=\"text-align: justify;\">A Defesa Civil de Juazeiro informa a popula\u00e7\u00e3o sobre a possibilidade de chuvas fortes nos pr\u00f3ximos dias. A previs\u00e3o do Instituto Nacional de Meteorologia para os dias 21 e 22 de dezembro \u00e9 de chuvas entre 20 e 50 mm\/h por dia, al\u00e9m de ventos intensos (40-60 km\/h).<\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">O coordenador da Defesa Civil, Ramiro Cordeiro, explica que as equipes da Prefeitura j\u00e1 est\u00e3o de prontid\u00e3o, para uma a\u00e7\u00e3o integrada, caso seja necess\u00e1rio e orienta a popula\u00e7\u00e3o. \u201cEm caso de rajadas de vento, orientamos a popula\u00e7\u00e3o a n\u00e3o se abrigar debaixo de \u00e1rvores, pois h\u00e1 leve risco de queda de \u00e1rvores ou pequenas descargas el\u00e9tricas. Pedimos tamb\u00e9m que n\u00e3o estacionem ve\u00edculos pr\u00f3ximos de torres de transmiss\u00e3o e placas de propaganda e, ainda, que evitem usar aparelhos eletr\u00f4nicos ligados \u00e0 tomada\u201d, alerta o gestor.<\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\"><b>Plant\u00e3o<\/b><\/p>\n<p class=\"x_MsoNormal\" style=\"text-align: justify;\">O trabalho preventivo da Prefeitura de Juazeiro segue em regime de plant\u00e3o para garantir a seguran\u00e7a da popula\u00e7\u00e3o. Em caso de necessidade, a comunidade poder\u00e1 entrar em contato com a Defesa Civil, atrav\u00e9s do telefone (74) 9 9198-1233 (WhatsApp) ou com o Corpo de Bombeiros, por meio do 193.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Defesa Civil de Juazeiro informa a popula\u00e7\u00e3o sobre a possibilidade de chuvas fortes nos pr\u00f3ximos dias. A previs\u00e3o do Instituto Nacional de Meteorologia para os dias 21 e 22 de dezembro \u00e9 de chuvas entre 20 e 50 mm\/h por dia, al\u00e9m de ventos intensos (40-60 km\/h). O coordenador da Defesa Civil, Ramiro Cordeiro, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":19766,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[203],"tags":[],"class_list":["post-31689","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-juazeiro"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/Chuva18.02.jpeg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/Chuva18.02.jpeg",500,288,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/Chuva18.02-150x150.jpeg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/Chuva18.02-300x173.jpeg",300,173,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/Chuva18.02.jpeg",500,288,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/Chuva18.02.jpeg",500,288,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/Chuva18.02.jpeg",500,288,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/Chuva18.02.jpeg",500,288,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/Chuva18.02.jpeg",500,288,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/Chuva18.02-420x288.jpeg",420,288,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/Chuva18.02-300x288.jpeg",300,288,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/Chuva18.02-464x288.jpeg",464,288,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/Chuva18.02.jpeg",500,288,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/Chuva18.02-322x230.jpeg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/02\/Chuva18.02.jpeg",500,288,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"A Defesa Civil de Juazeiro informa a popula\u00e7\u00e3o sobre a possibilidade de chuvas fortes nos pr\u00f3ximos dias. A previs\u00e3o do Instituto Nacional de Meteorologia para os dias 21 e 22 de dezembro \u00e9 de chuvas entre 20 e 50 mm\/h por dia, al\u00e9m de ventos intensos (40-60 km\/h). O coordenador da Defesa Civil, Ramiro Cordeiro,&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/31689","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=31689"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/31689\/revisions"}],"predecessor-version":[{"id":31690,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/31689\/revisions\/31690"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/19766"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=31689"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=31689"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=31689"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}