{"id":31842,"date":"2021-12-26T18:44:00","date_gmt":"2021-12-26T21:44:00","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=31842"},"modified":"2021-12-26T11:25:03","modified_gmt":"2021-12-26T14:25:03","slug":"parceria-entre-ministerio-e-unesco-premiara-projetos-de-biodiversidade","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2021\/12\/26\/parceria-entre-ministerio-e-unesco-premiara-projetos-de-biodiversidade","title":{"rendered":"Parceria entre minist\u00e9rio e Unesco premiar\u00e1 projetos de biodiversidade"},"content":{"rendered":"<p style=\"text-align: justify;\">O Minist\u00e9rio da Ci\u00eancia, Tecnologia e Inova\u00e7\u00f5es anunciou nesta semana o lan\u00e7amento de uma competi\u00e7\u00e3o para estimular o uso sustent\u00e1vel da<strong>&nbsp;biodiversidade no Brasil<\/strong>. Chamada de Pr\u00eamio MCTI\/Finep de Biodiversidade, a iniciativa conta com a parceria da Organiza\u00e7\u00e3o das Na\u00e7\u00f5es Unidas para a Educa\u00e7\u00e3o, a Ci\u00eancia e a Cultura (Unesco), da Financiadora de Estudos e Projetos (Finep), do Conselho Nacional de Desenvolvimento Cient\u00edfico e Tecnol\u00f3gico (CNPq) e da Rede de Ensino e Pesquisa (RNP).<\/p>\n<div class=\"teads-inread sm-screen\" style=\"text-align: justify;\">\n<div>\n<div class=\"teads-ui-components-label\">&nbsp;<\/div>\n<div id=\"teads0\" class=\"teads-player\"><span style=\"font-size: revert; color: initial;\">Segundo comunicado da pasta, a premia\u00e7\u00e3o ter\u00e1 duas categorias: produ\u00e7\u00e3o acad\u00eamica e&nbsp; desenvolvimento tecnol\u00f3gico e inova\u00e7\u00e3o. A primeira ser\u00e1 destinada a estudantes e pesquisadores de todos os n\u00edveis que produzam pesquisas cient\u00edficas envolvendo a explora\u00e7\u00e3o econ\u00f4mica sustent\u00e1vel da biodiversidade. A segunda \u00e9 voltada para a sociedade civil em geral e premiar\u00e1 cidad\u00e3os da sociedade civil em geral, mesmo fora do ambiente universit\u00e1rio e de pesquisa, que apresentem a\u00e7\u00f5es pr\u00e1ticas e projetos com foco no mesmo tema, a explora\u00e7\u00e3o econ\u00f4mica sustent\u00e1vel.<\/span><\/div>\n<div>&nbsp;<\/div>\n<\/div>\n<\/div>\n<div id=\"ad-middle\" class=\" adRef\" style=\"text-align: justify;\" data-google-query-id=\"CIqu3_7PgfUCFdYJuQYdg4gCEg\">\n<div id=\"google_ads_iframe_\/21867286880\/folhape\/middle_0__container__\"><span style=\"font-size: revert; color: initial;\">A<\/span><strong style=\"font-size: revert; color: initial;\">&nbsp;premia\u00e7\u00e3o<\/strong><span style=\"font-size: revert; color: initial;\">&nbsp;\u00e9 a mesma para ambas as categorias. O primeiro lugar em cada uma receber\u00e1 R$ 15 mil; o segundo lugar receber\u00e1 R$ 7 mil e o terceiro lugar ser\u00e1 premiado com R$ 3 mil.<\/span><\/div>\n<\/div>\n<p style=\"text-align: justify;\">\u201cPara n\u00f3s \u00e9 uma grande satisfa\u00e7\u00e3o participar desta premia\u00e7\u00e3o. A Unesco tem tradicionalmente apoiado diversas iniciativas que reconhe\u00e7am boas pr\u00e1ticas ligadas \u00e0 ci\u00eancia, tecnologia, biodiversidade no pa\u00eds\u201d, disse o coordenador de Ci\u00eancias Humanas e Sociais e Ci\u00eancias Naturais da Unesco, F\u00e1bio Leon, durante o evento de lan\u00e7amento do pr\u00eamio.<\/p>\n<p style=\"text-align: justify;\">As inscri\u00e7\u00f5es para ambas as categorias do Pr\u00eamio MCTI\/Finep de Biodiversidade j\u00e1 est\u00e3o abertas, e receber\u00e3o cadastros de interessados at\u00e9 4 de mar\u00e7o de 2022. O resultado final do concurso ser\u00e1 publicado em 19 de abril de 2022.&nbsp;As inscri\u00e7\u00f5es podem ser feitas aqui.<\/p>\n<p style=\"text-align: justify;\"><strong>Biodiversidade<\/strong><\/p>\n<p style=\"text-align: justify;\">Classificado como mega-diverso, o Brasil \u00e9 o habitat natural de cerca de&nbsp;<strong>46 mil esp\u00e9cies de plantas<\/strong>, mais de mil variedades de anf\u00edbios e cerca de 750 mam\u00edferos &#8211; n\u00fameros que representam algo em torno de 10 a 20% da biodiversidade mundial. Todas as esp\u00e9cies brasileiras, tanto da fauna quanto da flora, s\u00e3o catalogadas no Sistema de Informa\u00e7\u00e3o sobre a Biodiversidade Brasileira (SiBBR) &#8211; plataforma digital gerida pelo MCTI que organiza e&nbsp;armazena&nbsp;esp\u00e9cies brasileiras e que serve de base para pesquisadores e entidades.<\/p>\n<p>Por:Ag\u00eancia Brasil<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Minist\u00e9rio da Ci\u00eancia, Tecnologia e Inova\u00e7\u00f5es anunciou nesta semana o lan\u00e7amento de uma competi\u00e7\u00e3o para estimular o uso sustent\u00e1vel da&nbsp;biodiversidade no Brasil. Chamada de Pr\u00eamio MCTI\/Finep de Biodiversidade, a iniciativa conta com a parceria da Organiza\u00e7\u00e3o das Na\u00e7\u00f5es Unidas para a Educa\u00e7\u00e3o, a Ci\u00eancia e a Cultura (Unesco), da Financiadora de Estudos e Projetos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":31843,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[3372],"tags":[6939,6937,1514,6938],"class_list":["post-31842","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-meio-ambiente","tag-biodiversidade","tag-ministerio-e-unesco","tag-parceria","tag-premiara-projetos"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/12\/949854-16082149364-5fd2943b2b-o.jpg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/12\/949854-16082149364-5fd2943b2b-o.jpg",500,298,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/12\/949854-16082149364-5fd2943b2b-o-150x150.jpg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/12\/949854-16082149364-5fd2943b2b-o-300x179.jpg",300,179,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/12\/949854-16082149364-5fd2943b2b-o.jpg",500,298,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/12\/949854-16082149364-5fd2943b2b-o.jpg",500,298,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/12\/949854-16082149364-5fd2943b2b-o.jpg",500,298,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/12\/949854-16082149364-5fd2943b2b-o.jpg",500,298,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/12\/949854-16082149364-5fd2943b2b-o.jpg",500,298,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/12\/949854-16082149364-5fd2943b2b-o-420x298.jpg",420,298,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/12\/949854-16082149364-5fd2943b2b-o-300x298.jpg",300,298,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/12\/949854-16082149364-5fd2943b2b-o-464x290.jpg",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/12\/949854-16082149364-5fd2943b2b-o.jpg",500,298,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/12\/949854-16082149364-5fd2943b2b-o-322x230.jpg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/12\/949854-16082149364-5fd2943b2b-o.jpg",500,298,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"O Minist\u00e9rio da Ci\u00eancia, Tecnologia e Inova\u00e7\u00f5es anunciou nesta semana o lan\u00e7amento de uma competi\u00e7\u00e3o para estimular o uso sustent\u00e1vel da&nbsp;biodiversidade no Brasil. Chamada de Pr\u00eamio MCTI\/Finep de Biodiversidade, a iniciativa conta com a parceria da Organiza\u00e7\u00e3o das Na\u00e7\u00f5es Unidas para a Educa\u00e7\u00e3o, a Ci\u00eancia e a Cultura (Unesco), da Financiadora de Estudos e Projetos&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/31842","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=31842"}],"version-history":[{"count":2,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/31842\/revisions"}],"predecessor-version":[{"id":31848,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/31842\/revisions\/31848"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/31843"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=31842"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=31842"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=31842"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}