{"id":32597,"date":"2022-01-15T16:38:02","date_gmt":"2022-01-15T19:38:02","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=32597"},"modified":"2022-01-15T16:38:07","modified_gmt":"2022-01-15T19:38:07","slug":"golpe-dos-nudes-criminosos-criam-ate-delegacia-fake-para-exigir-dinheiro-de-vitimas","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2022\/01\/15\/golpe-dos-nudes-criminosos-criam-ate-delegacia-fake-para-exigir-dinheiro-de-vitimas","title":{"rendered":"Golpe dos nudes: criminosos criam at\u00e9 delegacia fake para exigir dinheiro de v\u00edtimas"},"content":{"rendered":"<p>O\u00a0<a href=\"https:\/\/g1.globo.com\/fantastico\/\">Fant\u00e1stico<\/a>\u00a0mostra v\u00eddeos e \u00e1udios de criminosos que aplicam o golpe dos nudes. Eles fingem ser pais e m\u00e3es de menores de idade. Inventaram at\u00e9 uma delegacia fake. Tudo para exigir dinheiro de homens que acreditavam ter trocado fotos sensuais com as supostas jovens.<\/p>\n<div class=\"mc-column content-text active-extra-styles\" data-block-type=\"raw\" data-block-weight=\"57\" data-block-id=\"4\">\n<blockquote class=\"content-blockquote theme-border-color-primary-before\"><p>Um homem troca mensagens apaixonadas e nudes com uma jovem que ele conheceu na internet. At\u00e9 que um dia, ele recebe este v\u00eddeo: \u201cPeguei o telefone da minha filha e vi essas porcaria aqui. O que\u00a0<em>tu\u00a0<\/em>est\u00e1 pensando, seu ped\u00f3filo, seu doente? Minha menina tem 13 anos. \u00c9 s\u00f3 uma crian\u00e7a.\u00a0<em>Tu t\u00e1<\/em>\u00a0louco da cabe\u00e7a?\u201d.<\/p><\/blockquote>\n<\/div>\n<div class=\"content-ads content-ads--reveal\" data-block-type=\"ads\" data-block-id=\"5\">\n<div class=\"tag-manager-publicidade-container mc-has-reveal mc-has-ad-lazyload\" data-id=\"banner_materia2\">\u00a0<\/div>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles\" data-block-type=\"raw\" data-block-weight=\"38\" data-block-id=\"6\">\n<p class=\"content-text__container\">\u00a0<\/p>\n<blockquote class=\"content-blockquote theme-border-color-primary-before\"><p>A mulher amea\u00e7a: \u201cIsso n\u00e3o vai ficar assim. Eu vou na delegacia, vou registrar uma ocorr\u00eancia contra\u00a0<em>tu<\/em>. Vou mandar o delegado te prender. Seu doente, seu ped\u00f3filo. Sem vergonha. Onde j\u00e1 se viu fazer uma coisa dessa\u201d.<\/p><\/blockquote>\n<p>\u00a0<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"26\" data-block-id=\"7\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\"><span class=\"highlight highlighted\">A mulher que aparece na reportagem n\u00e3o \u00e9 m\u00e3e de ningu\u00e9m. A tal filha, menor de idade, simplesmente n\u00e3o existe. O perfil na internet era falso<\/span>.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"32\" data-block-id=\"8\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">Os criminosos agiam principalmente no Rio Grande do Sul.\u00a0<span class=\"highlight highlighted\">Depois do primeiro v\u00eddeo com as amea\u00e7as, eles tamb\u00e9m costumavam mandar mensagens de \u00e1udio, se passando por pais ou parentes da suposta menina.<\/span><\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"43\" data-block-id=\"9\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\"><span class=\"highlight highlighted\">Os golpistas mentem que a menor estaria traumatizada, precisando de psic\u00f3logo. A quadrilha exige dinheiro para o tratamento e para n\u00e3o levar o caso \u00e0 pol\u00edcia<\/span>. Alguns homens d\u00e3o o dinheiro j\u00e1 neste momento. Outros homens desconfiam, n\u00e3o caem na extors\u00e3o de imediato.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"43\" data-block-id=\"10\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\"><span class=\"highlight highlighted\">Para pressionar os homens que acreditavam ter trocado nudes com uma menor, os criminosos foram al\u00e9m: criaram o cen\u00e1rio de uma delegacia de mentira, com at\u00e9 dois falsos policiais de figurantes<\/span>. Tudo para a atua\u00e7\u00e3o da golpista no papel de uma m\u00e3e desesperada.<\/p>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"21\" data-block-id=\"11\">\n<p class=\"content-text__container \" data-track-category=\"Link no Texto\" data-track-links=\"\">A pol\u00edcia diz que os v\u00eddeos produzidos pelos criminosos ga\u00fachos vazaram na internet e foram usados por quadrilhas de outros estados.<\/p>\n<p>Confira a mat\u00e9ria completa<\/p>\n<\/div>\n<div class=\"content-ads content-ads--reveal\" data-block-type=\"ads\" data-block-id=\"12\">\n<div class=\"tag-manager-publicidade-container mc-has-reveal mc-has-ad-lazyload\" data-id=\"banner_materia__a1c9d19f-5b57-4c21-b9fa-22210971845b\">\u00a0<\/div>\n<\/div>\n<div class=\"mc-column content-text active-extra-styles \" data-block-type=\"unstyled\" data-block-weight=\"7\" data-block-id=\"13\">\u00a0<\/div><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O\u00a0Fant\u00e1stico\u00a0mostra v\u00eddeos e \u00e1udios de criminosos que aplicam o golpe dos nudes. Eles fingem ser pais e m\u00e3es de menores de idade. Inventaram at\u00e9 uma delegacia fake. Tudo para exigir dinheiro de homens que acreditavam ter trocado fotos sensuais com as supostas jovens. Um homem troca mensagens apaixonadas e nudes com uma jovem que ele [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":32598,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[210,202],"tags":[],"class_list":["post-32597","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-justica","category-policia"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/01\/5cd8fc95-af12-4bd6-8447-afa0e7b6a753.jpg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/01\/5cd8fc95-af12-4bd6-8447-afa0e7b6a753.jpg",1280,719,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/01\/5cd8fc95-af12-4bd6-8447-afa0e7b6a753-150x150.jpg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/01\/5cd8fc95-af12-4bd6-8447-afa0e7b6a753-300x169.jpg",300,169,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/01\/5cd8fc95-af12-4bd6-8447-afa0e7b6a753-768x431.jpg",640,359,true],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/01\/5cd8fc95-af12-4bd6-8447-afa0e7b6a753-1024x575.jpg",640,359,true],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/01\/5cd8fc95-af12-4bd6-8447-afa0e7b6a753.jpg",1280,719,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/01\/5cd8fc95-af12-4bd6-8447-afa0e7b6a753.jpg",1280,719,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/01\/5cd8fc95-af12-4bd6-8447-afa0e7b6a753-1020x719.jpg",1020,719,true],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/01\/5cd8fc95-af12-4bd6-8447-afa0e7b6a753-420x307.jpg",420,307,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/01\/5cd8fc95-af12-4bd6-8447-afa0e7b6a753-300x443.jpg",300,443,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/01\/5cd8fc95-af12-4bd6-8447-afa0e7b6a753-464x290.jpg",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/01\/5cd8fc95-af12-4bd6-8447-afa0e7b6a753-600x500.jpg",600,500,true],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/01\/5cd8fc95-af12-4bd6-8447-afa0e7b6a753-322x230.jpg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/01\/5cd8fc95-af12-4bd6-8447-afa0e7b6a753-1210x642.jpg",1210,642,true]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"O\u00a0Fant\u00e1stico\u00a0mostra v\u00eddeos e \u00e1udios de criminosos que aplicam o golpe dos nudes. Eles fingem ser pais e m\u00e3es de menores de idade. Inventaram at\u00e9 uma delegacia fake. Tudo para exigir dinheiro de homens que acreditavam ter trocado fotos sensuais com as supostas jovens. Um homem troca mensagens apaixonadas e nudes com uma jovem que ele&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/32597","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=32597"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/32597\/revisions"}],"predecessor-version":[{"id":32599,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/32597\/revisions\/32599"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/32598"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=32597"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=32597"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=32597"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}