{"id":32651,"date":"2022-01-17T14:10:00","date_gmt":"2022-01-17T17:10:00","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=32651"},"modified":"2022-01-17T14:06:22","modified_gmt":"2022-01-17T17:06:22","slug":"acidente-com-vitima-fatal-na-ba-210-em-juazeiro","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2022\/01\/17\/acidente-com-vitima-fatal-na-ba-210-em-juazeiro","title":{"rendered":"Acidente com v\u00edtima fatal na BA-210, em Juazeiro"},"content":{"rendered":"<p style=\"background: white; vertical-align: baseline; margin: 0cm 0cm 11.25pt; text-align: justify;\"><span style=\"font-size: 11.0pt; font-family: 'Arial','sans-serif'; color: #424242;\">Na noite desse domingo (16), um grave acidente na BA-210, sentido do bairro Tabuleiro, em Juazeiro (BA), deixou uma pessoa morta. Em imagens que circulam pelas redes sociais, \u00e9 poss\u00edvel ver que se trata de um carro preto, que ficou muito avariado ap\u00f3s o acidente.<\/span><\/p>\n<p style=\"background: white; vertical-align: baseline; box-sizing: inherit; border-spacing: 0px; font-variant-ligatures: normal; font-variant-caps: normal; font-variant-numeric: inherit; font-variant-east-asian: inherit; font-stretch: inherit; line-height: inherit; orphans: 2; widows: 2; -webkit-text-stroke-width: 0px; text-decoration-thickness: initial; text-decoration-style: initial; text-decoration-color: initial; word-spacing: 0px; margin: 0cm 0cm 11.25pt; text-align: justify;\"><span style=\"font-size: 11.0pt; font-family: 'Arial','sans-serif'; color: #424242;\">Ainda n\u00e3o h\u00e1 informa\u00e7\u00f5es oficiais sobre o que motivou o acidente e a identidade da v\u00edtima.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na noite desse domingo (16), um grave acidente na BA-210, sentido do bairro Tabuleiro, em Juazeiro (BA), deixou uma pessoa morta. Em imagens que circulam pelas redes sociais, \u00e9 poss\u00edvel ver que se trata de um carro preto, que ficou muito avariado ap\u00f3s o acidente. Ainda n\u00e3o h\u00e1 informa\u00e7\u00f5es oficiais sobre o que motivou o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":32652,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[203],"tags":[920,4525,143,1751],"class_list":["post-32651","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-juazeiro","tag-acidente","tag-ba-210-2","tag-juazeiro-da-bahia","tag-vitima-fatal"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/01\/acidentenovajuazeiro.jpg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/01\/acidentenovajuazeiro.jpg",500,400,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/01\/acidentenovajuazeiro-150x150.jpg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/01\/acidentenovajuazeiro-300x240.jpg",300,240,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/01\/acidentenovajuazeiro.jpg",500,400,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/01\/acidentenovajuazeiro.jpg",500,400,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/01\/acidentenovajuazeiro.jpg",500,400,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/01\/acidentenovajuazeiro.jpg",500,400,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/01\/acidentenovajuazeiro.jpg",500,400,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/01\/acidentenovajuazeiro-420x307.jpg",420,307,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/01\/acidentenovajuazeiro-300x400.jpg",300,400,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/01\/acidentenovajuazeiro-464x290.jpg",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/01\/acidentenovajuazeiro.jpg",500,400,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/01\/acidentenovajuazeiro-322x230.jpg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/01\/acidentenovajuazeiro.jpg",500,400,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"Na noite desse domingo (16), um grave acidente na BA-210, sentido do bairro Tabuleiro, em Juazeiro (BA), deixou uma pessoa morta. Em imagens que circulam pelas redes sociais, \u00e9 poss\u00edvel ver que se trata de um carro preto, que ficou muito avariado ap\u00f3s o acidente. Ainda n\u00e3o h\u00e1 informa\u00e7\u00f5es oficiais sobre o que motivou o&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/32651","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=32651"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/32651\/revisions"}],"predecessor-version":[{"id":32653,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/32651\/revisions\/32653"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/32652"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=32651"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=32651"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=32651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}