{"id":33647,"date":"2022-02-10T09:29:00","date_gmt":"2022-02-10T12:29:00","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=33647"},"modified":"2022-02-09T07:32:24","modified_gmt":"2022-02-09T10:32:24","slug":"centrao-nunca-saiu-do-poder-e-e-preciso-mudar-isso-diz-ciro-gomes","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2022\/02\/10\/centrao-nunca-saiu-do-poder-e-e-preciso-mudar-isso-diz-ciro-gomes","title":{"rendered":"Centr\u00e3o nunca saiu do poder e \u00e9 preciso mudar isso, diz Ciro Gomes"},"content":{"rendered":"<p>O pr\u00e9-candidato \u00e0 Presid\u00eancia da Rep\u00fablica\u00a0<a href=\"https:\/\/www.cnnbrasil.com.br\/tudo-sobre\/ciro-gomes\/\">Ciro Gomes (PDT)<\/a>\u00a0declarou nesta quarta-feira (26), em entrevista \u00e0\u00a0<strong>CNN<\/strong>, que \u00e9 necess\u00e1rio mudar a maneira que se governa o Brasil com o n\u00facleo de partidos conhecido como Centr\u00e3o.<\/p>\n<p>Ciro afirma que as legendas nunca deixaram o governo federal em mais de 30 anos, desde o governo de\u00a0<a href=\"https:\/\/www.cnnbrasil.com.br\/tudo-sobre\/fernando-collor\/\">Fernando Collor de Mello (PROS)<\/a>, eleito em 1989. Elas passaram pelos governos de\u00a0<a href=\"https:\/\/www.cnnbrasil.com.br\/tudo-sobre\/fernando-henrique-cardoso\/\">Fernando Henrique Cardoso (PSDB)<\/a>, de\u00a0<a href=\"https:\/\/www.cnnbrasil.com.br\/tudo-sobre\/luiz-inacio-lula-da-silva\/\">Luiz In\u00e1cio Lula da Silva (PT)<\/a>\u00a0e continuam com o atual presidente\u00a0<a href=\"https:\/\/www.cnnbrasil.com.br\/tudo-sobre\/jair-bolsonaro\/\">Jair Bolsonaro (PL).<\/a><\/p>\n<p>\u201cE a necessidade que o Brasil tem de mudar o modelo econ\u00f4mico que se trata de emprego, sal\u00e1rio, juros do credi\u00e1rio, pre\u00e7o de petr\u00f3leo, de combust\u00edvel, do g\u00e1s de cozinha. E o modelo de governan\u00e7a pol\u00edtica, em que muda tudo para esse tal Centr\u00e3o nunca sair do poder. Estavam com Fernando Henrique, com Collor, com Lula e agora est\u00e3o fazendo a desgra\u00e7a do Brasil de novo com o Bolsonaro. \u00c9 preciso mudar isso\u201d, alega Ciro.<\/p>\n<p>O ex-governador do Cear\u00e1 avalia que seu insucesso nas elei\u00e7\u00f5es presidenciais anteriores, em 1998, quando ficou em terceiro lugar, em 2002, no quarto lugar e em 2018, novamente em terceiro, mostram \u201cuma evid\u00eancia a mais\u201d de sua sorte.<\/p>\n<p>Desta vez, ele diz que est\u00e1 \u201cmais maduro, pronto, com um projeto melhor acabado para o Brasil\u201d para as elei\u00e7\u00f5es de 2022.<\/p>\n<p>Caso seja eleito, Ciro expressa que ir\u00e1 governar \u201ccom quem o povo eleger\u201d. Ele ainda manifesta que ir\u00e1 abrir m\u00e3o da sua pr\u00f3pria reelei\u00e7\u00e3o \u201cpara dar ao pa\u00eds as reformas que n\u00f3s precisamos e n\u00e3o podemos mais adiar. N\u00e3o acho que com isso terei muito sucesso e vou me reeleger\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O pr\u00e9-candidato \u00e0 Presid\u00eancia da Rep\u00fablica\u00a0Ciro Gomes (PDT)\u00a0declarou nesta quarta-feira (26), em entrevista \u00e0\u00a0CNN, que \u00e9 necess\u00e1rio mudar a maneira que se governa o Brasil com o n\u00facleo de partidos conhecido como Centr\u00e3o. Ciro afirma que as legendas nunca deixaram o governo federal em mais de 30 anos, desde o governo de\u00a0Fernando Collor de Mello [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":33156,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[200,197],"tags":[],"class_list":["post-33647","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil","category-politica"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/01\/ciro-2.png","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/01\/ciro-2.png",500,350,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/01\/ciro-2-150x150.png",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/01\/ciro-2-300x210.png",300,210,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/01\/ciro-2.png",500,350,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/01\/ciro-2.png",500,350,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/01\/ciro-2.png",500,350,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/01\/ciro-2.png",500,350,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/01\/ciro-2.png",500,350,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/01\/ciro-2-420x307.png",420,307,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/01\/ciro-2-300x350.png",300,350,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/01\/ciro-2-464x290.png",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/01\/ciro-2.png",500,350,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/01\/ciro-2-322x230.png",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/01\/ciro-2.png",500,350,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"O pr\u00e9-candidato \u00e0 Presid\u00eancia da Rep\u00fablica\u00a0Ciro Gomes (PDT)\u00a0declarou nesta quarta-feira (26), em entrevista \u00e0\u00a0CNN, que \u00e9 necess\u00e1rio mudar a maneira que se governa o Brasil com o n\u00facleo de partidos conhecido como Centr\u00e3o. Ciro afirma que as legendas nunca deixaram o governo federal em mais de 30 anos, desde o governo de\u00a0Fernando Collor de Mello&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/33647","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=33647"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/33647\/revisions"}],"predecessor-version":[{"id":33648,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/33647\/revisions\/33648"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/33156"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=33647"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=33647"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=33647"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}