{"id":35023,"date":"2022-03-19T12:42:00","date_gmt":"2022-03-19T15:42:00","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=35023"},"modified":"2022-03-19T09:52:19","modified_gmt":"2022-03-19T12:52:19","slug":"parceria-da-prefeitura-de-juazeiro-com-empresa-de-energia-solar-garantira-construcao-e-requalificacao-de-duas-pracas-no-rodeadouro-e-em-juremal","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2022\/03\/19\/parceria-da-prefeitura-de-juazeiro-com-empresa-de-energia-solar-garantira-construcao-e-requalificacao-de-duas-pracas-no-rodeadouro-e-em-juremal","title":{"rendered":"Parceria da Prefeitura de Juazeiro com empresa de energia solar garantir\u00e1 constru\u00e7\u00e3o e requalifica\u00e7\u00e3o de duas pra\u00e7as no Rodeadouro e em Juremal"},"content":{"rendered":"<p style=\"font-weight: 400; text-align: justify;\">Os moradores da comunidade do Rodeadouro e do distrito de Juremal, zona rural de Juazeiro, ser\u00e3o beneficiados com a constru\u00e7\u00e3o e requalifica\u00e7\u00e3o de duas pra\u00e7as. A assinatura da ordem de servi\u00e7o aconteceu nesta sexta-feira (18) e \u00e9 resultado da celebra\u00e7\u00e3o de um termo de compromisso ambiental firmado entre a Atlas Renewable Energy (empresa de gera\u00e7\u00e3o de energia solar) e a Prefeitura de Juazeiro, atrav\u00e9s da Secretaria de Meio Ambiente e Ordenamento Urbano (Semaurb).<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">O evento contou com a presen\u00e7a da prefeita Suzana Ramos, do diretor de Desenvolvimento de Neg\u00f3cios da Atlas, Manoel de Andrade Lira Neto; do gerente de Desenvolvimento da Atlas, Danilo Mesquita; do secret\u00e1rio de Meio Ambiente e Ordenamento Urbano, Rubens Torres; do assessor jur\u00eddico, Adriano Ara\u00fajo; al\u00e9m da equipe t\u00e9cnica da Semaurb.<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">A prefeita Suzana Ramos enalteceu a parceria firmada com a empresa Atlas Renewable Energy. \u201cAcho de grande import\u00e2ncia essa parceria do munic\u00edpio, atrav\u00e9s da Semaurb e da Atlas. A constru\u00e7\u00e3o da pra\u00e7a na comunidade do Rodeadouro ir\u00e1 embelezar aquele importante ponto tur\u00edstico e a revitaliza\u00e7\u00e3o da pra\u00e7a que j\u00e1 existe no distrito de Juremal vai proporcionar mais bem-estar para os moradores da comunidade. \u00c9 uma parceria que j\u00e1 deu certo e espero que outras parcerias possam beneficiar outras localidades do nosso munic\u00edpio\u201d, disse a gestora.<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">\n<p style=\"font-weight: 400; text-align: justify;\"><strong>Projeto sustent\u00e1vel<\/strong><\/p>\n<p style=\"text-align: justify;\">\n<p style=\"font-weight: 400; text-align: justify;\">De acordo com os representantes da empresa Atlas, as pra\u00e7as contempladas atender\u00e3o ao projeto de equipamentos sustent\u00e1veis, obedecendo \u00e0s normas ambientais.<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">\u201cEsse termo de compromisso ambiental confirma nosso compromisso e nossa boa rela\u00e7\u00e3o com o munic\u00edpio para viabilizar a implanta\u00e7\u00e3o das duas pra\u00e7as. Os locais escolhidos t\u00eam uma certa car\u00eancia de alguns investimentos. Com a assinatura da ordem de servi\u00e7o daremos in\u00edcio e seguimento \u00e0s atividades. A ideia n\u00e3o \u00e9 apenas construir pra\u00e7as, mas sim trazer para esses equipamentos um olhar integrado para a sustentabilidade. O munic\u00edpio tem inten\u00e7\u00e3o de fazer algumas atividades de educa\u00e7\u00e3o ambiental nesses espa\u00e7os e implementar equipamentos que remetam a sustentabilidade, a conserva\u00e7\u00e3o, o cuidado com os res\u00edduos s\u00f3lidos e incentivem a conscientiza\u00e7\u00e3o da popula\u00e7\u00e3o sobre impactos ambientais\u201d, frisou o gerente de desenvolvimento da Atlas Renewable Energy, Danilo Mesquita.<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">\n<p style=\"font-weight: 400; text-align: justify;\"><strong>Execu\u00e7\u00e3o e fiscaliza\u00e7\u00e3o<\/strong><\/p>\n<p style=\"font-weight: 400; text-align: justify;\">\n<p style=\"font-weight: 400; text-align: justify;\">As obras das duas pra\u00e7as ser\u00e3o executadas por uma empresa contratada pela Atlas e ser\u00e3o acompanhadas e fiscalizadas pela Secretaria de Meio Ambiente e Ordenamento Urbano. \u201c\u00c9 com muita alegria e satisfa\u00e7\u00e3o que a gest\u00e3o municipal assina essa ordem de servi\u00e7o e termo de compromisso ambiental com a Atlas Renewable Energy. A Semaurb ir\u00e1 acompanhar junto com a empresa a execu\u00e7\u00e3o da obra dessas duas pra\u00e7as que ser\u00e3o ambientalmente sustent\u00e1veis e ir\u00e3o beneficiar diretamente os moradores das comunidades do Rodeadouro e Juremal\u201d, pontuou o titular da Semaurb, Rubens Torres.<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">\n<p style=\"font-weight: 400; text-align: justify;\"><strong>Compromisso social<\/strong><\/p>\n<p style=\"font-weight: 400; text-align: justify;\">\n<p style=\"font-weight: 400; text-align: justify;\">Para o Diretor de Desenvolvimento de Neg\u00f3cios da Atlas Renewable Energy, Manoel de Andrade Lira Neto, a parceria visa o desenvolvimento econ\u00f4mico e social do munic\u00edpio. \u201cHoje uma das nossas principais bandeiras que a gente encampa sempre nos nossos projetos \u00e9 o cuidado no treinamento das pessoas, o incentivo \u00e0 m\u00e3o de obra feminina, \u00e0 equidade de g\u00eanero, \u00e0s melhores condi\u00e7\u00f5es de trabalho, para que a gente possa realmente entregar para a sociedade empreendimentos cada vez mais sustent\u00e1veis\u201d, concluiu.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"font-weight: 400; text-align: justify;\">Ascom\/Semaurb\/PMJ<\/p>\n<p style=\"font-weight: 400; text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>Os moradores da comunidade do Rodeadouro e do distrito de Juremal, zona rural de Juazeiro, ser\u00e3o beneficiados com a constru\u00e7\u00e3o e requalifica\u00e7\u00e3o de duas pra\u00e7as. A assinatura da ordem de servi\u00e7o aconteceu nesta sexta-feira (18) e \u00e9 resultado da celebra\u00e7\u00e3o de um termo de compromisso ambiental firmado entre a Atlas Renewable Energy (empresa de gera\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":35024,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[203],"tags":[8322,8323,1514,340,8324],"class_list":["post-35023","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-juazeiro","tag-empresa-de-energia-solar","tag-garantira-construcao","tag-parceria","tag-prefeitura-de-juazeiro","tag-requalificacao-de-pracas"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/03\/Assinatura-ordem-de-servico-Praca-Atlas-29.jpg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/03\/Assinatura-ordem-de-servico-Praca-Atlas-29.jpg",500,333,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/03\/Assinatura-ordem-de-servico-Praca-Atlas-29-150x150.jpg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/03\/Assinatura-ordem-de-servico-Praca-Atlas-29-300x200.jpg",300,200,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/03\/Assinatura-ordem-de-servico-Praca-Atlas-29.jpg",500,333,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/03\/Assinatura-ordem-de-servico-Praca-Atlas-29.jpg",500,333,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/03\/Assinatura-ordem-de-servico-Praca-Atlas-29.jpg",500,333,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/03\/Assinatura-ordem-de-servico-Praca-Atlas-29.jpg",500,333,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/03\/Assinatura-ordem-de-servico-Praca-Atlas-29.jpg",500,333,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/03\/Assinatura-ordem-de-servico-Praca-Atlas-29-420x307.jpg",420,307,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/03\/Assinatura-ordem-de-servico-Praca-Atlas-29-300x333.jpg",300,333,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/03\/Assinatura-ordem-de-servico-Praca-Atlas-29-464x290.jpg",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/03\/Assinatura-ordem-de-servico-Praca-Atlas-29.jpg",500,333,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/03\/Assinatura-ordem-de-servico-Praca-Atlas-29-322x230.jpg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/03\/Assinatura-ordem-de-servico-Praca-Atlas-29.jpg",500,333,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"Os moradores da comunidade do Rodeadouro e do distrito de Juremal, zona rural de Juazeiro, ser\u00e3o beneficiados com a constru\u00e7\u00e3o e requalifica\u00e7\u00e3o de duas pra\u00e7as. A assinatura da ordem de servi\u00e7o aconteceu nesta sexta-feira (18) e \u00e9 resultado da celebra\u00e7\u00e3o de um termo de compromisso ambiental firmado entre a Atlas Renewable Energy (empresa de gera\u00e7\u00e3o&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/35023","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=35023"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/35023\/revisions"}],"predecessor-version":[{"id":35025,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/35023\/revisions\/35025"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/35024"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=35023"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=35023"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=35023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}