{"id":35174,"date":"2022-03-24T08:43:00","date_gmt":"2022-03-24T11:43:00","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=35174"},"modified":"2022-03-24T08:21:38","modified_gmt":"2022-03-24T11:21:38","slug":"temporal-deixa-mais-de-500-pessoas-desalojadas-em-camaragibe-duas-pessoas-morreram","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2022\/03\/24\/temporal-deixa-mais-de-500-pessoas-desalojadas-em-camaragibe-duas-pessoas-morreram","title":{"rendered":"Temporal deixa mais de 500 pessoas desalojadas em Camaragibe; duas pessoas morreram"},"content":{"rendered":"<p style=\"text-align: justify;\">Cidade mais afetada pelo\u00a0<a href=\"https:\/\/www.folhape.com.br\/noticias\/chuva-provoca-pontos-de-alagamento-e-transtornos-na-rmr-veja-maiores\/220408\/\" target=\"_blank\" rel=\"noopener\"><strong>temporal que caiu em Pernambuco<\/strong><\/a>\u00a0entre segunda-feira (21) e ter\u00e7a-feira (22), Camaragibe, na Regi\u00e3o Metropolitana do Recife, teve\u00a0<strong>duas mortes e mais de 500 pessoas desalojadas<\/strong>, conforme divulgou a Defesa Civil do Estado (Codecipe), nesta quarta-feira (23).<\/p>\n<div class=\"teads-inread sm-screen\" style=\"text-align: justify;\">\n<div class=\"teads-ui-components-label\"><span style=\"color: initial; font-size: revert;\">Segundo a Codecipe, t\u00e9cnicos estiveram reunidos com a Prefeitura de Camaragibe e a Defesa Civil municipal, na tarde de ter\u00e7a-feira, para <\/span><strong style=\"color: initial; font-size: revert;\">prestar apoio<\/strong><span style=\"color: initial; font-size: revert;\">\u00a0com orienta\u00e7\u00f5es quanto ao atendimento \u00e0s fam\u00edlias afetadas pelas chuvas na cidade.<\/span><\/div>\n<\/div>\n<div id=\"supertag-ad-8vkx3hd0r\" style=\"text-align: justify;\" data-google-query-id=\"CPbMnYTP3vYCFVkFuQYdP98FBg\">\n<div id=\"google_ads_iframe_\/21830119956,88816410\/folhape.com.br\/D2_MOB_INTERNA_BF_0__container__\"><\/div>\n<\/div>\n<div class=\"dn_noticiasRelacionadas\" style=\"text-align: justify;\">\n<div class=\"spacer30\"><span style=\"font-size: revert; color: initial;\">O balan\u00e7o da Codecipe indica 501 pessoas desalojadas e a morte de duas pessoas. O primeiro \u00f3bito foi do jovem de 16 anos Felipe Salvador Dias, <\/span><a style=\"font-size: revert;\" href=\"https:\/\/www.folhape.com.br\/noticias\/adolescente-morre-em-camaragibe-durante-as-fortes-chuvas-registradas\/220478\/\" target=\"_blank\" rel=\"noopener\"><strong>encontrado sem vida em um c\u00f3rrego no centro da cidade<\/strong><\/a><span style=\"font-size: revert; color: initial;\">.<\/span><\/div>\n<\/div>\n<p style=\"text-align: justify;\">A segunda morte registrada foi de Nivaldo Pedro Salviano da Silva, de 55 anos,\u00a0<a href=\"https:\/\/www.folhape.com.br\/noticias\/deslizamento-de-barreira-em-camaragibe-deixa-uma-pessoa-morta\/220538\/\" target=\"_blank\" rel=\"noopener\"><strong>soterrado ap\u00f3s um deslizamento de barreira<\/strong><\/a>\u00a0no bairro de C\u00e9u Azul.<\/p>\n<p style=\"text-align: justify;\">&#8220;A Defesa Civil adverte que as pessoas continuem evitando \u00e1reas alagadas, banhos de rios e c\u00f3rregos, e que os moradores de morros e encostas continuem atentos e deixem imediatamente o local em caso de movimenta\u00e7\u00f5es de terras, e procurem a Defesa Civil do munic\u00edpio para apoio e orienta\u00e7\u00f5es&#8221;, informou a Codecipe, em comunicado oficial.<\/p>\n<p style=\"text-align: justify;\">A Central de Opera\u00e7\u00f5es da Codecipe mant\u00e9m plant\u00e3o 24 horas por dia e pode ser acionada pelos telefones\u00a0<strong>199<\/strong>\u00a0e\u00a0<strong>3181-2490<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Em Camaragibe, a Defesa Civil pode ser chamada pelos contatos\u00a0<strong>153<\/strong>,\u00a0<strong>(81) 9.9945-3015<\/strong>\u00a0e\u00a0<strong>(81) 2129-9564<\/strong>.<\/p>\n<p style=\"text-align: justify;\"><strong>Previs\u00e3o da Apac<\/strong><br \/>\nDe acordo com a previs\u00e3o da Ag\u00eancia Pernambucana de \u00c1guas e Clima (Apac),\u00a0<a href=\"https:\/\/www.folhape.com.br\/noticias\/apac-renova-alerta-de-chuvas-para-as-proximas-24-horas\/220374\/\" target=\"_blank\" rel=\"noopener\"><strong>o alerta de chuvas foi reduzido de moderada a forte para moderada<\/strong><\/a>\u00a0e vale, a princ\u00edpio, at\u00e9 12h01 desta quarta-feira.<\/p>\n<p style=\"text-align: justify;\">O aviso abrange a Regi\u00e3o Metropolitana do Recife e a Mata Sul.<\/p>\n<p style=\"text-align: justify;\">\n<section class=\"bannerBillboardDetalhe\">\n<div id=\"middle\"><\/div>\n<\/section>\n<div class=\"clear\" style=\"text-align: justify;\">Por:<strong>\u00a0Portal Folha de Pernambuco<\/strong><\/div>\n<div class=\"spacer30\" style=\"text-align: justify;\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Cidade mais afetada pelo\u00a0temporal que caiu em Pernambuco\u00a0entre segunda-feira (21) e ter\u00e7a-feira (22), Camaragibe, na Regi\u00e3o Metropolitana do Recife, teve\u00a0duas mortes e mais de 500 pessoas desalojadas, conforme divulgou a Defesa Civil do Estado (Codecipe), nesta quarta-feira (23). Segundo a Codecipe, t\u00e9cnicos estiveram reunidos com a Prefeitura de Camaragibe e a Defesa Civil municipal, na [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":35175,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1507],"tags":[8414,8444,8445,6052],"class_list":["post-35174","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pernambuco","tag-camaragibe","tag-deixa-mais-de-500-pessoas-desalojadas","tag-duas-pessoas-morreram","tag-temporal"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/03\/camaragibe-2.jpg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/03\/camaragibe-2.jpg",500,333,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/03\/camaragibe-2-150x150.jpg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/03\/camaragibe-2-300x200.jpg",300,200,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/03\/camaragibe-2.jpg",500,333,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/03\/camaragibe-2.jpg",500,333,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/03\/camaragibe-2.jpg",500,333,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/03\/camaragibe-2.jpg",500,333,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/03\/camaragibe-2.jpg",500,333,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/03\/camaragibe-2-420x307.jpg",420,307,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/03\/camaragibe-2-300x333.jpg",300,333,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/03\/camaragibe-2-464x290.jpg",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/03\/camaragibe-2.jpg",500,333,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/03\/camaragibe-2-322x230.jpg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/03\/camaragibe-2.jpg",500,333,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"Cidade mais afetada pelo\u00a0temporal que caiu em Pernambuco\u00a0entre segunda-feira (21) e ter\u00e7a-feira (22), Camaragibe, na Regi\u00e3o Metropolitana do Recife, teve\u00a0duas mortes e mais de 500 pessoas desalojadas, conforme divulgou a Defesa Civil do Estado (Codecipe), nesta quarta-feira (23). Segundo a Codecipe, t\u00e9cnicos estiveram reunidos com a Prefeitura de Camaragibe e a Defesa Civil municipal, na&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/35174","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=35174"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/35174\/revisions"}],"predecessor-version":[{"id":35176,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/35174\/revisions\/35176"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/35175"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=35174"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=35174"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=35174"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}