{"id":35356,"date":"2022-03-29T13:40:00","date_gmt":"2022-03-29T16:40:00","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=35356"},"modified":"2022-03-29T09:50:33","modified_gmt":"2022-03-29T12:50:33","slug":"atraves-do-programa-aprova-juazeiro-cerca-de-40-alunos-conseguiram-ingressar-na-universidade-em-2021","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2022\/03\/29\/atraves-do-programa-aprova-juazeiro-cerca-de-40-alunos-conseguiram-ingressar-na-universidade-em-2021","title":{"rendered":"Atrav\u00e9s do Programa Aprova Juazeiro, cerca de 40 alunos conseguiram ingressar na universidade em 2021"},"content":{"rendered":"<p style=\"text-align: justify;\">\u201cO programa foi uma pe\u00e7a fundamental para eu alcan\u00e7ar o meu objetivo de cursar Psicologia&#8221;, conta Ra\u00edssa Tayn\u00e1 Ribeiro, ex-aluna do programa Aprova Juazeiro, que atrav\u00e9s do Exame Nacional do Ensino M\u00e9dio (Enem), conseguiu a aprova\u00e7\u00e3o em Psicologia na Universidade Federal do Vale do S\u00e3o Francisco (Univasf), curso e institui\u00e7\u00e3o que sempre desejou ingressar.<\/p>\n<p>Organizado pela Prefeitura Municipal de Juazeiro, atrav\u00e9s da Secretaria de Educa\u00e7\u00e3o e Juventude (Seduc), o programa tem como objetivo garantir aos alunos e egressos da rede p\u00fablica estadual, bolsas de estudo integrais em cursos pr\u00e9-vestibulares gerando mais oportunidade no acesso \u00e0s universidades.<\/p>\n<p>Apesar de as atividades terem acontecido de forma remota, em 2021 o programa foi um sucesso. Dos 120 alunos que passaram pelo projeto, at\u00e9 o momento cerca de 40 foram aprovados em institui\u00e7\u00f5es de n\u00edvel superior pelo pa\u00eds, em cursos como Medicina, Psicologia, Engenharia El\u00e9trica, Ci\u00eancias Sociais, Jornalismo, Administra\u00e7\u00e3o, entre outros.<\/p>\n<p>\u201cO projeto promove maior acesso ao aprendizado para jovens que buscam entrar na universidade, atuando de maneira inclusiva. Sou grata pela oportunidade de ter participado do Aprova. Projetos como esse s\u00e3o essenciais para que jovens, como eu, possam ter acesso \u00e0 educa\u00e7\u00e3o de qualidade e mais oportunidades futuras\u201d, relata a estudante Ra\u00edssa.<\/p>\n<p><b>O Aprova Juazeiro em 2022<\/b><\/p>\n<p>Este ano o intuito \u00e9 obter um resultado ainda maior no n\u00famero de aprovados, e para alcan\u00e7ar esse objetivo o programa ofertou um aumento de aproximadamente 75% no quantitativo de vagas.<\/p>\n<p>O gerente de Juventude da Seduc, Rhavi Dias, ressalta a import\u00e2ncia do programa como agente de transforma\u00e7\u00e3o social, gerando mais oportunidade de educa\u00e7\u00e3o para os estudantes. \u201cVejo o programa como uma enorme ferramenta de inclus\u00e3o e transforma\u00e7\u00e3o social. S\u00e3o alunos da rede p\u00fablica ganhando a oportunidade de ter a melhor prepara\u00e7\u00e3o poss\u00edvel para realizar seus sonhos e ingressar em institui\u00e7\u00f5es de n\u00edvel superior por todo o pa\u00eds. Para este ano, a ideia \u00e9 fazer o maior Aprova desde a sua cria\u00e7\u00e3o e estamos trabalhando fortemente no acompanhamento dos alunos\u201d, exp\u00f5e o gerente.<\/p>\n<p>Neste s\u00e1bado, dia 2 de abril, acontecer\u00e1 o evento de abertura para os contemplados no programa em 2022.<\/p>\n<p style=\"text-align: justify;\">Ascom PMJ<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cO programa foi uma pe\u00e7a fundamental para eu alcan\u00e7ar o meu objetivo de cursar Psicologia&#8221;, conta Ra\u00edssa Tayn\u00e1 Ribeiro, ex-aluna do programa Aprova Juazeiro, que atrav\u00e9s do Exame Nacional do Ensino M\u00e9dio (Enem), conseguiu a aprova\u00e7\u00e3o em Psicologia na Universidade Federal do Vale do S\u00e3o Francisco (Univasf), curso e institui\u00e7\u00e3o que sempre desejou ingressar. Organizado [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":35357,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[203],"tags":[3580,8577,8578,8579],"class_list":["post-35356","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-juazeiro","tag-aprova-juazeiro","tag-atraves-do-programa","tag-cerca-de-40-alunos","tag-ingressam-na-universidade-em-2021"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/03\/Aprova-Juazeiro.jpeg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/03\/Aprova-Juazeiro.jpeg",500,333,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/03\/Aprova-Juazeiro-150x150.jpeg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/03\/Aprova-Juazeiro-300x200.jpeg",300,200,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/03\/Aprova-Juazeiro.jpeg",500,333,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/03\/Aprova-Juazeiro.jpeg",500,333,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/03\/Aprova-Juazeiro.jpeg",500,333,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/03\/Aprova-Juazeiro.jpeg",500,333,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/03\/Aprova-Juazeiro.jpeg",500,333,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/03\/Aprova-Juazeiro-420x307.jpeg",420,307,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/03\/Aprova-Juazeiro-300x333.jpeg",300,333,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/03\/Aprova-Juazeiro-464x290.jpeg",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/03\/Aprova-Juazeiro.jpeg",500,333,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/03\/Aprova-Juazeiro-322x230.jpeg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/03\/Aprova-Juazeiro.jpeg",500,333,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"\u201cO programa foi uma pe\u00e7a fundamental para eu alcan\u00e7ar o meu objetivo de cursar Psicologia&#8221;, conta Ra\u00edssa Tayn\u00e1 Ribeiro, ex-aluna do programa Aprova Juazeiro, que atrav\u00e9s do Exame Nacional do Ensino M\u00e9dio (Enem), conseguiu a aprova\u00e7\u00e3o em Psicologia na Universidade Federal do Vale do S\u00e3o Francisco (Univasf), curso e institui\u00e7\u00e3o que sempre desejou ingressar. Organizado&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/35356","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=35356"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/35356\/revisions"}],"predecessor-version":[{"id":35358,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/35356\/revisions\/35358"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/35357"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=35356"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=35356"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=35356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}