{"id":3574,"date":"2019-10-02T09:00:08","date_gmt":"2019-10-02T12:00:08","guid":{"rendered":"http:\/\/blogopara.com.br\/?p=3574"},"modified":"2019-10-02T09:00:21","modified_gmt":"2019-10-02T12:00:21","slug":"no-dia-do-idoso-brasil-ainda-falha-em-melhorarias-para-essa-populacao","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2019\/10\/02\/no-dia-do-idoso-brasil-ainda-falha-em-melhorarias-para-essa-populacao","title":{"rendered":"No Dia do Idoso, Brasil ainda falha em melhorarias para essa popula\u00e7\u00e3o"},"content":{"rendered":"<p class=\" \" style=\"text-align: justify;\">O Instituto Brasileiro de Geografia e Estat\u00edstica (IBGE) afirma que, at\u00e9 2060, a popula\u00e7\u00e3o brasileira com 80 anos ou mais dever\u00e1 ser representada por 19 milh\u00f5es de pessoas. A expectativa de vida no Brasil se estende a cada ano, por\u00e9m ainda falta respaldo do governo e da sociedade em geral para se preparar para essa situa\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\">No Dia Internacional do <strong>Idoso<\/strong> , comemorado neste domingo (1\u00ba), o desafio do Brasil \u00e9 duplo: al\u00e9m de promover a valoriza\u00e7\u00e3o das pessoas mais velhas, \u00e9 preciso garantir pol\u00edticas para que elas envelhe\u00e7am com qualidade.<\/p>\n<p style=\"text-align: justify;\">Segundo o vice-presidente do Conselho Nacional da Pessoa Idosa (CNDPI), Bahij Amin Auh a mudan\u00e7a deve come\u00e7ar com educa\u00e7\u00e3o. \u201cO Brasil conquistou a vit\u00f3ria de aumentar a longevidade da sua popula\u00e7\u00e3o. Hoje, vive-se mais \u2013 a m\u00e9dia de expectativa de vida da popula\u00e7\u00e3o brasileira \u00e9 de mais de 75 anos. Agora, \u00e9 preciso um amplo programa educacional, para que toda a popula\u00e7\u00e3o tenha no\u00e7\u00f5es b\u00e1sicas sobre o processo de envelhecimento, para que valorize e respeite a pessoa idosa\u201d.<\/p>\n<p style=\"text-align: justify;\">Hoje, j\u00e1 h\u00e1 previs\u00e3o legal, inclusive no Estatuto do Idoso, de 2003, para que os sistemas escolares trabalhem conte\u00fados sobre esse tema, mas, segundo Auh, isso n\u00e3o tem sido feito. Representante da Ordem dos Advogados do Brasil (OAB), ele diz ainda que a promo\u00e7\u00e3o dessa valoriza\u00e7\u00e3o passa pela garantia de mais informa\u00e7\u00f5es para os idosos acerca dos seus pr\u00f3prios direitos.<\/p>\n<p style=\"text-align: justify;\">Outro problema que o pa\u00eds precisa enfrentar \u00e9 o aumento a oferta de pol\u00edticas p\u00fablicas que garantam que a popula\u00e7\u00e3o idosa envelhe\u00e7a de forma ativa. \u201cN\u00e3o adianta um corpo vivo. \u00c9 preciso que a mente e as rela\u00e7\u00f5es das pessoas idosas estejam em atividade\u201d, afirma. Uma das quest\u00f5es mais relevantes para ele \u00e9 a pol\u00edtica de acolhimento. Diante de mudan\u00e7as nas configura\u00e7\u00f5es sociais, muitos idosos passaram a ficar sem companhia em casa e sem receber os cuidados necess\u00e1rios, conversar ou contar com o apoio da fam\u00edlia para desenvolver atividades.<\/p>\n<h3 style=\"text-align: justify;\">Pol\u00edticas de acolhimento<\/h3>\n<p style=\"text-align: justify;\">De acordo com dados do Sistema \u00danico de Assist\u00eancia Social (Suas), h\u00e1, no Brasil, 1.669 institui\u00e7\u00f5es de acolhimento de idosos. Muitas pessoas conhecem apenas as institui\u00e7\u00f5es de longa perman\u00eancia, conhecidas popularmente como asilos. N\u00e3o obstante, existem outros modelos em funcionamento no pa\u00eds, como os centros de conviv\u00eancia, onde idosos que t\u00eam autonomia praticam atividades recreativas e aprendem novos of\u00edcios, e os chamados centros-dia, que em geral recebem pessoas que precisam receber algum tipo de atendimento terap\u00eautico.<\/p>\n<p style=\"text-align: justify;\">Tais op\u00e7\u00f5es ainda s\u00e3o restritas e est\u00e3o concentradas em grandes centros urbanos, mas podem ser sa\u00eddas para a situa\u00e7\u00e3o vivenciada por muitos idosos que n\u00e3o t\u00eam companhia e tamb\u00e9m para os membros de fam\u00edlias que precisam ou desejam trabalhar fora de casa, mas t\u00eam responsabilidades com os mais velhos.<\/p>\n<p style=\"text-align: justify;\">Atualmente, cerca de 60 mil pessoas usam os diferentes servi\u00e7os de acolhimento existentes, informa a coordenadora-geral de Servi\u00e7os de Acolhimento do Minist\u00e9rio do Desenvolvimento Social, Nilzarete de Lima. Apesar de o n\u00famero ser expressivo, ela diz que ainda h\u00e1 desconhecimento sobre os servi\u00e7os e tamb\u00e9m preconceitos. \u201c\u00c9 muito presente a ideia de que as pessoas acolhidas nessas institui\u00e7\u00f5es s\u00e3o aquelas que n\u00e3o t\u00eam mais fam\u00edlia e que, por isso, o atendimento dado n\u00e3o \u00e9 adequado e n\u00e3o respeita a individualidade delas\u201d.<\/p>\n<p style=\"text-align: justify;\">Nilzarete reconhece, contudo, que problemas existem, e diz que tem buscado super\u00e1-los. Um problema central \u00e9 a diversidade de padr\u00f5es adotados nas institui\u00e7\u00f5es, o que est\u00e1 relacionado ao fato de 70% a 80% delas serem ligadas a institui\u00e7\u00f5es filantr\u00f3picas ou outros tipos de organiza\u00e7\u00f5es da sociedade civil, explica Nilzarete. O governo federal participa dessa pol\u00edtica por meio do cofinanciamento das a\u00e7\u00f5es e do estabelecimento de regras de funcionamento.<\/p>\n<p style=\"text-align: justify;\">Nos \u00faltimos anos, o governo atua para reordenar a presta\u00e7\u00e3o dos servi\u00e7os. Superando a antiga concep\u00e7\u00e3o assistencialista rumo \u00e0 afirma\u00e7\u00e3o da assist\u00eancia social como direito, diz Nilzarete, \u201ca gente vem trabalhando com uma pol\u00edtica de inclus\u00e3o dos idosos \u00e0 comunidade e de reordenamento dessas unidades, para que seja adotada uma nova vis\u00e3o, como pol\u00edtica de Estado, de direito e de prote\u00e7\u00e3o social\u201d. Em vez de um lugar onde os idosos s\u00e3o abandonados ou de um hospital permanente, ela prop\u00f5e que as institui\u00e7\u00f5es sejam a casas dessas pessoas e ofere\u00e7am atendimento humanizado.<\/p>\n<p style=\"text-align: justify;\">Para promover essa vis\u00e3o, ela ressalta que o Minist\u00e9rio do Desenvolvimento Social participa de uma c\u00e2mara t\u00e9cnica que, junto com outras pastas, conselhos de direitos e organiza\u00e7\u00f5es da sociedade civil, objetiva estudar a rede existente e propor esse reordenamento. Financiamento, estrutura dos locais e caracter\u00edsticas dos servi\u00e7os ofertados s\u00e3o algumas das quest\u00f5es analisadas. \u201cQueremos que as fam\u00edlias tenham a seguran\u00e7a de que v\u00e3o deixar algu\u00e9m no servi\u00e7o de atendimento, mesmo o tempor\u00e1rio, e de que esse parente vai ser cuidado\u201d, afirma.<\/p>\n<pre><strong>Fonte: <a href=\"https:\/\/ultimosegundo.ig.com.br\/brasil\/2017-10-01\/idoso-politicas-publicas.html\">\u00daltimo Segundo - iG<\/a> <\/strong><\/pre>\n","protected":false},"excerpt":{"rendered":"<p>O Instituto Brasileiro de Geografia e Estat\u00edstica (IBGE) afirma que, at\u00e9 2060, a popula\u00e7\u00e3o brasileira com 80 anos ou mais dever\u00e1 ser representada por 19 milh\u00f5es de pessoas. A expectativa de vida no Brasil se estende a cada ano, por\u00e9m ainda falta respaldo do governo e da sociedade em geral para se preparar para essa [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3582,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[200,203],"tags":[880,879,881],"class_list":["post-3574","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil","category-juazeiro","tag-dia-do-idoso","tag-idoso","tag-politica-publica"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2019\/10\/idosos-4.jpg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2019\/10\/idosos-4.jpg",1140,760,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2019\/10\/idosos-4-150x150.jpg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2019\/10\/idosos-4-300x200.jpg",300,200,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2019\/10\/idosos-4-768x512.jpg",640,427,true],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2019\/10\/idosos-4-1024x683.jpg",640,427,true],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2019\/10\/idosos-4.jpg",1140,760,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2019\/10\/idosos-4.jpg",1140,760,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2019\/10\/idosos-4.jpg",1020,680,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2019\/10\/idosos-4.jpg",420,280,false],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2019\/10\/idosos-4.jpg",300,200,false],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2019\/10\/idosos-4.jpg",435,290,false],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2019\/10\/idosos-4.jpg",600,400,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2019\/10\/idosos-4.jpg",322,215,false],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2019\/10\/idosos-4.jpg",963,642,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"O Instituto Brasileiro de Geografia e Estat\u00edstica (IBGE) afirma que, at\u00e9 2060, a popula\u00e7\u00e3o brasileira com 80 anos ou mais dever\u00e1 ser representada por 19 milh\u00f5es de pessoas. A expectativa de vida no Brasil se estende a cada ano, por\u00e9m ainda falta respaldo do governo e da sociedade em geral para se preparar para essa&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3574","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=3574"}],"version-history":[{"count":2,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3574\/revisions"}],"predecessor-version":[{"id":3577,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3574\/revisions\/3577"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/3582"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=3574"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=3574"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=3574"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}