{"id":36576,"date":"2022-05-01T14:57:00","date_gmt":"2022-05-01T17:57:00","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=36576"},"modified":"2022-05-01T09:16:46","modified_gmt":"2022-05-01T12:16:46","slug":"projeto-deus-visita-sua-casa-inicia-mais-uma-acao-com-a-mentoria-do-vereador-berg-da-carnaiba","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2022\/05\/01\/projeto-deus-visita-sua-casa-inicia-mais-uma-acao-com-a-mentoria-do-vereador-berg-da-carnaiba","title":{"rendered":"Projeto Deus Visita sua Casa inicia mais uma a\u00e7\u00e3o com a mentoria do vereador Berg da Carna\u00edba"},"content":{"rendered":"<p style=\"text-align: justify;\">Aos 54 anos de idade, dona Lourdes Raimunda dos Santos, conhecida na comunidade como dona Lurdinha, est\u00e1 realizando o seu maior sonho: a casa pr\u00f3pria.O vereador de Juazeiro, Berg da Carna\u00edba, que h\u00e1 mais de seis anos, lidera o Projeto Deus Visita sua Casa junto com os amigos do grupo Volunt\u00e1rios do Bem, est\u00e1 mais uma vez colocando as m\u00e3os na massa para levantar o teto dela, que passou a vida inteira se sacrificando para pagar o aluguel onde reside com seu filho.<\/p>\n<p style=\"text-align: justify;\">\nVi\u00fava, nascida e criada no Distrito de Massaroca, dona Lourdes conta que passa por perrengue para manter a fam\u00edlia.<br \/>\nDesempregada e com a pens\u00e3o de uma neta para pagar, ela diz que os dias t\u00eam sido dif\u00edceis e muitos deles enfrenta com a f\u00e9 e a perseveran\u00e7a, mas sem perspectiva de dias melhores. \u201cDeus h\u00e1 de continuar aben\u00e7oando Berg para que ele ajude cada vez mais pessoas. Ele \u00e9 um homem iluminado e merece toda nossa ora\u00e7\u00e3o por sempre estar disposto a ajudar as fam\u00edlias que mais precisam. Estou muito emocionada de ver ele e sua equipe levantando a minha casa. \u00c9 um momento de muita gratid\u00e3o a Deus e a Berg\u201d, agradece ao vereador.<\/p>\n<p style=\"text-align: justify;\">\nDona Lourdes \u00e9 mais uma cidad\u00e3 juazeirense contemplada com o Projeto do vereador que j\u00e1 construiu mais de 50 casas para fam\u00edlias carentes no munic\u00edpio. Obra que Berg da Carna\u00edba define como miss\u00e3o determinada por Deus. \u201cN\u00e3o me canso de lutar em favor de quem mais precisa, coloco Deus na frente, arrega\u00e7o as mangas e junto com os amigos, me dedico inteiramente ao trabalho de ajudar o pr\u00f3ximo. Minha felicidade \u00e9 ver o sorriso de gratid\u00e3o e alegria das pessoas que por alguma raz\u00e3o perderam a esperan\u00e7a e n\u00f3s devolvemos essa vontade de viver e de preservar para estas pessoas\u201d, relata emocionado Berg da Carna\u00edba.<\/p>\n<p style=\"text-align: justify;\">\nAs obras de constru\u00e7\u00e3o da casa de dona Lourdes come\u00e7aram neste s\u00e1bado (30), e continuar\u00e3o para sua conclus\u00e3o. O projeto continua realizando sonhos dos juazeirenses que vivem em situa\u00e7\u00e3o vulner\u00e1vel.<\/p>\n<p style=\"text-align: justify;\">\nM\u00f4nia Ramos Jornalista<br \/>\nASCOM<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aos 54 anos de idade, dona Lourdes Raimunda dos Santos, conhecida na comunidade como dona Lurdinha, est\u00e1 realizando o seu maior sonho: a casa pr\u00f3pria.O vereador de Juazeiro, Berg da Carna\u00edba, que h\u00e1 mais de seis anos, lidera o Projeto Deus Visita sua Casa junto com os amigos do grupo Volunt\u00e1rios do Bem, est\u00e1 mais [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":36577,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[218],"tags":[9263,9264,9262,2536],"class_list":["post-36576","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-carnaiba","tag-inicia-mais-uma-acao","tag-mentoria","tag-projeto-deus-visita-sua-casa","tag-vereador-berg-da-carnaiba"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-04-30-at-19.32.30.jpeg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-04-30-at-19.32.30.jpeg",500,666,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-04-30-at-19.32.30-150x150.jpeg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-04-30-at-19.32.30-225x300.jpeg",225,300,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-04-30-at-19.32.30.jpeg",500,666,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-04-30-at-19.32.30.jpeg",500,666,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-04-30-at-19.32.30.jpeg",500,666,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-04-30-at-19.32.30.jpeg",500,666,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-04-30-at-19.32.30.jpeg",500,666,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-04-30-at-19.32.30-420x307.jpeg",420,307,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-04-30-at-19.32.30-300x443.jpeg",300,443,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-04-30-at-19.32.30-464x290.jpeg",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-04-30-at-19.32.30-500x500.jpeg",500,500,true],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-04-30-at-19.32.30-322x230.jpeg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-04-30-at-19.32.30-500x642.jpeg",500,642,true]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"Aos 54 anos de idade, dona Lourdes Raimunda dos Santos, conhecida na comunidade como dona Lurdinha, est\u00e1 realizando o seu maior sonho: a casa pr\u00f3pria.O vereador de Juazeiro, Berg da Carna\u00edba, que h\u00e1 mais de seis anos, lidera o Projeto Deus Visita sua Casa junto com os amigos do grupo Volunt\u00e1rios do Bem, est\u00e1 mais&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/36576","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=36576"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/36576\/revisions"}],"predecessor-version":[{"id":36578,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/36576\/revisions\/36578"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/36577"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=36576"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=36576"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=36576"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}