{"id":36783,"date":"2022-05-06T08:48:00","date_gmt":"2022-05-06T11:48:00","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=36783"},"modified":"2022-05-06T08:09:52","modified_gmt":"2022-05-06T11:09:52","slug":"menino-de-11-anos-relata-tortura-e-e-resgatado-em-sp-pais-sao-procurados","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2022\/05\/06\/menino-de-11-anos-relata-tortura-e-e-resgatado-em-sp-pais-sao-procurados","title":{"rendered":"Menino de 11 anos relata tortura e \u00e9 resgatado em SP; pais s\u00e3o procurados"},"content":{"rendered":"<p style=\"text-align: justify;\">Um menino de 11 anos foi encontrado por vizinhos com sinais de tortura e maus-tratos, em Itu (SP). A suspeita \u00e9 de que ele sofria viol\u00eancia f\u00edsica e psicol\u00f3gica praticada pelos pais h\u00e1 pelo menos cinco anos. O casal teve a pris\u00e3o preventiva decretada e est\u00e1 foragido.<\/p>\n<p>O Conselho Tutelar afirma que recebeu a den\u00fancia sobre as agress\u00f5es na segunda-feira (2) e foi at\u00e9 o local indicado para resgatar a crian\u00e7a. O menino conseguiu fugir da resid\u00eancia dos pais e relatou as agress\u00f5es sofridas para um amigo, depois que o pai teria amea\u00e7ado de &#8220;cortar os seus dedos&#8221; com um fac\u00e3o. O fato teria acontecido depois que o garoto pediu R$ 4 para comprar p\u00e3o-de-queijo, o que teria desagradado o homem. O colega em quest\u00e3o comunicou o caso a moradores vizinhos.<\/p>\n<p>A crian\u00e7a teria relatado \u00e0s pessoas que o encontraram que sofria agress\u00f5es f\u00edsicas, psicol\u00f3gicas e at\u00e9 mesmo priva\u00e7\u00e3o alimentar na casa onde morava com os pais, no bairro Vila da Paz.<\/p>\n<p>As agress\u00f5es, segundo o menino, come\u00e7aram quando ele tinha 7 anos e eram realizadas de v\u00e1rias maneiras como enforcamento com fio, golpe de fac\u00e3o no corpo, tapas e socos. O menino relatou que chegou at\u00e9 mesmo a ser atingido por \u00e1gua de bateria de carro na cabe\u00e7a.<\/p>\n<div class=\"d-flex justify-content-center my-3\" style=\"text-align: justify;\">\n<div id=\"banner-300x250-1-area\" data-desktop=\"300x250\" data-mobile=\"320x50\" data-google-query-id=\"CLr0rd_cyvcCFQMwuQYdyAcA8w\">\n<div id=\"google_ads_iframe_\/8804\/parceiros\/bnews_0__container__\"><span style=\"font-size: revert; color: initial;\">Ainda segundo o relato da crian\u00e7a, para que vizinhos n\u00e3o ouvissem os seus gritos e choro, o pai o levava para uma \u00e1rea onde tinha uma casa abandonada e l\u00e1 ocorriam as agress\u00f5es. Ele disse ainda que tinha medo de os pais serem presos e ele ser encaminhado a um abrigo, por isso n\u00e3o os denunciava.<\/span><\/div>\n<\/div>\n<\/div>\n<p style=\"text-align: justify;\">O menino foi acolhido pelo Conselho Tutelar e est\u00e1 sob a tutela do estado. Ele fez exame de corpo de delito no Instituto M\u00e9dico Legal (IML) de Sorocaba (SP) para avaliar os ferimentos.<\/p>\n<p>Segundo a Pol\u00edcia Civil, o pedido de pris\u00e3o preventiva dos pais foi qualificado como tortura, les\u00e3o corporal e abandono de incapaz. O caso corre em segredo de Justi\u00e7a.<\/p>\n<p style=\"text-align: justify;\">Segundo informa\u00e7\u00f5es da Pol\u00edcia Civil, o casal ainda n\u00e3o tem defesa constitu\u00edda. Este espa\u00e7o ser\u00e1 atualizado t\u00e3o logo os investigados ou seus representantes legais apresentem manifesta\u00e7\u00e3o.<br \/>\nNo bairro Vila da Paz, onde a fam\u00edlia da crian\u00e7a reside, moradores relatam que o menino quase n\u00e3o era visto brincando pelo bairro e que frequentemente tinha marcas de agress\u00e3o. Quando ele era questionado sobre os machucados, dizia ser devido a quedas.<\/p>\n<p>&#8220;Ele vinha aqui frequentemente. Entrava, pegava o que precisava e j\u00e1 saia. Ele n\u00e3o conversava e dificilmente olhava no nosso rosto, sempre estava de bon\u00e9 e parecia estar triste. Quando a gente perguntava sobre os machucados, que eram principalmente no rosto, ele falava que havia ca\u00eddo da \u00e1rvore, de bicicleta, sempre tinha uma desculpa&#8221;, relata uma comerciante do bairro, que pediu para n\u00e3o ter o nome divulgado.<\/p>\n<p>Ainda segundo a mulher, os pais da crian\u00e7a tamb\u00e9m frequentavam o local.<\/p>\n<p style=\"text-align: justify;\">\n&#8220;A m\u00e3e era de poucas palavras, mas o pai sempre muito simp\u00e1tico. A gente imaginava que o menino apanhasse de maneira exagerada da m\u00e3e, mas n\u00e3o que era torturado daquela forma t\u00e3o cruel&#8221;, diz a mulher.<\/p>\n<p>Por: Folhapress<\/p>\n<div class=\"d-flex justify-content-center my-3\">\n<div id=\"banner-300x250-2-area\" data-desktop=\"300x250\" data-mobile=\"320x50\" data-google-query-id=\"CM2nyvTcyvcCFeYGuQYdkAMJ7A\">\n<div id=\"google_ads_iframe_\/8804\/parceiros\/bnews_1__container__\" style=\"text-align: justify;\"><\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Um menino de 11 anos foi encontrado por vizinhos com sinais de tortura e maus-tratos, em Itu (SP). A suspeita \u00e9 de que ele sofria viol\u00eancia f\u00edsica e psicol\u00f3gica praticada pelos pais h\u00e1 pelo menos cinco anos. O casal teve a pris\u00e3o preventiva decretada e est\u00e1 foragido. O Conselho Tutelar afirma que recebeu a den\u00fancia [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":36784,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[200],"tags":[3915,9366,1059,586],"class_list":["post-36783","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil","tag-menino-de-11-anos","tag-pais-procurados","tag-resgate","tag-tortura"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/246997_widelg_widelg-1.jpg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/246997_widelg_widelg-1.jpg",500,281,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/246997_widelg_widelg-1-150x150.jpg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/246997_widelg_widelg-1-300x169.jpg",300,169,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/246997_widelg_widelg-1.jpg",500,281,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/246997_widelg_widelg-1.jpg",500,281,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/246997_widelg_widelg-1.jpg",500,281,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/246997_widelg_widelg-1.jpg",500,281,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/246997_widelg_widelg-1.jpg",500,281,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/246997_widelg_widelg-1-420x281.jpg",420,281,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/246997_widelg_widelg-1-300x281.jpg",300,281,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/246997_widelg_widelg-1-464x281.jpg",464,281,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/246997_widelg_widelg-1.jpg",500,281,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/246997_widelg_widelg-1-322x230.jpg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/246997_widelg_widelg-1.jpg",500,281,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"Um menino de 11 anos foi encontrado por vizinhos com sinais de tortura e maus-tratos, em Itu (SP). A suspeita \u00e9 de que ele sofria viol\u00eancia f\u00edsica e psicol\u00f3gica praticada pelos pais h\u00e1 pelo menos cinco anos. O casal teve a pris\u00e3o preventiva decretada e est\u00e1 foragido. O Conselho Tutelar afirma que recebeu a den\u00fancia&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/36783","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=36783"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/36783\/revisions"}],"predecessor-version":[{"id":36785,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/36783\/revisions\/36785"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/36784"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=36783"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=36783"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=36783"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}