{"id":37237,"date":"2022-05-16T17:14:00","date_gmt":"2022-05-16T20:14:00","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=37237"},"modified":"2022-05-16T15:30:49","modified_gmt":"2022-05-16T18:30:49","slug":"matriculas-para-o-projovem-sao-prorrogadas-em-juazeiro","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2022\/05\/16\/matriculas-para-o-projovem-sao-prorrogadas-em-juazeiro","title":{"rendered":"Matr\u00edculas para o Projovem s\u00e3o prorrogadas em Juazeiro"},"content":{"rendered":"<p style=\"text-align: justify;\">A Prefeitura de Juazeiro, atrav\u00e9s da Secretaria de Educa\u00e7\u00e3o e Juventude (Seduc), prorrogou as matr\u00edculas para o Programa Nacional de Inclus\u00e3o de Jovens (Projovem), no munic\u00edpio. O programa \u00e9 voltado para jovens com idades entre 18 e 29 anos que n\u00e3o conclu\u00edram o ensino fundamental, e visa promover a escolariza\u00e7\u00e3o e qualifica\u00e7\u00e3o profissional por meio da oferta de um curso t\u00e9cnico de Administra\u00e7\u00e3o. As matr\u00edculas s\u00e3o gratuitas e podem ser realizadas presencialmente, at\u00e9 o dia 24 de maio.<\/p>\n<p style=\"text-align: justify;\">Em Juazeiro, o Projovem \u00e9 oferecido nas escolas municipais Professora Maria Franca Pires, localizada \u00e0 Rua Allan Karine, S\/N, no bairro Jo\u00e3o XXIII, e na Escola Professora Hayd\u00e9e Fonseca Falc\u00e3o, que fica na Quadra 23, S\/N, no bairro Jo\u00e3o Paulo II. Com a amplia\u00e7\u00e3o das vagas, as escolas, juntas, disponibilizar\u00e3o 60 oportunidades. O Projovem proporciona aos jovens a oportunidade de voltar a estudar, ou de ingressar pela primeira vez na escola. Sua metodologia oferece a chance de concluir o ensino fundamental no per\u00edodo de 18 meses. A proposta do programa \u00e9 promover a inclus\u00e3o socioecon\u00f4mica das pessoas que n\u00e3o tiveram a oportunidade de concluir esta etapa da vida escolar, e se inserir no mercado de trabalho.<\/p>\n<p style=\"text-align: justify;\">Passo a passo da matr\u00edcula<\/p>\n<p style=\"text-align: justify;\">Para se matricular, os jovens devem buscar uma das unidades de ensino em que \u00e9 oferecido o programa, no per\u00edodo de 8h \u00e0s 12h, 13h \u00e0s 17h ou de 18h \u00e0s 20h, portando os seguintes documentos: carteira de identidade (original e c\u00f3pia); certid\u00e3o de nascimento ou casamento (original e c\u00f3pia); CPF (original e c\u00f3pia); comprovante de escolaridade (original e c\u00f3pia); comprovante de endere\u00e7o (original e c\u00f3pia); t\u00edtulo de eleitor (original e c\u00f3pia); e 1 foto 3\u00d74.<\/p>\n<p style=\"text-align: justify;\">As aulas est\u00e3o previstas para come\u00e7ar no dia 18 de junho e ser\u00e3o oferecidas de segunda a sexta-feira, das 19h \u00e0s 22h, nas duas escolas que fazem parte do projeto. Os estudantes que registrarem 75% da frequ\u00eancia em sala de aula e das atividades receber\u00e3o ainda uma bolsa-aux\u00edlio no valor de R$100,00 por m\u00eas.<\/p>\n<p style=\"text-align: justify;\">Ascom\/Seduc\/PM<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Juazeiro, atrav\u00e9s da Secretaria de Educa\u00e7\u00e3o e Juventude (Seduc), prorrogou as matr\u00edculas para o Programa Nacional de Inclus\u00e3o de Jovens (Projovem), no munic\u00edpio. O programa \u00e9 voltado para jovens com idades entre 18 e 29 anos que n\u00e3o conclu\u00edram o ensino fundamental, e visa promover a escolariza\u00e7\u00e3o e qualifica\u00e7\u00e3o profissional por meio [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":37238,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[203],"tags":[9,4759,9546,9547],"class_list":["post-37237","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-juazeiro","tag-juazeiro","tag-matriculas","tag-projovem","tag-prorrogadas"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-16-at-13.06.21.jpeg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-16-at-13.06.21.jpeg",500,500,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-16-at-13.06.21-150x150.jpeg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-16-at-13.06.21-300x300.jpeg",300,300,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-16-at-13.06.21.jpeg",500,500,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-16-at-13.06.21.jpeg",500,500,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-16-at-13.06.21.jpeg",500,500,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-16-at-13.06.21.jpeg",500,500,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-16-at-13.06.21.jpeg",500,500,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-16-at-13.06.21-420x307.jpeg",420,307,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-16-at-13.06.21-300x443.jpeg",300,443,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-16-at-13.06.21-464x290.jpeg",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-16-at-13.06.21.jpeg",500,500,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-16-at-13.06.21-322x230.jpeg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-16-at-13.06.21.jpeg",500,500,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"A Prefeitura de Juazeiro, atrav\u00e9s da Secretaria de Educa\u00e7\u00e3o e Juventude (Seduc), prorrogou as matr\u00edculas para o Programa Nacional de Inclus\u00e3o de Jovens (Projovem), no munic\u00edpio. O programa \u00e9 voltado para jovens com idades entre 18 e 29 anos que n\u00e3o conclu\u00edram o ensino fundamental, e visa promover a escolariza\u00e7\u00e3o e qualifica\u00e7\u00e3o profissional por meio&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/37237","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=37237"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/37237\/revisions"}],"predecessor-version":[{"id":37239,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/37237\/revisions\/37239"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/37238"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=37237"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=37237"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=37237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}