{"id":37241,"date":"2022-05-16T16:46:50","date_gmt":"2022-05-16T19:46:50","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=37241"},"modified":"2022-05-16T16:46:53","modified_gmt":"2022-05-16T19:46:53","slug":"vereador-lourival-quirino-acompanha-a-reforma-da-praca-alsus-sangalo","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2022\/05\/16\/vereador-lourival-quirino-acompanha-a-reforma-da-praca-alsus-sangalo","title":{"rendered":"Vereador Lourival Quirino acompanha a reforma da pra\u00e7a Alsus Sangalo"},"content":{"rendered":"<div>\n<p style=\"text-align: justify;\">O vereador Lourival Quirino (sem partido) esteve em reuni\u00e3o na manh\u00e3 desta segunda-feira (16) com a equipe de engenharia da SEDUR &#8211; Secretaria de Desenvolvimento Urbano e com o Assessor Especial Jo\u00e3o Vitor, para definiram a reforma e a revitaliza\u00e7\u00e3o da pra\u00e7a que leva o nome do pai da cantora juazeirense, Ivete Sangalo.<\/p>\n<p style=\"text-align: justify;\">Na pra\u00e7a est\u00e1 o busto do pai da cantora Ivete Sangalo, Alsus Sangalo, um dos primeiros moradores do bairro.<\/p>\n<p style=\"text-align: justify;\">Para o Vereador Lourival Quirino, \u201cnossa confian\u00e7a na prefeita Suzana Ramos, que tem atendido os pleitos das comunidades, mas \u201cagora chegou a hora do Country. \u201cTenho consci\u00eancia que bairro \u00e9 um dos privilegiados em rela\u00e7\u00e3o a tantos outros de Juazeiro, que n\u00e3o possuem a m\u00ednima estrutura, mas com certeza a prefeita vai olhar com mais carinho para essa comunidade\u201d, pontou o vereador.<\/p>\n<p style=\"text-align: justify;\">Para o Assessor Especial, Jo\u00e3o Vitor, que conferiu a situa\u00e7\u00e3o das pra\u00e7as e concordou com a necessidade da reforma, \u201cn\u00e3o h\u00e1 d\u00favidas que a urbaniza\u00e7\u00e3o e a reforma da pra\u00e7a \u00e9 necess\u00e1ria, a pra\u00e7a Alsus Sangalo estar\u00e1 dentro das prioridades da Secretaria\u201d.<\/p>\n<p style=\"text-align: justify;\">\n<\/div>\n<div style=\"text-align: justify;\"><\/div>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>O vereador Lourival Quirino (sem partido) esteve em reuni\u00e3o na manh\u00e3 desta segunda-feira (16) com a equipe de engenharia da SEDUR &#8211; Secretaria de Desenvolvimento Urbano e com o Assessor Especial Jo\u00e3o Vitor, para definiram a reforma e a revitaliza\u00e7\u00e3o da pra\u00e7a que leva o nome do pai da cantora juazeirense, Ivete Sangalo. Na pra\u00e7a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":37250,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[203,197],"tags":[],"class_list":["post-37241","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-juazeiro","category-politica"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-16-at-09.24.15.jpeg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-16-at-09.24.15.jpeg",500,664,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-16-at-09.24.15-150x150.jpeg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-16-at-09.24.15-226x300.jpeg",226,300,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-16-at-09.24.15.jpeg",500,664,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-16-at-09.24.15.jpeg",500,664,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-16-at-09.24.15.jpeg",500,664,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-16-at-09.24.15.jpeg",500,664,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-16-at-09.24.15.jpeg",500,664,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-16-at-09.24.15-420x307.jpeg",420,307,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-16-at-09.24.15-300x443.jpeg",300,443,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-16-at-09.24.15-464x290.jpeg",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-16-at-09.24.15-500x500.jpeg",500,500,true],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-16-at-09.24.15-322x230.jpeg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-16-at-09.24.15-500x642.jpeg",500,642,true]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"O vereador Lourival Quirino (sem partido) esteve em reuni\u00e3o na manh\u00e3 desta segunda-feira (16) com a equipe de engenharia da SEDUR &#8211; Secretaria de Desenvolvimento Urbano e com o Assessor Especial Jo\u00e3o Vitor, para definiram a reforma e a revitaliza\u00e7\u00e3o da pra\u00e7a que leva o nome do pai da cantora juazeirense, Ivete Sangalo. Na pra\u00e7a&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/37241","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=37241"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/37241\/revisions"}],"predecessor-version":[{"id":37251,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/37241\/revisions\/37251"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/37250"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=37241"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=37241"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=37241"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}