{"id":37523,"date":"2022-05-24T12:23:00","date_gmt":"2022-05-24T15:23:00","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=37523"},"modified":"2022-05-24T11:28:09","modified_gmt":"2022-05-24T14:28:09","slug":"abertura-de-1o-salao-de-turismo-do-vale-do-sao-francisco-reforca-riquezas-turisticas-e-culturais-de-juazeiro","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2022\/05\/24\/abertura-de-1o-salao-de-turismo-do-vale-do-sao-francisco-reforca-riquezas-turisticas-e-culturais-de-juazeiro","title":{"rendered":"Abertura de 1\u00ba Sal\u00e3o de Turismo do Vale do S\u00e3o Francisco refor\u00e7a riquezas tur\u00edsticas e culturais de Juazeiro"},"content":{"rendered":"<p style=\"text-align: justify;\">O 1\u00ba Sal\u00e3o de Turismo do Vale do S\u00e3o Francisco, que teve in\u00edcio na noite desta quinta-feira (19), j\u00e1 demonstrou que ser\u00e1 um grande sucesso. A Prefeitura de Juazeiro montou um stand diversificado para apresentar elementos da cultura, turismo e artesanato locais. Quem passou pelo espa\u00e7o, aprovou o que viu.<\/p>\n<p style=\"text-align: justify;\">A moradora de Cura\u00e7\u00e1, Edjane Maia, elogiou a representa\u00e7\u00e3o de Juazeiro no Sal\u00e3o. \u201cTudo muito bonito e organizado. Est\u00e1 sendo uma oportunidade muito boa para a gente conhecer mais de cidades, que, mesmo t\u00e3o pr\u00f3ximas, tem bastante pra mostrar\u201d, disse.<\/p>\n<p style=\"text-align: justify;\">Na abertura, o secret\u00e1rio de Cultura, Turismo e Esportes de Juazeiro, S\u00e9rgio Fernandes, comemorou a retomada de eventos como o Sal\u00e3o de Turismo e falou da import\u00e2ncia de fortalecer o potencial tur\u00edstico da regi\u00e3o. \u201c\u00c9 com muita alegria que hoje estamos aqui, reunidos com diversos outros munic\u00edpios, mostrando todo o potencial das nossas cidades. Quando chegou o projeto do Sal\u00e3o, a prefeita Suzana Ramos deu total apoio, pois a gente sabe a import\u00e2ncia do turismo e a riqueza cultural de Juazeiro\u201d, afirmou.<\/p>\n<p style=\"text-align: justify;\"><b>Sal\u00e3o de Turismo do Vale do S\u00e3o Francisco<\/b><\/p>\n<p style=\"text-align: justify;\">O 1\u00b0 Sal\u00e3o de Turismo do Vale do S\u00e3o Francisco \u00e9 idealizado pela Cooperativa de Produtores e Empreendedores do Turismo e Agroneg\u00f3cio do Subm\u00e9dio do S\u00e3o Francisco (Coopemvale) e a Ag\u00eancia de Turismo Rural, Enoturismo, Pedag\u00f3gico e Criativo em Petrolina (Criatur). A Prefeitura de Juazeiro \u00a0\u00e9 co-organizadora \u00a0do evento que segue at\u00e9 \u00a0o domingo (22) e conta com diversas apresenta\u00e7\u00f5es culturais. A entrada \u00e9 gratuita.<\/p>\n<div style=\"text-align: justify;\"><\/div>\n<div style=\"text-align: justify;\">Texto: Karem Moraes<\/div>\n","protected":false},"excerpt":{"rendered":"<p>O 1\u00ba Sal\u00e3o de Turismo do Vale do S\u00e3o Francisco, que teve in\u00edcio na noite desta quinta-feira (19), j\u00e1 demonstrou que ser\u00e1 um grande sucesso. A Prefeitura de Juazeiro montou um stand diversificado para apresentar elementos da cultura, turismo e artesanato locais. Quem passou pelo espa\u00e7o, aprovou o que viu. A moradora de Cura\u00e7\u00e1, Edjane [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":37526,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1506,203],"tags":[9654,4441,2348,720],"class_list":["post-37523","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","category-juazeiro","tag-1o-salao","tag-abertura","tag-turismo","tag-vale-do-sao-francisco"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/Abertura-Salao-de-Turismo-3.jpg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/Abertura-Salao-de-Turismo-3.jpg",500,333,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/Abertura-Salao-de-Turismo-3-150x150.jpg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/Abertura-Salao-de-Turismo-3-300x200.jpg",300,200,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/Abertura-Salao-de-Turismo-3.jpg",500,333,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/Abertura-Salao-de-Turismo-3.jpg",500,333,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/Abertura-Salao-de-Turismo-3.jpg",500,333,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/Abertura-Salao-de-Turismo-3.jpg",500,333,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/Abertura-Salao-de-Turismo-3.jpg",500,333,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/Abertura-Salao-de-Turismo-3-420x307.jpg",420,307,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/Abertura-Salao-de-Turismo-3-300x333.jpg",300,333,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/Abertura-Salao-de-Turismo-3-464x290.jpg",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/Abertura-Salao-de-Turismo-3.jpg",500,333,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/Abertura-Salao-de-Turismo-3-322x230.jpg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/Abertura-Salao-de-Turismo-3.jpg",500,333,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"O 1\u00ba Sal\u00e3o de Turismo do Vale do S\u00e3o Francisco, que teve in\u00edcio na noite desta quinta-feira (19), j\u00e1 demonstrou que ser\u00e1 um grande sucesso. A Prefeitura de Juazeiro montou um stand diversificado para apresentar elementos da cultura, turismo e artesanato locais. Quem passou pelo espa\u00e7o, aprovou o que viu. A moradora de Cura\u00e7\u00e1, Edjane&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/37523","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=37523"}],"version-history":[{"count":3,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/37523\/revisions"}],"predecessor-version":[{"id":37528,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/37523\/revisions\/37528"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/37526"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=37523"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=37523"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=37523"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}