{"id":37529,"date":"2022-05-24T13:48:00","date_gmt":"2022-05-24T16:48:00","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=37529"},"modified":"2022-05-24T11:39:14","modified_gmt":"2022-05-24T14:39:14","slug":"mulher-e-presa-por-trafico-de-drogas-em-juazeiro","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2022\/05\/24\/mulher-e-presa-por-trafico-de-drogas-em-juazeiro","title":{"rendered":"Mulher \u00e9 presa por tr\u00e1fico de drogas em juazeiro"},"content":{"rendered":"<p style=\"text-align: justify;\">A 75\u00aa Companhia Independente de Pol\u00edcia Militar (CIPM), com apoio do Policiamento da Regi\u00e3o Norte (CPR-N), prendeu, nesta segunda (24), uma mulher por tr\u00e1fico de drogas em Juazeiro(BA). A pris\u00e3o ocorreu em frente ao p\u00e1tio do Posto Frei Dami\u00e3o.<\/p>\n<p style=\"text-align: justify;\">Os Policiais Militares do PETO\/75CIPM\u00a0 estavam realizando rondas no p\u00e1tio do Posto, quando observaram uma mulher em atitude suspeita ao avistar a viatura. Em seguida, foi realizada abordagem e busca pessoal e encontrado em sua posse quarenta pedras de subst\u00e2ncia an\u00e1loga \u00e0 crack, oito petecas de subst\u00e2ncia an\u00e1loga \u00e0 coca\u00edna, cem reais em dinheiro e um aparelho celular Samsung.<\/p>\n<p style=\"text-align: justify;\">Diante do flagrante, a mulher e os materiais foram conduzidos \u00e0 Delegacia de Pol\u00edcia Civil para ado\u00e7\u00e3o das medidas legais cab\u00edveis ao caso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A 75\u00aa Companhia Independente de Pol\u00edcia Militar (CIPM), com apoio do Policiamento da Regi\u00e3o Norte (CPR-N), prendeu, nesta segunda (24), uma mulher por tr\u00e1fico de drogas em Juazeiro(BA). A pris\u00e3o ocorreu em frente ao p\u00e1tio do Posto Frei Dami\u00e3o. Os Policiais Militares do PETO\/75CIPM\u00a0 estavam realizando rondas no p\u00e1tio do Posto, quando observaram uma mulher [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":37530,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[203],"tags":[2877,693,2169,1408],"class_list":["post-37529","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-juazeiro","tag-juazeiro-ba","tag-mulher","tag-presa","tag-trafico-de-drogas"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-24-at-10.15.40.jpeg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-24-at-10.15.40.jpeg",500,500,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-24-at-10.15.40-150x150.jpeg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-24-at-10.15.40-300x300.jpeg",300,300,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-24-at-10.15.40.jpeg",500,500,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-24-at-10.15.40.jpeg",500,500,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-24-at-10.15.40.jpeg",500,500,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-24-at-10.15.40.jpeg",500,500,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-24-at-10.15.40.jpeg",500,500,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-24-at-10.15.40-420x307.jpeg",420,307,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-24-at-10.15.40-300x443.jpeg",300,443,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-24-at-10.15.40-464x290.jpeg",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-24-at-10.15.40.jpeg",500,500,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-24-at-10.15.40-322x230.jpeg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-24-at-10.15.40.jpeg",500,500,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"A 75\u00aa Companhia Independente de Pol\u00edcia Militar (CIPM), com apoio do Policiamento da Regi\u00e3o Norte (CPR-N), prendeu, nesta segunda (24), uma mulher por tr\u00e1fico de drogas em Juazeiro(BA). A pris\u00e3o ocorreu em frente ao p\u00e1tio do Posto Frei Dami\u00e3o. Os Policiais Militares do PETO\/75CIPM\u00a0 estavam realizando rondas no p\u00e1tio do Posto, quando observaram uma mulher&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/37529","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=37529"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/37529\/revisions"}],"predecessor-version":[{"id":37531,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/37529\/revisions\/37531"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/37530"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=37529"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=37529"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=37529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}