{"id":37695,"date":"2022-05-28T08:48:00","date_gmt":"2022-05-28T11:48:00","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=37695"},"modified":"2022-05-28T08:25:16","modified_gmt":"2022-05-28T11:25:16","slug":"ivete-sangalo-comemora-50-anos-com-grande-show-em-juazeiro","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2022\/05\/28\/ivete-sangalo-comemora-50-anos-com-grande-show-em-juazeiro","title":{"rendered":"Ivete Sangalo comemora 50 anos com grande show em Juazeiro"},"content":{"rendered":"<p style=\"text-align: justify;\">Em grande estilo, a cantora Ivete Sangalo comemorou seus 50 anos de vida com um show na cidade natal dela, Juazeiro, norte da Bahia, na noite desta sexta-feira (27). A artista levou o p\u00fablico ao del\u00edrio com um lindo espet\u00e1culo, que foi aberto com a m\u00fasica &#8220;T\u00e1 solteira, mas n\u00e3o t\u00e1 sozinha&#8221;.<\/p>\n<p style=\"text-align: justify;\">Na sequ\u00eancia, f\u00e3s e admiradores da artista sa\u00edram do ch\u00e3o quando &#8220;Veveta&#8221; trouxe a can\u00e7\u00e3o &#8220;Alegria&#8221;. Outros hits dela ou cl\u00e1ssicos da m\u00fasica baiana n\u00e3o foram esquecidos, como &#8220;Sorte Grande&#8221; e &#8220;C\u00e9u da Boca&#8221;. Houve espa\u00e7o tamb\u00e9m para uma performance ao som de funk, ao lado dos dan\u00e7arinos.<\/p>\n<p style=\"text-align: justify;\">Um dos momentos mais emocionantes do show foi quando a plateia cantou parab\u00e9ns para &#8220;Mainha&#8221;, que ficou bastante emocionada com a homenagem. Ela retribuiu o carinho dos f\u00e3s fazendo uma reflex\u00e3o.<\/p>\n<div class=\"d-flex justify-content-center my-3\" style=\"text-align: justify;\">\n<div id=\"banner-300x250-1-area\" data-desktop=\"300x250\" data-mobile=\"320x50\" data-google-query-id=\"CPyU2rKIgvgCFXg3uQYdhjUNGQ\">\n<div id=\"google_ads_iframe_\/8804\/parceiros\/bnews_0__container__\"><span style=\"font-size: revert; color: initial;\">&#8220;A coisa mais habitual que eu fazia em Juazeiro, na cal\u00e7ada quente, com o vento frio, era olhar para as estrelas e perguntar: \u2018Ivetinha daqui a cinco anos, daqui a 20, onde voc\u00ea vai estar?\u2019. Ontem me deitei e falei: \u2018Ivetinha olha onde voc\u00ea chegou!'&#8221;, iniciou.<\/span><\/div>\n<\/div>\n<\/div>\n<p style=\"text-align: justify;\">&#8220;Estou de volta ao meu lugar, a minha cidade mais amada. Por esse lugar tenho muita gratid\u00e3o e tenho orgulho da mulher que me tornei. Sou grata a Juazeiro da Bahia, essa terra que me fez gigante! Obrigada Juazeiro! Vim comemorar meus 50 anos com voc\u00eas, comemorar meio s\u00e9culo de exist\u00eancia. Obrigada Juazeiro, amo voc\u00eas! Trouxe minha alegria e meu carnaval!\u201d, completou a artista.<\/p>\n<p style=\"text-align: justify;\">Outro ponto alto do evento foi a presen\u00e7a do filho mais velho dela, Marcelo. O garoto fez uma apresenta\u00e7\u00e3o na percuss\u00e3o, o que encheu a m\u00e3e de orgulho: &#8220;Te amo filh\u00e3o!&#8221;. Em seguida, tamb\u00e9m declarou toda a paix\u00e3o dela as g\u00eameas, Marina e Helena, ao cantar &#8220;Agora Eu j\u00e1 Sei&#8221;: &#8220;Amo voc\u00eas meus filhos, quantas alegrias!&#8221;<\/p>\n<p>Por: BNews<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em grande estilo, a cantora Ivete Sangalo comemorou seus 50 anos de vida com um show na cidade natal dela, Juazeiro, norte da Bahia, na noite desta sexta-feira (27). A artista levou o p\u00fablico ao del\u00edrio com um lindo espet\u00e1culo, que foi aberto com a m\u00fasica &#8220;T\u00e1 solteira, mas n\u00e3o t\u00e1 sozinha&#8221;. Na sequ\u00eancia, f\u00e3s [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":37696,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[203],"tags":[9721,9722,3510,9],"class_list":["post-37695","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-juazeiro","tag-comemora-50-anos","tag-grande-show","tag-ivete-sangalo","tag-juazeiro"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/ivete_sangalo_50_anos_tvglobo_widelg-1.jpg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/ivete_sangalo_50_anos_tvglobo_widelg-1.jpg",500,281,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/ivete_sangalo_50_anos_tvglobo_widelg-1-150x150.jpg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/ivete_sangalo_50_anos_tvglobo_widelg-1-300x169.jpg",300,169,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/ivete_sangalo_50_anos_tvglobo_widelg-1.jpg",500,281,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/ivete_sangalo_50_anos_tvglobo_widelg-1.jpg",500,281,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/ivete_sangalo_50_anos_tvglobo_widelg-1.jpg",500,281,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/ivete_sangalo_50_anos_tvglobo_widelg-1.jpg",500,281,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/ivete_sangalo_50_anos_tvglobo_widelg-1.jpg",500,281,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/ivete_sangalo_50_anos_tvglobo_widelg-1-420x281.jpg",420,281,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/ivete_sangalo_50_anos_tvglobo_widelg-1-300x281.jpg",300,281,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/ivete_sangalo_50_anos_tvglobo_widelg-1-464x281.jpg",464,281,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/ivete_sangalo_50_anos_tvglobo_widelg-1.jpg",500,281,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/ivete_sangalo_50_anos_tvglobo_widelg-1-322x230.jpg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/05\/ivete_sangalo_50_anos_tvglobo_widelg-1.jpg",500,281,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"Em grande estilo, a cantora Ivete Sangalo comemorou seus 50 anos de vida com um show na cidade natal dela, Juazeiro, norte da Bahia, na noite desta sexta-feira (27). A artista levou o p\u00fablico ao del\u00edrio com um lindo espet\u00e1culo, que foi aberto com a m\u00fasica &#8220;T\u00e1 solteira, mas n\u00e3o t\u00e1 sozinha&#8221;. Na sequ\u00eancia, f\u00e3s&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/37695","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=37695"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/37695\/revisions"}],"predecessor-version":[{"id":37697,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/37695\/revisions\/37697"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/37696"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=37695"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=37695"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=37695"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}