{"id":38429,"date":"2022-06-17T10:46:00","date_gmt":"2022-06-17T13:46:00","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=38429"},"modified":"2022-06-16T21:53:44","modified_gmt":"2022-06-17T00:53:44","slug":"justica-decreta-sequestro-de-bens-do-pcc-e-de-contador-ligado-a-lula","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2022\/06\/17\/justica-decreta-sequestro-de-bens-do-pcc-e-de-contador-ligado-a-lula","title":{"rendered":"Justi\u00e7a decreta sequestro de bens do PCC e de contador ligado a Lula"},"content":{"rendered":"<p style=\"text-align: justify;\">A 1\u00aa Vara de Crimes Tribut\u00e1rios, Organiza\u00e7\u00e3o Criminosa e Lavagem de Dinheiro da Justi\u00e7a estadual de S\u00e3o Paulo determinou o bloqueio de R$ 40 milh\u00f5es em im\u00f3veis e \u00f4nibus de integrantes do PCC e do contador\u00a0<a href=\"https:\/\/www.cnnbrasil.com.br\/politica\/contador-ligado-a-lula-e-suspeito-de-lavar-r-16-milhoes-em-loteria-com-pcc\/\">Jo\u00e3o Muniz Leite, que foi respons\u00e1vel pelo Imposto de Renda do ex-presidente Luiz In\u00e1cio Lula da Silva<\/a>\u00a0e, at\u00e9 hoje, cuida da contabilidade e divide sala com empresas do filho do petista, F\u00e1bio Lu\u00eds Lula da Silva, o Lulinha.<\/p>\n<p style=\"text-align: justify;\">O pedido foi feito pelo delegado Fernando Santiago, e endossado pelo Minist\u00e9rio P\u00fablico Estadual de S\u00e3o Paulo. Al\u00e9m de Muniz, atinge o traficante de drogas Anselmo Becheli Santa Fausta, o Cara Preta, considerado um dos principais fornecedores de drogas do Primeiro Comando da Capital (PCC), e seu s\u00f3cio, Silvio Luiz Ferreira, o \u201cCebola\u201d, chefe da Sintonia do Progresso, o setor que cuida do tr\u00e1fico dom\u00e9stico mantido pela fac\u00e7\u00e3o. Santa Fausta foi morto, em dezembro de 2021, em uma emboscada na zona leste.<\/p>\n<p style=\"text-align: justify;\">A medida da Justi\u00e7a atingiu 250 \u00f4nibus da UPBus, a empresa de \u00f4nibus comprada por Santa Fausta supostamente com o dinheiro lavado nas loterias. A UPBus mant\u00e9m contrato de R$ 660 milh\u00f5es com a Prefeitura de S\u00e3o Paulo e toma conta de 13 linhas de \u00f4nibus na zona leste. Al\u00e9m de Santa Fausta, Cebola, que est\u00e1 foragido, faz parte da diretoria da empresa. O sequestro dos \u00f4nibus e n\u00e3o das contas da empresa serviu para que ela n\u00e3o paralise seu funcionamento, prejudicando os usu\u00e1rios.<\/p>\n<p style=\"text-align: justify;\">O contador \u00e9 suspeito de ser o \u201coperador de um complexo esquema de lavagem de dinheiro atrav\u00e9s de pr\u00eamios da Loteria Federal\u201d. Como mostrou o Estad\u00e3o, Muniz, ao lado da esposa, ganhou em loterias federais 55 vezes somente no ano de 2021. Segundo a contagem final da Pol\u00edcia Civil, o montante lavado pelo contador em pr\u00eamios na loteria chegou aos R$ 40 milh\u00f5es. Do total, R$ 16 milh\u00f5es ficaram com o contador e o restante teria ficado com Santa Fausta. Em diversas ocasi\u00f5es, os valores das apostas superavam o dos pr\u00eamios obtidos, com exce\u00e7\u00e3o de dois pr\u00eamios de R$ 16 milh\u00f5es na Mega Sena.<\/p>\n<figure id=\"attachment_789840\" class=\"wp-caption alignnone\" style=\"text-align: justify;\" aria-describedby=\"caption-attachment-789840\"><figcaption id=\"caption-attachment-789840\" class=\"wp-caption-text\"><\/figcaption><\/figure>\n<h2 style=\"text-align: justify;\">Familiares<\/h2>\n<p style=\"text-align: justify;\">O ex-presidente Lula n\u00e3o \u00e9 alvo da investiga\u00e7\u00e3o. Muniz \u00e9 contador da fam\u00edlia do ex-presidente at\u00e9 os dias atuais. Levam o logo da JML Assessoria Cont\u00e1bil e Fiscal os documentos de cadastro, na Junta Comercial de S\u00e3o Paulo, em fevereiro de 2022, da mais recente empresa criada por Lulinha, a LLF Tech Participa\u00e7\u00f5es LTDA, sediada no apartamento onde o filho do ex-presidente reside. O im\u00f3vel est\u00e1 em nome do empres\u00e1rio Jonas Suassuna, que foi s\u00f3cio de Lulinha e propriet\u00e1rio formal do s\u00edtio Santa B\u00e1rbara, em Atibaia, propriedade em raz\u00e3o da qual Lula foi processado na Lava Jato.<\/p>\n<p style=\"text-align: justify;\">O advogado de Jo\u00e3o Muniz, Jorge Delmanto, afirmou ao Estad\u00e3o que vai \u201cacessar o processo\u201d, para, ent\u00e3o se manifestar sobre a investiga\u00e7\u00e3o. \u201cAdianto apenas que a empresa de Contabilidade tem mais de 30 anos de atua\u00e7\u00e3o, com mais de 60 funcion\u00e1rios e m\u00e9dia de 1000 clientes ativos, sendo empresa voltada ao profissionalismo, legalidade, ilibada e com postura \u00e9tica em todos os casos\u201d, disse.<\/p>\n<p style=\"text-align: justify;\">A reportagem procurou ainda a assessoria de Lula e a sua defesa e a de seu filho. O advogado Cristiano Zanin Martins, que defende Lula, disse n\u00e3o saber se Muniz ainda presta servi\u00e7os para o petista. O criminalista F\u00e1bio Tofic, que defende Lulinha, n\u00e3o se manifestou. A defesa da fam\u00edlia Santa Fausta e dos demais integrantes do PCC investigados pelo Denarc tamb\u00e9m n\u00e3o foi localizada pela reportagem.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A 1\u00aa Vara de Crimes Tribut\u00e1rios, Organiza\u00e7\u00e3o Criminosa e Lavagem de Dinheiro da Justi\u00e7a estadual de S\u00e3o Paulo determinou o bloqueio de R$ 40 milh\u00f5es em im\u00f3veis e \u00f4nibus de integrantes do PCC e do contador\u00a0Jo\u00e3o Muniz Leite, que foi respons\u00e1vel pelo Imposto de Renda do ex-presidente Luiz In\u00e1cio Lula da Silva\u00a0e, at\u00e9 hoje, cuida [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":38430,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[200,202],"tags":[],"class_list":["post-38429","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil","category-policia"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/06\/D5QYNCQOJZDPTDTKZUK44OF45U.jpg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/06\/D5QYNCQOJZDPTDTKZUK44OF45U.jpg",500,314,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/06\/D5QYNCQOJZDPTDTKZUK44OF45U-150x150.jpg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/06\/D5QYNCQOJZDPTDTKZUK44OF45U-300x188.jpg",300,188,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/06\/D5QYNCQOJZDPTDTKZUK44OF45U.jpg",500,314,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/06\/D5QYNCQOJZDPTDTKZUK44OF45U.jpg",500,314,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/06\/D5QYNCQOJZDPTDTKZUK44OF45U.jpg",500,314,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/06\/D5QYNCQOJZDPTDTKZUK44OF45U.jpg",500,314,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/06\/D5QYNCQOJZDPTDTKZUK44OF45U.jpg",500,314,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/06\/D5QYNCQOJZDPTDTKZUK44OF45U-420x307.jpg",420,307,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/06\/D5QYNCQOJZDPTDTKZUK44OF45U-300x314.jpg",300,314,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/06\/D5QYNCQOJZDPTDTKZUK44OF45U-464x290.jpg",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/06\/D5QYNCQOJZDPTDTKZUK44OF45U.jpg",500,314,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/06\/D5QYNCQOJZDPTDTKZUK44OF45U-322x230.jpg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/06\/D5QYNCQOJZDPTDTKZUK44OF45U.jpg",500,314,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"A 1\u00aa Vara de Crimes Tribut\u00e1rios, Organiza\u00e7\u00e3o Criminosa e Lavagem de Dinheiro da Justi\u00e7a estadual de S\u00e3o Paulo determinou o bloqueio de R$ 40 milh\u00f5es em im\u00f3veis e \u00f4nibus de integrantes do PCC e do contador\u00a0Jo\u00e3o Muniz Leite, que foi respons\u00e1vel pelo Imposto de Renda do ex-presidente Luiz In\u00e1cio Lula da Silva\u00a0e, at\u00e9 hoje, cuida&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/38429","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=38429"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/38429\/revisions"}],"predecessor-version":[{"id":38431,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/38429\/revisions\/38431"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/38430"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=38429"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=38429"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=38429"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}