{"id":40249,"date":"2022-07-30T13:45:00","date_gmt":"2022-07-30T16:45:00","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=40249"},"modified":"2022-07-29T21:37:36","modified_gmt":"2022-07-30T00:37:36","slug":"equipe-da-rede-municipal-de-ensino-de-juazeiro-participa-de-capacitacao-sobre-novo-sistema-que-registra-frequencia-de-alunos-beneficiarios-do-auxilio-brasil","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2022\/07\/30\/equipe-da-rede-municipal-de-ensino-de-juazeiro-participa-de-capacitacao-sobre-novo-sistema-que-registra-frequencia-de-alunos-beneficiarios-do-auxilio-brasil","title":{"rendered":"Equipe da rede municipal de ensino de Juazeiro participa de capacita\u00e7\u00e3o sobre novo sistema que registra frequ\u00eancia de alunos benefici\u00e1rios do Aux\u00edlio Brasil"},"content":{"rendered":"<p style=\"text-align: justify;\">Foi realizada nesta quinta-feira (28), uma capacita\u00e7\u00e3o sobre o novo \u2018Sistema Presen\u00e7a\u2019, que \u00e9 a plataforma para registro de frequ\u00eancia escolar de benefici\u00e1rios e benefici\u00e1rias do Programa Aux\u00edlio Brasil, do Governo Federal. A forma\u00e7\u00e3o, que aconteceu no Col\u00e9gio Modelo Lu\u00eds Eduardo Magalh\u00e3es, foi uma parceria entre o Governo Estadual e a Prefeitura de Juazeiro, atrav\u00e9s da Secretaria de Educa\u00e7\u00e3o e Juventude (Seduc), e contou com a presen\u00e7a dos secret\u00e1rios escolares do munic\u00edpio, de escolas p\u00fablicas e privadas. A superintendente de Gest\u00e3o Escolar Programas e Projetos da Seduc, Alexandrina Ara\u00fajo, esteve presente no treinamento.<\/p>\n<p><b>Sobre o sistema<\/b><\/p>\n<p>O Sistema Presen\u00e7a \u00e9 gerido pelas unidades escolares, que s\u00e3o as respons\u00e1veis por informar a frequ\u00eancia escolar dos alunos cujas fam\u00edlias sejam benefici\u00e1rias do Programa Aux\u00edlio Brasil, programa social de transfer\u00eancia direta e indireta de renda, coordenado pelo Minist\u00e9rio da Cidadania, destinado \u00e0s fam\u00edlias em situa\u00e7\u00e3o de pobreza e de extrema pobreza em todo o pa\u00eds.<\/p>\n<p><b>Incentivo<\/b><\/p>\n<p>De acordo com Ana Tavares, coordenadora municipal do Sistema Presen\u00e7a, o programa incentiva que os alunos frequentem as aulas e os respons\u00e1veis participem mais ativamente da vida escolar das crian\u00e7as. \u201cAl\u00e9m de monitorar a frequ\u00eancia escolar, o sistema garante o recebimento do benef\u00edcio e ajuda a combater a evas\u00e3o escolar, que aumentou principalmente com a pandemia\u201d, ressalta Ana. A secret\u00e1ria escolar da EMEI Nosso Senhor dos Aflitos, no bairro Piranga, Leonice Teon\u00edlia, aprova a implanta\u00e7\u00e3o do Sistema Presen\u00e7a. \u201cCom todo o apoio que recebemos, n\u00f3s ajudamos as fam\u00edlias e tamb\u00e9m o aprendizado dos alunos\u201d, salientou.<\/p>\n\n\n<p>Ascom Seduc\/pmj<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foi realizada nesta quinta-feira (28), uma capacita\u00e7\u00e3o sobre o novo \u2018Sistema Presen\u00e7a\u2019, que \u00e9 a plataforma para registro de frequ\u00eancia escolar de benefici\u00e1rios e benefici\u00e1rias do Programa Aux\u00edlio Brasil, do Governo Federal. A forma\u00e7\u00e3o, que aconteceu no Col\u00e9gio Modelo Lu\u00eds Eduardo Magalh\u00e3es, foi uma parceria entre o Governo Estadual e a Prefeitura de Juazeiro, atrav\u00e9s [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":40250,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[203],"tags":[],"class_list":["post-40249","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-juazeiro"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/07\/PROFE.jpg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/07\/PROFE.jpg",500,333,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/07\/PROFE-150x150.jpg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/07\/PROFE-300x200.jpg",300,200,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/07\/PROFE.jpg",500,333,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/07\/PROFE.jpg",500,333,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/07\/PROFE.jpg",500,333,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/07\/PROFE.jpg",500,333,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/07\/PROFE.jpg",500,333,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/07\/PROFE-420x307.jpg",420,307,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/07\/PROFE-300x333.jpg",300,333,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/07\/PROFE-464x290.jpg",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/07\/PROFE.jpg",500,333,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/07\/PROFE-322x230.jpg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/07\/PROFE.jpg",500,333,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"Foi realizada nesta quinta-feira (28), uma capacita\u00e7\u00e3o sobre o novo \u2018Sistema Presen\u00e7a\u2019, que \u00e9 a plataforma para registro de frequ\u00eancia escolar de benefici\u00e1rios e benefici\u00e1rias do Programa Aux\u00edlio Brasil, do Governo Federal. A forma\u00e7\u00e3o, que aconteceu no Col\u00e9gio Modelo Lu\u00eds Eduardo Magalh\u00e3es, foi uma parceria entre o Governo Estadual e a Prefeitura de Juazeiro, atrav\u00e9s&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/40249","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=40249"}],"version-history":[{"count":2,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/40249\/revisions"}],"predecessor-version":[{"id":40255,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/40249\/revisions\/40255"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/40250"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=40249"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=40249"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=40249"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}