{"id":41625,"date":"2022-08-29T11:45:00","date_gmt":"2022-08-29T14:45:00","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=41625"},"modified":"2022-08-28T19:24:05","modified_gmt":"2022-08-28T22:24:05","slug":"acm-neto-chega-a-250-municipios-percorridos-na-bahia","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2022\/08\/29\/acm-neto-chega-a-250-municipios-percorridos-na-bahia","title":{"rendered":"ACM Neto chega a 250 munic\u00edpios percorridos na Bahia"},"content":{"rendered":"<p style=\"text-align: justify;\">Com a agenda deste domingo (28), o candidato a governador ACM Neto ultrapassa o n\u00famero de 250 cidades percorridas na Bahia desde o in\u00edcio da sua pr\u00e9-campanha. Ao lado dos candidatos a vice-governadora Ana Coelho (Republicanos) e a senador Cac\u00e1 Le\u00e3o (PP), ele participa de carreatas em oito munic\u00edpios do Baixo Sul e do M\u00e9dio Rio de Contas.<\/p>\n<p style=\"text-align: justify;\">As cinco primeiras cidades visitadas pela manh\u00e3 e in\u00edcio da tarde foram Apuarema, Itamari, Nova Ibi\u00e1, Pira\u00ed do Norte e Presidente Tancredo Neves. Em todas, a comitiva da coliga\u00e7\u00e3o Pra Mudar a Bahia foi recebida por lideran\u00e7as locais e sentiu o carinho da popula\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\">&#8220;Esse domingo \u00e9 um dia muito especial para a nossa campanha, pois estamos visitando num s\u00f3 dia oito munic\u00edpios. Sendo que, quando pisei os p\u00e9s aqui em Presidente Tancredo Neves, completei a marca de 250 munic\u00edpios percorridos pela Bahia&#8221;, discursou na cidade do Baixo Sul.<\/p>\n<p style=\"text-align: justify;\">ACM Neto lembrou que trata-se de um feito in\u00e9dito na pol\u00edtica baiana. &#8220;Nunca um candidato a governador do estado andou tanto pela Bahia como eu andei. Nunca um candidato teve um contato assim t\u00e3o pr\u00f3ximo com as pessoas como eu tive. Nunca um candidato teve o respeito de ouvir tantos baianos e ver de perto os problemas e, sobretudo, enxergar quais s\u00e3o os desejos e sonhos do nosso povo&#8221;, completou.<\/p>\n<p style=\"text-align: justify;\">Em Apuarema, a cidade parou para ver a comitiva passar em carro aberto. Em praticamente todas as casas, o povo saiu na cal\u00e7ada ou abriu as janelas para saudar Neto, Cac\u00e1 e Ana ao som do jingle: &#8220;ACM agora \u00e9 44&#8221;. Uma multid\u00e3o a p\u00e9 tamb\u00e9m seguiu o percurso de 2,5 km pelas ruas.<\/p>\n<p style=\"text-align: justify;\">Em Itamari, nem os chuviscos atrapalharam a carreata. Bem na v\u00e9spera do almo\u00e7o, o povo deu um tempinho na cerveja para aparecer na frente das casas a fim de saudar a comitiva. O percurso de 2 km percorreu os bairros mais pobres e o centro da cidade.<\/p>\n<p style=\"text-align: justify;\">Em Nova Ibi\u00e1, Pira\u00ed do Norte e Presidente Tancredo Neves n\u00e3o foi diferente. As pessoas reunidas em casa no domingo receberam as carreatas como um grande evento familiar. Foram para as cal\u00e7adas em cheio, pedindo o adesivo do 44 e declarando seu voto nas elei\u00e7\u00f5es de outubro.<\/p>\n<p style=\"text-align: justify;\">Ainda neste domingo, o candidato do Uni\u00e3o Brasil realiza carreatas em Teol\u00e2ndia, Wenceslau Guimar\u00e3es e Gandu. S\u00f3 na atual agenda pelo interior do estado, que come\u00e7ou na quarta-feira (24) foram 22 cidades visitadas em cinco dias.<\/p>\n<p style=\"text-align: justify;\">Ainda como pr\u00e9-candidato ao governo da Bahia, ACM Neto chegou \u00e0 conven\u00e7\u00e3o do Uni\u00e3o Brasil, no dia 5 de agosto, com quase 200 munic\u00edpios diferentes visitados. Ele come\u00e7ou a percorrer o estado ainda em 2021, dialogando com lideran\u00e7as de todas as regi\u00f5es e ouvindo a popula\u00e7\u00e3o.<\/p>\n\n\n<p>Ascom ACM Neto<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Com a agenda deste domingo (28), o candidato a governador ACM Neto ultrapassa o n\u00famero de 250 cidades percorridas na Bahia desde o in\u00edcio da sua pr\u00e9-campanha. Ao lado dos candidatos a vice-governadora Ana Coelho (Republicanos) e a senador Cac\u00e1 Le\u00e3o (PP), ele participa de carreatas em oito munic\u00edpios do Baixo Sul e do M\u00e9dio [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":38521,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[199,10109],"tags":[],"class_list":["post-41625","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bahia","category-eleicoes-2022"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/06\/acmnetogovernador_alo_alo_bahia.jpg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/06\/acmnetogovernador_alo_alo_bahia.jpg",500,333,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/06\/acmnetogovernador_alo_alo_bahia-150x150.jpg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/06\/acmnetogovernador_alo_alo_bahia-300x200.jpg",300,200,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/06\/acmnetogovernador_alo_alo_bahia.jpg",500,333,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/06\/acmnetogovernador_alo_alo_bahia.jpg",500,333,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/06\/acmnetogovernador_alo_alo_bahia.jpg",500,333,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/06\/acmnetogovernador_alo_alo_bahia.jpg",500,333,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/06\/acmnetogovernador_alo_alo_bahia.jpg",500,333,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/06\/acmnetogovernador_alo_alo_bahia-420x307.jpg",420,307,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/06\/acmnetogovernador_alo_alo_bahia-300x333.jpg",300,333,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/06\/acmnetogovernador_alo_alo_bahia-464x290.jpg",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/06\/acmnetogovernador_alo_alo_bahia.jpg",500,333,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/06\/acmnetogovernador_alo_alo_bahia-322x230.jpg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/06\/acmnetogovernador_alo_alo_bahia.jpg",500,333,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"Com a agenda deste domingo (28), o candidato a governador ACM Neto ultrapassa o n\u00famero de 250 cidades percorridas na Bahia desde o in\u00edcio da sua pr\u00e9-campanha. Ao lado dos candidatos a vice-governadora Ana Coelho (Republicanos) e a senador Cac\u00e1 Le\u00e3o (PP), ele participa de carreatas em oito munic\u00edpios do Baixo Sul e do M\u00e9dio&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/41625","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=41625"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/41625\/revisions"}],"predecessor-version":[{"id":41626,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/41625\/revisions\/41626"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/38521"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=41625"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=41625"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=41625"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}