{"id":42117,"date":"2022-09-08T10:54:34","date_gmt":"2022-09-08T13:54:34","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=42117"},"modified":"2022-09-08T10:54:37","modified_gmt":"2022-09-08T13:54:37","slug":"onda-azul-toma-conta-da-avenida-e-mostra-a-forca-de-jordavio-ramos-neste-07-de-setembro","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2022\/09\/08\/onda-azul-toma-conta-da-avenida-e-mostra-a-forca-de-jordavio-ramos-neste-07-de-setembro","title":{"rendered":"Onda azul toma conta da avenida e mostra a for\u00e7a de Jord\u00e1vio Ramos neste 07 de setembro"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">O candidato a deputado estadual Jord\u00e1vio Ramos (PSDB), realizou nesta quarta-feira (07), a grande \u2018marcha da renova\u00e7\u00e3o\u2019, onde levou para o circuito dos desfiles da independ\u00eancia em Juazeiro (BA), seu eleitorado, que fez bonito e mostrou sua for\u00e7a para as elei\u00e7\u00f5es.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Acompanhado do deputado federal Adolfo Viana, e da prefeita de Juazeiro Suzana Ramos, Jord\u00e1vio Ramos realizou uma grande festa da democracia. \u201cEsse \u00e9 o resultado que estamos caminhando a passos largos rumo \u00e0 vit\u00f3ria. A emo\u00e7\u00e3o toma conta de mim, ver as pessoas na avenida neste feriad\u00e3o nos acompanhando me motiva demais e esse calor humano vai me conduzir at\u00e9 \u00e0 Assembleia Legislativa da Bahia\u201d, salientou Jord\u00e1vio Ramos.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Isaura Barbosa que estava acompanhando os desfiles de 07 de setembro, disse que se impressionou com a onda azul tomando de conta da avenida. \u201cEu estava acompanhando os desfiles e de repente vi aquele mar de gente vindo tudo vestido de azul, e todos felizes mesmo com o sol escaldante. Isso mostra que as pessoas acreditam em Jord\u00e1vio Ramos\u201d, disse Isaura.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O candidato a deputado estadual Jord\u00e1vio Ramos (PSDB), realizou nesta quarta-feira (07), a grande \u2018marcha da renova\u00e7\u00e3o\u2019, onde levou para o circuito dos desfiles da independ\u00eancia em Juazeiro (BA), seu eleitorado, que fez bonito e mostrou sua for\u00e7a para as elei\u00e7\u00f5es.\u00a0 Acompanhado do deputado federal Adolfo Viana, e da prefeita de Juazeiro Suzana Ramos, Jord\u00e1vio [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":42118,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[199,203],"tags":[1327,4099],"class_list":["post-42117","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bahia","category-juazeiro","tag-eleicoes-2022","tag-jordavio-ramos"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-08-at-02.22.40-1.jpeg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-08-at-02.22.40-1.jpeg",500,333,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-08-at-02.22.40-1-150x150.jpeg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-08-at-02.22.40-1-300x200.jpeg",300,200,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-08-at-02.22.40-1.jpeg",500,333,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-08-at-02.22.40-1.jpeg",500,333,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-08-at-02.22.40-1.jpeg",500,333,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-08-at-02.22.40-1.jpeg",500,333,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-08-at-02.22.40-1.jpeg",500,333,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-08-at-02.22.40-1-420x307.jpeg",420,307,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-08-at-02.22.40-1-300x333.jpeg",300,333,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-08-at-02.22.40-1-464x290.jpeg",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-08-at-02.22.40-1.jpeg",500,333,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-08-at-02.22.40-1-322x230.jpeg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-08-at-02.22.40-1.jpeg",500,333,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"O candidato a deputado estadual Jord\u00e1vio Ramos (PSDB), realizou nesta quarta-feira (07), a grande \u2018marcha da renova\u00e7\u00e3o\u2019, onde levou para o circuito dos desfiles da independ\u00eancia em Juazeiro (BA), seu eleitorado, que fez bonito e mostrou sua for\u00e7a para as elei\u00e7\u00f5es.\u00a0 Acompanhado do deputado federal Adolfo Viana, e da prefeita de Juazeiro Suzana Ramos, Jord\u00e1vio&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/42117","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=42117"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/42117\/revisions"}],"predecessor-version":[{"id":42119,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/42117\/revisions\/42119"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/42118"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=42117"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=42117"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=42117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}