{"id":42698,"date":"2022-09-19T12:38:39","date_gmt":"2022-09-19T15:38:39","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=42698"},"modified":"2022-09-19T12:38:42","modified_gmt":"2022-09-19T15:38:42","slug":"acm-neto-se-consolida-para-vencer-eleicoes-no-primeiro-turno-com-mais-que-o-dobro-de-intencoes-de-votos","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2022\/09\/19\/acm-neto-se-consolida-para-vencer-eleicoes-no-primeiro-turno-com-mais-que-o-dobro-de-intencoes-de-votos","title":{"rendered":"ACM Neto se consolida para vencer elei\u00e7\u00f5es no primeiro turno, com mais que o dobro de inten\u00e7\u00f5es de votos"},"content":{"rendered":"<p style=\"text-align: justify;\">Novo levantamento realizado pelo instituto Paran\u00e1 Pesquisas aponta que o candidato a governador ACM Neto (Uni\u00e3o Brasil) se consolida para vencer as elei\u00e7\u00f5es no primeiro turno. De acordo com a nova pesquisa, divulgada nesta segunda-feira (19) pelo Bahia Not\u00edcias, o ex-prefeito de Salvador aparece com 51,2% das inten\u00e7\u00f5es de voto.<\/p>\n<p style=\"text-align: justify;\">O resultado de ACM Neto \u00e9 o dobro em rela\u00e7\u00e3o ao segundo colocado, Jer\u00f4nimo Rodrigues (PT), que est\u00e1 com 24,5%. Na terceira posi\u00e7\u00e3o aparece Jo\u00e3o Roma (PL), com 10,4%. Os demais postulantes, somados, t\u00eam 2,5%.<\/p>\n<p style=\"text-align: justify;\">Levando em considera\u00e7\u00e3o os votos v\u00e1lidos, a vantagem de Neto \u00e9 ainda maior. Neste cen\u00e1rio, o candidato do Uni\u00e3o Brasil chega a aproximadamente 58%, enquanto o ex-secret\u00e1rio da Educa\u00e7\u00e3o do estado aparece com 27,7% &#8211; diferen\u00e7a de mais de 30 pontos percentuais.<\/p>\n<p style=\"text-align: justify;\">No cen\u00e1rio espont\u00e2neo, quando n\u00e3o s\u00e3o apresentados os nomes dos candidatos, a pesquisa mostra que ACM Neto mant\u00e9m o dobro de vantagem para o candidato do PT. O ex-prefeito de Salvador aparece com 31,5% contra 14% de Jer\u00f4nimo.<\/p>\n<p style=\"text-align: justify;\">A pesquisa ouviu 1540 eleitores em 70 munic\u00edpios baianos entre os dias 14 e 18 de setembro de 2022. O levantamento tem margem de erro de 2,5% e um intervalo de confian\u00e7a de 95%. A pesquisa est\u00e1 registrada na Justi\u00e7a Eleitoral com o n\u00famero BA-02288\/2022.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Novo levantamento realizado pelo instituto Paran\u00e1 Pesquisas aponta que o candidato a governador ACM Neto (Uni\u00e3o Brasil) se consolida para vencer as elei\u00e7\u00f5es no primeiro turno. De acordo com a nova pesquisa, divulgada nesta segunda-feira (19) pelo Bahia Not\u00edcias, o ex-prefeito de Salvador aparece com 51,2% das inten\u00e7\u00f5es de voto. O resultado de ACM Neto [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":42699,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[199,10109],"tags":[1705,2010],"class_list":["post-42698","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bahia","category-eleicoes-2022","tag-acm-neto","tag-deputado-federal"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-19-at-08.27.00.jpeg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-19-at-08.27.00.jpeg",500,333,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-19-at-08.27.00-150x150.jpeg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-19-at-08.27.00-300x200.jpeg",300,200,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-19-at-08.27.00.jpeg",500,333,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-19-at-08.27.00.jpeg",500,333,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-19-at-08.27.00.jpeg",500,333,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-19-at-08.27.00.jpeg",500,333,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-19-at-08.27.00.jpeg",500,333,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-19-at-08.27.00-420x307.jpeg",420,307,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-19-at-08.27.00-300x333.jpeg",300,333,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-19-at-08.27.00-464x290.jpeg",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-19-at-08.27.00.jpeg",500,333,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-19-at-08.27.00-322x230.jpeg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/09\/WhatsApp-Image-2022-09-19-at-08.27.00.jpeg",500,333,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"Novo levantamento realizado pelo instituto Paran\u00e1 Pesquisas aponta que o candidato a governador ACM Neto (Uni\u00e3o Brasil) se consolida para vencer as elei\u00e7\u00f5es no primeiro turno. De acordo com a nova pesquisa, divulgada nesta segunda-feira (19) pelo Bahia Not\u00edcias, o ex-prefeito de Salvador aparece com 51,2% das inten\u00e7\u00f5es de voto. O resultado de ACM Neto&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/42698","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=42698"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/42698\/revisions"}],"predecessor-version":[{"id":42700,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/42698\/revisions\/42700"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/42699"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=42698"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=42698"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=42698"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}