{"id":43739,"date":"2022-10-08T19:11:40","date_gmt":"2022-10-08T22:11:40","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=43739"},"modified":"2022-10-08T19:11:42","modified_gmt":"2022-10-08T22:11:42","slug":"prefeito-wilker-se-afirma-como-o-prefeito-de-maior-lideranca-regional-do-norte-da-bahia","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2022\/10\/08\/prefeito-wilker-se-afirma-como-o-prefeito-de-maior-lideranca-regional-do-norte-da-bahia","title":{"rendered":"Prefeito Wilker se afirma como o prefeito de maior lideran\u00e7a regional do Norte da Bahia"},"content":{"rendered":"<p style=\"text-align: justify;\">As elei\u00e7\u00f5es realizadas no \u00faltimo dia 02 de outubro em todo o Brasil deram visibilidade regional, estadual e at\u00e9 nacional a diversas lideran\u00e7as antes confinadas aos seus munic\u00edpios e ou comunidades.<\/p>\n<p style=\"text-align: justify;\">H\u00e1 casos de lideran\u00e7as que n\u00e3o foram candidatos, mas tiveram papel preponderante na regi\u00e3o onde atuam. O exemplo mais pr\u00f3ximo e de maior visibilidade na regi\u00e3o norte da Bahia, mais precisamente os munic\u00edpios que comp\u00f5em a \u00e1rea do Lago de Sobradinho e Juazeiro, \u00e9 sem sombras de d\u00favidas o Prefeito de Casa Nova, Wilker Torres.<\/p>\n<p style=\"text-align: justify;\">Mentor da candidatura do irm\u00e3o, Tum a deputado federal; assumindo a miss\u00e3o de barrar o crescimento da oposi\u00e7\u00e3o na regi\u00e3o, Wilker Torres conseguiu fa\u00e7anhas eleitorais dignas de registro.<\/p>\n<p style=\"text-align: justify;\">A primeira destas proezas foi dar ao irm\u00e3o Tum, 65% dos votos v\u00e1lidos em Casa Nova, isso depois de reeleger-se e sofrer bombardeio di\u00e1rio da oposi\u00e7\u00e3o por 5 anos e 10 meses.<\/p>\n<p style=\"text-align: justify;\">A maior cidade da regi\u00e3o, Juazeiro, onde a prefeita patrocinou a candidatura do filho, Jord\u00e1vio Ramos, com toda a m\u00e1quina funcionando, obteve 31 por cento dos votos.<\/p>\n<p style=\"text-align: justify;\">Dos candidatos que se declararam juazeirenses, o Coronel Anselmo teve 1,2 por cento dos votos e Joseph Bandeira, pouco mais de 8 por cento.<\/p>\n<p style=\"text-align: justify;\">Elmar Nascimento tem seu ber\u00e7o pol\u00edtico em Campo Formoso, est\u00e1 no exerc\u00edcio de seu quarto mandato de deputado federal, \u201cdono\u201d da 6\u00aa Superintend\u00eancia da CODEVASF, que atua em todas os munic\u00edpios da regi\u00e3o, benefici\u00e1rio de milh\u00f5es em emendas do Or\u00e7amento secreto, s\u00f3 conseguiu ter presen\u00e7a efetiva em Campo Formoso, onde o irm\u00e3o \u00e9 prefeito: 40 por cento, longe dos 65 dados a Tum em Casa Nova.<\/p>\n<p style=\"text-align: justify;\">Wilker marcou presen\u00e7a em Remanso, onde Tum conseguiu 19 por cento dos votos; Pil\u00e3o Arcado Tum foi a 10 por cento dos votos v\u00e1lidos e em Sento S\u00e9, 11 por cento.<\/p>\n<p style=\"text-align: justify;\">Por pouco mais de 5 mil votos Tum n\u00e3o ultrapassou o \u00fanico candidato eleito de seu partido o AVANTE, tornando-se o \u00fanico deputado federal da regi\u00e3o do Lago de Sobradinho, Norte da Bahia. Em compensa\u00e7\u00e3o seu irm\u00e3o, Wilker Torres, sai da elei\u00e7\u00e3o com uma estatura muito maior, reconhecido em toda regi\u00e3o como um l\u00edder que tem voto.<\/p>\n<p style=\"text-align: justify;\">Os n\u00fameros falam por si.<\/p>\n<p style=\"text-align: justify;\">Ascom<\/p>\n","protected":false},"excerpt":{"rendered":"<p>As elei\u00e7\u00f5es realizadas no \u00faltimo dia 02 de outubro em todo o Brasil deram visibilidade regional, estadual e at\u00e9 nacional a diversas lideran\u00e7as antes confinadas aos seus munic\u00edpios e ou comunidades. H\u00e1 casos de lideran\u00e7as que n\u00e3o foram candidatos, mas tiveram papel preponderante na regi\u00e3o onde atuam. O exemplo mais pr\u00f3ximo e de maior visibilidade [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":25453,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[199,10109],"tags":[],"class_list":["post-43739","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bahia","category-eleicoes-2022"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/07\/Wilker-e-Tum-em-brasilia.jpeg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/07\/Wilker-e-Tum-em-brasilia.jpeg",500,397,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/07\/Wilker-e-Tum-em-brasilia-150x150.jpeg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/07\/Wilker-e-Tum-em-brasilia-300x238.jpeg",300,238,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/07\/Wilker-e-Tum-em-brasilia.jpeg",500,397,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/07\/Wilker-e-Tum-em-brasilia.jpeg",500,397,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/07\/Wilker-e-Tum-em-brasilia.jpeg",500,397,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/07\/Wilker-e-Tum-em-brasilia.jpeg",500,397,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/07\/Wilker-e-Tum-em-brasilia.jpeg",500,397,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/07\/Wilker-e-Tum-em-brasilia-420x307.jpeg",420,307,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/07\/Wilker-e-Tum-em-brasilia-300x397.jpeg",300,397,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/07\/Wilker-e-Tum-em-brasilia-464x290.jpeg",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/07\/Wilker-e-Tum-em-brasilia.jpeg",500,397,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/07\/Wilker-e-Tum-em-brasilia-322x230.jpeg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/07\/Wilker-e-Tum-em-brasilia.jpeg",500,397,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"As elei\u00e7\u00f5es realizadas no \u00faltimo dia 02 de outubro em todo o Brasil deram visibilidade regional, estadual e at\u00e9 nacional a diversas lideran\u00e7as antes confinadas aos seus munic\u00edpios e ou comunidades. H\u00e1 casos de lideran\u00e7as que n\u00e3o foram candidatos, mas tiveram papel preponderante na regi\u00e3o onde atuam. O exemplo mais pr\u00f3ximo e de maior visibilidade&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/43739","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=43739"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/43739\/revisions"}],"predecessor-version":[{"id":43740,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/43739\/revisions\/43740"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/25453"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=43739"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=43739"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=43739"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}