{"id":43847,"date":"2022-10-11T15:45:00","date_gmt":"2022-10-11T18:45:00","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=43847"},"modified":"2022-10-11T09:58:39","modified_gmt":"2022-10-11T12:58:39","slug":"programacao-da-tv-escola-juazeiro-apresentara-historia-de-pontos-turisticos-em-comunidades-da-cidade-e-producoes-ja-podem-ser-enviadas","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2022\/10\/11\/programacao-da-tv-escola-juazeiro-apresentara-historia-de-pontos-turisticos-em-comunidades-da-cidade-e-producoes-ja-podem-ser-enviadas","title":{"rendered":"Programa\u00e7\u00e3o da TV Escola Juazeiro apresentar\u00e1 hist\u00f3ria de \u2018pontos tur\u00edsticos\u2019 em comunidades da cidade e produ\u00e7\u00f5es j\u00e1 podem ser enviadas"},"content":{"rendered":"<p style=\"text-align: justify;\">Com o objetivo de valorizar a cultura de Juazeiro, a partir do olhar dos estudantes da rede municipal de ensino, a TV Escola Juazeiro ir\u00e1 exibir o programa \u201cExpedi\u00e7\u00f5es Juazeiro\u201d. A programa\u00e7\u00e3o contar\u00e1 com a apresenta\u00e7\u00e3o de pontos da cidade conhecidos pelos alunos e que representam a identidade do lugar. O per\u00edodo para envio dos v\u00eddeos para veicula\u00e7\u00e3o no programa, que ir\u00e1 integrar a Col\u00f4nia de F\u00e9rias, j\u00e1 est\u00e1 aberto e segue at\u00e9 o dia 30 de novembro.<\/p>\n<p style=\"text-align: justify;\">A ideia \u00e9 que os alunos da rede municipal apresentem um local interessante em sua comunidade e contem a hist\u00f3ria desse ponto. Os v\u00eddeos devem ser gravados na horizontal (celular deitado), ter no m\u00e1ximo 5 minutos de dura\u00e7\u00e3o e ser identificados com o nome do aluno e da unidade de ensino em que ele est\u00e1 matriculado. Para veicula\u00e7\u00e3o do v\u00eddeo na TV Escola Juazeiro, \u00e9 necess\u00e1rio a assinatura dos pais ou respons\u00e1veis, no Termo de Autoriza\u00e7\u00e3o de Uso de Imagem, dispon\u00edvel nas escolas municipais e tamb\u00e9m atrav\u00e9s do contato para envio dos v\u00eddeos.\u00a0 As produ\u00e7\u00f5es devem ser enviadas para o whatsapp (74) 9999- 7272.<\/p>\n<p style=\"text-align: justify;\">A data de exibi\u00e7\u00e3o do quadro \u201cSeu Talento na TV\u201d e toda a programa\u00e7\u00e3o da \u201cCol\u00f4nia de F\u00e9rias\u201d, ser\u00e1 divulgada posteriormente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Com o objetivo de valorizar a cultura de Juazeiro, a partir do olhar dos estudantes da rede municipal de ensino, a TV Escola Juazeiro ir\u00e1 exibir o programa \u201cExpedi\u00e7\u00f5es Juazeiro\u201d. A programa\u00e7\u00e3o contar\u00e1 com a apresenta\u00e7\u00e3o de pontos da cidade conhecidos pelos alunos e que representam a identidade do lugar. O per\u00edodo para envio dos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":43848,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[209,203],"tags":[6473,340],"class_list":["post-43847","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacao","category-juazeiro","tag-educacao-municipal-de-juazeiro","tag-prefeitura-de-juazeiro"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/10\/Rodeadouro.jpg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/10\/Rodeadouro.jpg",500,281,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/10\/Rodeadouro-150x150.jpg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/10\/Rodeadouro-300x169.jpg",300,169,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/10\/Rodeadouro.jpg",500,281,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/10\/Rodeadouro.jpg",500,281,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/10\/Rodeadouro.jpg",500,281,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/10\/Rodeadouro.jpg",500,281,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/10\/Rodeadouro.jpg",500,281,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/10\/Rodeadouro-420x281.jpg",420,281,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/10\/Rodeadouro-300x281.jpg",300,281,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/10\/Rodeadouro-464x281.jpg",464,281,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/10\/Rodeadouro.jpg",500,281,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/10\/Rodeadouro-322x230.jpg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/10\/Rodeadouro.jpg",500,281,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"Com o objetivo de valorizar a cultura de Juazeiro, a partir do olhar dos estudantes da rede municipal de ensino, a TV Escola Juazeiro ir\u00e1 exibir o programa \u201cExpedi\u00e7\u00f5es Juazeiro\u201d. A programa\u00e7\u00e3o contar\u00e1 com a apresenta\u00e7\u00e3o de pontos da cidade conhecidos pelos alunos e que representam a identidade do lugar. O per\u00edodo para envio dos&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/43847","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=43847"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/43847\/revisions"}],"predecessor-version":[{"id":43849,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/43847\/revisions\/43849"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/43848"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=43847"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=43847"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=43847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}