{"id":44610,"date":"2022-10-26T17:38:00","date_gmt":"2022-10-26T20:38:00","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=44610"},"modified":"2022-10-26T09:18:50","modified_gmt":"2022-10-26T12:18:50","slug":"violencia-de-roberto-jefferson-vai-reabrir-a-discussao-sobre-cacs","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2022\/10\/26\/violencia-de-roberto-jefferson-vai-reabrir-a-discussao-sobre-cacs","title":{"rendered":"Viol\u00eancia de Roberto Jefferson vai reabrir a discuss\u00e3o sobre CACs"},"content":{"rendered":"<p style=\"text-align: justify;\">O caso Roberto Jefferson (PTB) reabrir\u00e1 a discuss\u00e3o pelo aperto na fiscaliza\u00e7\u00e3o das armas dos CAC\u2019s (Colecionador, Atirador Desportivo e Ca\u00e7ador) no Congresso. Depois que Roberto Jefferson atingiu policiais que foram prend\u00ea-lo no \u00faltimo domingo, as associa\u00e7\u00f5es e federa\u00e7\u00f5es de policiais federais querem promover esse debate. A avalia\u00e7\u00e3o \u00e9 a de que h\u00e1 um ponto cego entre o que deve ser fiscalizado pelo Ex\u00e9rcito e pela PF. N\u00e3o d\u00e1, por exemplo, para um sujeito sob investiga\u00e7\u00e3o e em pris\u00e3o domiciliar, como era o caso de Jefferson, manter granadas em casa. A ideia \u00e9 n\u00e3o esperar sequer a chegada de 2023.<\/p>\n<p style=\"text-align: justify;\">\u00bb \u00bb \u00bb<\/p>\n<p style=\"text-align: justify;\">Falta combinar com uma parte expressiva da bancada do governo, que ampliou o acesso \u00e0s armas. Por\u00e9m, depois de dois policiais feridos, a <a href=\"https:\/\/www.correiobraziliense.com.br\/politica\/2022\/10\/5046696-bancada-da-bala-elege-103-representantes-nas-eleicoes-dois-sao-do-df.html\"><strong>bancada da bala<\/strong><\/a>, formada basicamente por representantes da categoria, tende a apoiar uma lei mais clara e mais rigorosa na fiscaliza\u00e7\u00e3o e puni\u00e7\u00e3o.<\/p>\n<h3 style=\"text-align: justify;\">O foco \u00e9 a economia<\/h3>\n<p style=\"text-align: justify;\">Nesses \u00faltimos dias, a campanha de Lula pretende centrar o foco na economia para sair da armadilha do discurso de costumes que centralizou o debate nas primeiras semanas desse segundo turno. A avalia\u00e7\u00e3o \u00e9 a de que, se Lula conseguir colar em Bolsonaro a imagem de que \u00e9 um candidato a servi\u00e7o do mercado, a fim de cortar benef\u00edcios dos trabalhadores, o petista consegue reduzir a diferen\u00e7a em S\u00e3o Paulo.<\/p>\n<p style=\"text-align: justify;\"><strong>\u2026 e a coaliz\u00e3o<br \/>\n<\/strong>Lula tem dito a todos os interlocutores e em entrevistas, que seu governo n\u00e3o ser\u00e1 uma administra\u00e7\u00e3o do PT. Vem na linha de tentar quebrar a resist\u00eancia ao partido, que, embora tenha uma legi\u00e3o de seguidores, tamb\u00e9m tem uma grande rejei\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\"><strong>Recordar \u00e9 viver<br \/>\n<\/strong>A turma de Bolsonaro continuar\u00e1 na linha da m\u00e1 gest\u00e3o dos fundos de pens\u00e3o, como a entrevista com aposentado exibida no hor\u00e1rio eleitoral, o discurso das igrejas e na tecla de que Lula n\u00e3o foi inocentado. Apostar\u00e1 ainda na tese de que quem concedeu o Aux\u00edlio Brasil de R$ 600 \u00e9 quem ter\u00e1 condi\u00e7\u00f5es de manter esse valor.<\/p>\n<p style=\"text-align: justify;\"><strong>A prova de fogo das pesquisas<br \/>\n<\/strong>Quem estuda a fundo todas as pesquisas de inten\u00e7\u00e3o de voto, caso da Vector Consultoria, fez um levantamento das pesquisas dispon\u00edveis em 15 estados para mostrar a seus clientes que, nessas semanas em que o debate esteve centrado na pauta de costumes, o presidente Jair Bolsonaro ampliou mais as suas inten\u00e7\u00f5es de voto do que Lula. Portanto, avalia a Vector, a elei\u00e7\u00e3o, a pre\u00e7os de hoje, est\u00e1 empatada.<\/p>\n<p style=\"text-align: justify;\"><strong>Zema na \u00e1rea\/<\/strong> Quem colocou na roda o tema das aposentadorias e dos fundos de pens\u00e3o das estatais foi o governador reeleito de Minas Gerais, Romeu Zema, que est\u00e1 trabalhando os munic\u00edpios mineiros em favor da reelei\u00e7\u00e3o de Bolsonaro.<\/p>\n<p style=\"text-align: justify;\"><strong>Eles querem \u00e9 espa\u00e7o\/<\/strong> Parlamentares do Uni\u00e3o Brasil e do PP descartam uma fus\u00e3o. Ou v\u00e3o partir para uma federa\u00e7\u00e3o, ou ficar\u00e3o no bloco parlamentar. A tend\u00eancia hoje \u00e9 o bloco que, tradicionalmente, n\u00e3o tem tirado espa\u00e7o de lideran\u00e7a dos partidos integrantes.<\/p>\n<p style=\"text-align: justify;\"><strong>Por falar em federa\u00e7\u00e3o\u2026\/<\/strong> Alguns aliados do presidente da C\u00e2mara, Arthur Lira, j\u00e1 pediram aos partidos que fa\u00e7am uma an\u00e1lise do regimento da C\u00e2mara \u00e0 luz da institui\u00e7\u00e3o das federa\u00e7\u00f5es partid\u00e1rias. A inten\u00e7\u00e3o \u00e9 avaliar se d\u00e1 para tratar cada partido da federa\u00e7\u00e3o isoladamente na hora de distribuir as comiss\u00f5es t\u00e9cnicas da Casa.<\/p>\n<p style=\"text-align: justify;\"><strong>Cad\u00ea o Power Point?\/<\/strong> A entrevista de F\u00e1bio Wajngarten e do ministro F\u00e1bio Faria na porta do Alvorada para denunciar que r\u00e1dios estariam colocando mais inser\u00e7\u00f5es para Lula do que para Bolsonaro deixou a desejar. Faltou um kit para a imprensa, com detalhes sobre as 154 mil inser\u00e7\u00f5es a mais que Lula teria tido neste segundo turno, gr\u00e1ficos e o nome das r\u00e1dios que burlaram a legisla\u00e7\u00e3o eleitoral. N\u00e3o houve um material explicativo para a grave den\u00fancia. Ali\u00e1s, a porta do Alvorada tamb\u00e9m n\u00e3o \u00e9 um comit\u00ea de campanha, n\u00e9?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O caso Roberto Jefferson (PTB) reabrir\u00e1 a discuss\u00e3o pelo aperto na fiscaliza\u00e7\u00e3o das armas dos CAC\u2019s (Colecionador, Atirador Desportivo e Ca\u00e7ador) no Congresso. Depois que Roberto Jefferson atingiu policiais que foram prend\u00ea-lo no \u00faltimo domingo, as associa\u00e7\u00f5es e federa\u00e7\u00f5es de policiais federais querem promover esse debate. A avalia\u00e7\u00e3o \u00e9 a de que h\u00e1 um ponto [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":44611,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[10104],"tags":[14,1264,1559],"class_list":["post-44610","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-violencia","tag-brasil","tag-policial","tag-politica-2"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/10\/denise_ilustracao-8-550x334-1.jpg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/10\/denise_ilustracao-8-550x334-1.jpg",500,303,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/10\/denise_ilustracao-8-550x334-1-150x150.jpg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/10\/denise_ilustracao-8-550x334-1-300x182.jpg",300,182,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/10\/denise_ilustracao-8-550x334-1.jpg",500,303,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/10\/denise_ilustracao-8-550x334-1.jpg",500,303,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/10\/denise_ilustracao-8-550x334-1.jpg",500,303,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/10\/denise_ilustracao-8-550x334-1.jpg",500,303,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/10\/denise_ilustracao-8-550x334-1.jpg",500,303,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/10\/denise_ilustracao-8-550x334-1-420x303.jpg",420,303,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/10\/denise_ilustracao-8-550x334-1-300x303.jpg",300,303,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/10\/denise_ilustracao-8-550x334-1-464x290.jpg",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/10\/denise_ilustracao-8-550x334-1.jpg",500,303,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/10\/denise_ilustracao-8-550x334-1-322x230.jpg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2022\/10\/denise_ilustracao-8-550x334-1.jpg",500,303,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"O caso Roberto Jefferson (PTB) reabrir\u00e1 a discuss\u00e3o pelo aperto na fiscaliza\u00e7\u00e3o das armas dos CAC\u2019s (Colecionador, Atirador Desportivo e Ca\u00e7ador) no Congresso. Depois que Roberto Jefferson atingiu policiais que foram prend\u00ea-lo no \u00faltimo domingo, as associa\u00e7\u00f5es e federa\u00e7\u00f5es de policiais federais querem promover esse debate. A avalia\u00e7\u00e3o \u00e9 a de que h\u00e1 um ponto&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/44610","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=44610"}],"version-history":[{"count":1,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/44610\/revisions"}],"predecessor-version":[{"id":44612,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/44610\/revisions\/44612"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/44611"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=44610"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=44610"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=44610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}