{"id":46647,"date":"2022-12-04T13:12:00","date_gmt":"2022-12-04T16:12:00","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=46647"},"modified":"2022-12-03T21:15:34","modified_gmt":"2022-12-04T00:15:34","slug":"mp-eleitoral-pede-aprovacao-das-contas-da-chapa-de-lula-e-alckmin","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2022\/12\/04\/mp-eleitoral-pede-aprovacao-das-contas-da-chapa-de-lula-e-alckmin","title":{"rendered":"MP Eleitoral pede aprova\u00e7\u00e3o das contas da chapa de Lula e Alckmin"},"content":{"rendered":"<p style=\"text-align: justify;\">O Minist\u00e9rio P\u00fablico Eleitoral considerou que a\u00a0<a href=\"https:\/\/www.metropoles.com\/colunas\/igor-gadelha\/os-cinco-nomes-ja-considerados-certos-para-o-ministerio-de-lula\" target=\"_blank\" rel=\"noopener\">chapa de Luiz In\u00e1cio Lula da Silva (PT) e Geraldo Alckmin (PSB)<\/a> \u00e0 presid\u00eancia da Rep\u00fablica comprovou gastos de campanha que haviam sido questionados no Tribunal Superior Eleitoral (TSE). Com isso, o MPE se manifestou pela aprova\u00e7\u00e3o das contas da chapa, que venceu a elei\u00e7\u00e3o em segundo turno no \u00faltimo dia 30 de outubro.<\/p>\n<p style=\"text-align: justify;\" data-gtm-vis-recent-on-screen-8752935_845=\"53382\" data-gtm-vis-first-on-screen-8752935_845=\"53383\" data-gtm-vis-total-visible-time-8752935_845=\"100\" data-gtm-vis-has-fired-8752935_845=\"1\">A \u00e1rea t\u00e9cnica do TSE\u00a0<a href=\"https:\/\/www.metropoles.com\/brasil\/lula-tera-que-explicar-ao-tse-inconsistencias-de-r-620-mil-em-contas\" target=\"_blank\" rel=\"noopener\">havia identificado inconsist\u00eancias na presta\u00e7\u00e3o de contas da chapa, que totalizavam R$ 620 mil em pend\u00eancias<\/a>. Com isso, o vice-presidente da Corte, ministro Ricardo Lewandowski, deu tr\u00eas dias para que a campanha se explicasse, o que\u00a0<a href=\"https:\/\/www.metropoles.com\/brasil\/lula-responde-tse-sobre-questionamento-de-r-620-mil-em-contas-eleitorais\" target=\"_blank\" rel=\"noopener\">foi feito na \u00faltima quarta (30\/11)<\/a>.<\/p>\n<p style=\"text-align: justify;\">Neste s\u00e1bado (03\/12), vice-procurador-geral eleitoral, Paulo Gonet, se manifestou por parte do MP Eleitoral, considerando as explica\u00e7\u00f5es satisfat\u00f3rias e recomendando a aprova\u00e7\u00e3o das contas. A decis\u00e3o de aprovar ou n\u00e3o, por\u00e9m, ainda ser\u00e1 tomada pelos ministros do TSE. A manifesta\u00e7\u00e3o do MP Eleitoral \u00e9 um dos elementos levados em conta nessa decis\u00e3o.<\/p>\n<p style=\"text-align: justify;\">Ao todo, a campanha de Lula e Alckmin declarou gastos de R$ 131,3 milh\u00f5es nestas elei\u00e7\u00f5es.<img decoding=\"async\" id=\"clever-41487-cube-overlay\" style=\"color: initial;\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAP\/\/\/wAAACH5BAEAAAAALAAAAAABAAEAAAICRAEAOw==\" alt=\"overlay-clever\" \/><\/p>\n<p style=\"text-align: justify;\" data-gtm-vis-recent-on-screen-8752935_866=\"94075\" data-gtm-vis-first-on-screen-8752935_866=\"94075\" data-gtm-vis-total-visible-time-8752935_866=\"100\" data-gtm-vis-has-fired-8752935_866=\"1\" data-gtm-vis-recent-on-screen-8752935_862=\"94077\" data-gtm-vis-first-on-screen-8752935_862=\"94077\" data-gtm-vis-total-visible-time-8752935_862=\"100\" data-gtm-vis-has-fired-8752935_862=\"1\">O TSE j\u00e1 marcou a diploma\u00e7\u00e3o da chapa, que ser\u00e1 no pr\u00f3ximo dia 12 de dezembro. A posse de Lula e Alckmin como presidente e vice ser\u00e1 em 1\u00ba de janeiro de 2023. Eles foram eleitos para um mandato de quatro anos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Minist\u00e9rio P\u00fablico Eleitoral considerou que a\u00a0chapa de Luiz In\u00e1cio Lula da Silva (PT) e Geraldo Alckmin (PSB) \u00e0 presid\u00eancia da Rep\u00fablica comprovou gastos de campanha que haviam sido questionados no Tribunal Superior Eleitoral (TSE). Com isso, o MPE se manifestou pela aprova\u00e7\u00e3o das contas da chapa, que venceu a elei\u00e7\u00e3o em segundo turno no [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":30353,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[200,197],"tags":[],"class_list":["post-46647","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-brasil","category-politica"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/11\/lula-geraldo-alckmin.jpg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/11\/lula-geraldo-alckmin.jpg",500,370,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/11\/lula-geraldo-alckmin-150x150.jpg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/11\/lula-geraldo-alckmin-300x222.jpg",300,222,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/11\/lula-geraldo-alckmin.jpg",500,370,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/11\/lula-geraldo-alckmin.jpg",500,370,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/11\/lula-geraldo-alckmin.jpg",500,370,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/11\/lula-geraldo-alckmin.jpg",500,370,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/11\/lula-geraldo-alckmin.jpg",500,370,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/11\/lula-geraldo-alckmin-420x307.jpg",420,307,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/11\/lula-geraldo-alckmin-300x370.jpg",300,370,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/11\/lula-geraldo-alckmin-464x290.jpg",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/11\/lula-geraldo-alckmin.jpg",500,370,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/11\/lula-geraldo-alckmin-322x230.jpg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2021\/11\/lula-geraldo-alckmin.jpg",500,370,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"O Minist\u00e9rio P\u00fablico Eleitoral considerou que a\u00a0chapa de Luiz In\u00e1cio Lula da Silva (PT) e Geraldo Alckmin (PSB) \u00e0 presid\u00eancia da Rep\u00fablica comprovou gastos de campanha que haviam sido questionados no Tribunal Superior Eleitoral (TSE). Com isso, o MPE se manifestou pela aprova\u00e7\u00e3o das contas da chapa, que venceu a elei\u00e7\u00e3o em segundo turno no&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/46647","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=46647"}],"version-history":[{"count":2,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/46647\/revisions"}],"predecessor-version":[{"id":46649,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/46647\/revisions\/46649"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/30353"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=46647"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=46647"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=46647"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}