{"id":47154,"date":"2022-12-13T15:59:00","date_gmt":"2022-12-13T18:59:00","guid":{"rendered":"https:\/\/blogopara.com.br\/?p=47154"},"modified":"2022-12-12T19:20:45","modified_gmt":"2022-12-12T22:20:45","slug":"empresa-americana-devolve-dinheiro-ao-governo-da-bahia-referente-a-compra-de-respiradores-nao-recebidos","status":"publish","type":"post","link":"https:\/\/blogopara.com.br\/index.php\/2022\/12\/13\/empresa-americana-devolve-dinheiro-ao-governo-da-bahia-referente-a-compra-de-respiradores-nao-recebidos","title":{"rendered":"Empresa americana devolve dinheiro ao Governo da Bahia referente \u00e0 compra de respiradores n\u00e3o recebidos"},"content":{"rendered":"<p class=\"bodytext\" style=\"text-align: justify;\">A empresa norte-americana Ocean 26 Inc, que negociou a venda de 600 respiradores com o Governo do Estado no in\u00edcio da pandemia da covid-19,\u00a0em 2020,\u00a0devolveu o dinheiro da compra ao Governo da Bahia\u00a0ap\u00f3s acordo judicial celebrado e homologado pelo Tribunal Distrital dos Estados Unidos do Distrito Central da Calif\u00f3rnia. O dinheiro ressarcido j\u00e1 est\u00e1 em caixa e poder\u00e1 ser utilizado para realizar novos investimentos na \u00e1rea da sa\u00fade.<\/p>\n<p class=\"bodytext\" style=\"text-align: justify;\">A compra foi realizada pelo Estado\u00a0em mar\u00e7o de 2020, e a entrega dos equipamentos deveria ter sido feita em abril do mesmo ano. Como ocorria em todo o mundo, o governo baiano antecipou parte do valor do pagamento, cerca de U$ 8,4 milh\u00f5es, mas os respiradores nunca foram entregues, fato que motivou a a\u00e7\u00e3o judicial contra a empresa perante a justi\u00e7a americana.<\/p>\n<div class=\"single-publicidade\" style=\"text-align: justify;\">\n<div id=\"minhabahia_300x250_01\"><span style=\"font-size: revert; color: initial;\">De acordo com a Procuradoria Geral do Estado (PGE), a decis\u00e3o judicial favor\u00e1vel \u00e0 Bahia n\u00e3o impedir\u00e1 a continua\u00e7\u00e3o de outras medidas a serem adotadas de responsabiliza\u00e7\u00e3o. Por decis\u00e3o da justi\u00e7a dos Estados Unidos, est\u00e1 vedada a divulga\u00e7\u00e3o p\u00fablica integral do acordo, gravado por cl\u00e1usula de confidencialidade estabelecida pela lei americana, apenas excetuada pelas informa\u00e7\u00f5es obrigat\u00f3rias a prestar aos \u00f3rg\u00e3os de controle, como o TCE.<\/span><\/div>\n<div>\u00a0<\/div>\n<\/div>\n<h4 class=\"bodytext\" style=\"text-align: justify;\"><strong>Pulsar e Hempcare<\/strong><\/h4>\n<p class=\"bodytext\" style=\"text-align: justify;\">Em 2020, o Governo do Estado j\u00e1 havia conquistado a primeira vit\u00f3ria contra as tr\u00eas empresas que n\u00e3o cumpriram os contratos celebrados durante o enfrentamento da Covid-19. Em junho daquele ano, a empresa Pulsar devolveu ao Cons\u00f3rcio Nordeste o valor de US$ 7,9 milh\u00f5es, referentes \u00e0 aquisi\u00e7\u00e3o de 750 respiradores. A Pulsar n\u00e3o conseguiu cumprir o prazo de entrega dos equipamentos, e o governador Rui Costa, que presidia o cons\u00f3rcio \u00e0 \u00e9poca, solicitou a imediata devolu\u00e7\u00e3o dos recursos investidos.<\/p>\n<p class=\"bodytext\" style=\"text-align: justify;\">A empresa Hempcare \u00e9 a \u00fanica que ainda n\u00e3o efetivou a devolu\u00e7\u00e3o dos recursos antecipados pelo Governo do Estado. O contrato para compra de 300 respiradores foi assinado em abril de 2020 e exigiu a antecipa\u00e7\u00e3o de R$ 49 milh\u00f5es. A empresa, que n\u00e3o cumpriu o prazo de entrega estabelecido, se recusou a devolver o dinheiro alegando ter utilizado os recursos para pagamento a um fabricante chin\u00eas.<\/p>\n<p class=\"bodytext\" style=\"text-align: justify;\">Com o descumprimento do contrato, o Governo do Estado decidiu acionar as autoridades policiais, apresentando den\u00fancia \u00e0 Secretaria da Seguran\u00e7a P\u00fablica da Bahia (SSP). Os representantes da empresa tiveram bens bloqueados e foram presos durante Opera\u00e7\u00e3o Ragnarok, da Pol\u00edcia Civil da Bahia. Ap\u00f3s a a\u00e7\u00e3o do Governo do Estado, o Minist\u00e9rio P\u00fablico Federal (MPF) instaurou inqu\u00e9rito e assumiu a apura\u00e7\u00e3o do caso. Os acusados aguardam a conclus\u00e3o da investiga\u00e7\u00e3o em liberdade, e o dinheiro ainda n\u00e3o foi devolvido. O Governo tamb\u00e9m iniciou a\u00e7\u00e3o judicial para recupera\u00e7\u00e3o do valor e, no ano passado, chegou a entrar com representa\u00e7\u00e3o perante o Conselho Nacional de Justi\u00e7a (CNJ) para tentar conferir agilidade ao processo, obtendo decis\u00e3o favor\u00e1vel.<\/p>\n<p>Fonte: Jornal Correio<\/p>\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A empresa norte-americana Ocean 26 Inc, que negociou a venda de 600 respiradores com o Governo do Estado no in\u00edcio da pandemia da covid-19,\u00a0em 2020,\u00a0devolveu o dinheiro da compra ao Governo da Bahia\u00a0ap\u00f3s acordo judicial celebrado e homologado pelo Tribunal Distrital dos Estados Unidos do Distrito Central da Calif\u00f3rnia. O dinheiro ressarcido j\u00e1 est\u00e1 em [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":12535,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[199],"tags":[],"class_list":["post-47154","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bahia"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/07\/Portal-Acesse-Pol\u00edtica-O-site-de-pol\u00edtica-que-mais-cresce-na-Bahia-acessepolitica.com_.br-respiradores-coronavirus-2.jpg","uagb_featured_image_src":{"full":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/07\/Portal-Acesse-Pol\u00edtica-O-site-de-pol\u00edtica-que-mais-cresce-na-Bahia-acessepolitica.com_.br-respiradores-coronavirus-2.jpg",500,333,false],"thumbnail":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/07\/Portal-Acesse-Pol\u00edtica-O-site-de-pol\u00edtica-que-mais-cresce-na-Bahia-acessepolitica.com_.br-respiradores-coronavirus-2-150x150.jpg",150,150,true],"medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/07\/Portal-Acesse-Pol\u00edtica-O-site-de-pol\u00edtica-que-mais-cresce-na-Bahia-acessepolitica.com_.br-respiradores-coronavirus-2-300x200.jpg",300,200,true],"medium_large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/07\/Portal-Acesse-Pol\u00edtica-O-site-de-pol\u00edtica-que-mais-cresce-na-Bahia-acessepolitica.com_.br-respiradores-coronavirus-2.jpg",500,333,false],"large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/07\/Portal-Acesse-Pol\u00edtica-O-site-de-pol\u00edtica-que-mais-cresce-na-Bahia-acessepolitica.com_.br-respiradores-coronavirus-2.jpg",500,333,false],"1536x1536":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/07\/Portal-Acesse-Pol\u00edtica-O-site-de-pol\u00edtica-que-mais-cresce-na-Bahia-acessepolitica.com_.br-respiradores-coronavirus-2.jpg",500,333,false],"2048x2048":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/07\/Portal-Acesse-Pol\u00edtica-O-site-de-pol\u00edtica-que-mais-cresce-na-Bahia-acessepolitica.com_.br-respiradores-coronavirus-2.jpg",500,333,false],"mantranews-slider-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/07\/Portal-Acesse-Pol\u00edtica-O-site-de-pol\u00edtica-que-mais-cresce-na-Bahia-acessepolitica.com_.br-respiradores-coronavirus-2.jpg",500,333,false],"mantranews-featured-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/07\/Portal-Acesse-Pol\u00edtica-O-site-de-pol\u00edtica-que-mais-cresce-na-Bahia-acessepolitica.com_.br-respiradores-coronavirus-2-420x307.jpg",420,307,true],"mantranews-featured-long":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/07\/Portal-Acesse-Pol\u00edtica-O-site-de-pol\u00edtica-que-mais-cresce-na-Bahia-acessepolitica.com_.br-respiradores-coronavirus-2-300x333.jpg",300,333,true],"mantranews-block-medium":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/07\/Portal-Acesse-Pol\u00edtica-O-site-de-pol\u00edtica-que-mais-cresce-na-Bahia-acessepolitica.com_.br-respiradores-coronavirus-2-464x290.jpg",464,290,true],"mantranews-carousel-image":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/07\/Portal-Acesse-Pol\u00edtica-O-site-de-pol\u00edtica-que-mais-cresce-na-Bahia-acessepolitica.com_.br-respiradores-coronavirus-2.jpg",500,333,false],"mantranews-block-thumb":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/07\/Portal-Acesse-Pol\u00edtica-O-site-de-pol\u00edtica-que-mais-cresce-na-Bahia-acessepolitica.com_.br-respiradores-coronavirus-2-322x230.jpg",322,230,true],"mantranews-single-large":["https:\/\/blogopara.com.br\/wp-content\/uploads\/2020\/07\/Portal-Acesse-Pol\u00edtica-O-site-de-pol\u00edtica-que-mais-cresce-na-Bahia-acessepolitica.com_.br-respiradores-coronavirus-2.jpg",500,333,false]},"uagb_author_info":{"display_name":"Reda\u00e7\u00e3o geral","author_link":"https:\/\/blogopara.com.br\/index.php\/author\/blogopara"},"uagb_comment_info":0,"uagb_excerpt":"A empresa norte-americana Ocean 26 Inc, que negociou a venda de 600 respiradores com o Governo do Estado no in\u00edcio da pandemia da covid-19,\u00a0em 2020,\u00a0devolveu o dinheiro da compra ao Governo da Bahia\u00a0ap\u00f3s acordo judicial celebrado e homologado pelo Tribunal Distrital dos Estados Unidos do Distrito Central da Calif\u00f3rnia. O dinheiro ressarcido j\u00e1 est\u00e1 em&hellip;","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/47154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=47154"}],"version-history":[{"count":3,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/47154\/revisions"}],"predecessor-version":[{"id":47157,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/posts\/47154\/revisions\/47157"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media\/12535"}],"wp:attachment":[{"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=47154"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=47154"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogopara.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=47154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}